{"id":10863,"date":"2021-12-28T18:31:55","date_gmt":"2021-12-28T21:31:55","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=10863"},"modified":"2021-12-28T18:31:57","modified_gmt":"2021-12-28T21:31:57","slug":"conheca-os-direitos-do-consumidor-para-a-troca-de-presentes-de-natal","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/12\/28\/conheca-os-direitos-do-consumidor-para-a-troca-de-presentes-de-natal\/","title":{"rendered":"Conhe\u00e7a os direitos do consumidor para a troca de presentes de Natal"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">H\u00e1 situa\u00e7\u00f5es em que a troca \u00e9 obrigat\u00f3ria; em outras depende da loja<\/h1>\n\n\n\n<p>Presente \u00e9 sin\u00f4nimo de satisfa\u00e7\u00e3o garantida? Depende. \u00c0s vezes somos presenteados com um livro repetido ou uma roupa em tamanho que n\u00e3o serve. E o que fazer nessas situa\u00e7\u00f5es? A resposta varia conforme o motivo da troca, as regras da loja onde o item foi adquirido e tamb\u00e9m do que prev\u00ea o C\u00f3digo de Defesa do Consumidor. Existem situa\u00e7\u00f5es em que a troca \u00e9 obrigat\u00f3ria e em outras, depende da loja onde o produto foi comprado.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1434201&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1434201&amp;o=node\"><\/p>\n\n\n\n<p>A troca de produtos que n\u00e3o apresentam defeitos depende da pol\u00edtica de cada estabelecimento. Por isso, vale conversar com a pessoa que comprou o presente para saber se o vendedor se comprometeu a fazer a troca. O C\u00f3digo de Defesa do Consumidor diz que o estabelecimento que tenha uma pol\u00edtica de troca tem a obriga\u00e7\u00e3o de substituir o produto adquirido. Grandes redes de roupas e livros, por exemplo, tendem a trocar os itens desde que mantida a etiqueta e em prazo preestabelecido.<\/p>\n\n\n\n<p>Em ambas as situa\u00e7\u00f5es, a troca deve respeitar o valor pago pelo produto, mesmo que haja liquida\u00e7\u00f5es ou aumento de pre\u00e7o. Em caso de troca pelo mesmo produto, a loja n\u00e3o pode exigir complemento de valor. O consumidor tamb\u00e9m n\u00e3o pode pedir abatimento do pre\u00e7o caso haja mudan\u00e7a entre o que foi pago e o valor no dia da troca.<\/p>\n\n\n\n<p>&#8220;Sendo assim, cada loja pode ter uma pol\u00edtica de troca diferente, e o consumidor deve estar atento a essas regras: prazo, cupom fiscal, etiqueta, dentre outras. Sempre que poss\u00edvel, o consumidor deve solicitar essas regras de troca por escrito para, em caso de problema, registrar sua reclama\u00e7\u00e3o no Procon&#8221;, informou o Instituto de Defesa do Consumidor do Distrito Federal (Procon-DF).<\/p>\n\n\n\n<p>Os \u00f3rg\u00e3os de defesa do consumidor recomendam ainda que a nota fiscal seja guardada para uma eventual troca. Para roupas e sapatos, por exemplo, a etiqueta deve ser mantida na pe\u00e7a e s\u00f3 retirada quando houver a certeza de que o produto n\u00e3o precisar\u00e1 ser trocado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">V\u00edcio ou defeito<\/h2>\n\n\n\n<p>O c\u00f3digo diz que a troca s\u00f3 ser\u00e1 obrigat\u00f3ria nos casos em que o produto apresentar v\u00edcio ou defeito. Nesses casos, fica garantido ao consumidor, por exemplo, trocar uma roupa com problemas de confec\u00e7\u00e3o ou um brinquedo que saiu quebrado da loja. Entretanto, se o produto j\u00e1 tiver sido adquirido com defeito e o consumidor foi avisado disso no momento da compra, ent\u00e3o ele n\u00e3o ter\u00e1 direito \u00e0 troca.<\/p>\n\n\n\n<p>Se o defeito for aparente, a legisla\u00e7\u00e3o determina o prazo de 30 dias para que o consumidor possa pedir a troca, caso o produto seja um bem n\u00e3o dur\u00e1vel, como alimentos, produtos de beleza. Se for um bem dur\u00e1vel, como um eletrodom\u00e9stico, um eletroeletr\u00f4nico, uma roupa, um sapato, ent\u00e3o o prazo \u00e9 de 90 dias.<\/p>\n\n\n\n<p>O c\u00f3digo diz ainda que se n\u00e3o for poss\u00edvel o conserto do produto no prazo de at\u00e9 30 dias, o consumidor poder\u00e1 optar pela troca do produto, pela devolu\u00e7\u00e3o do dinheiro ou pelo abatimento proporcional do pre\u00e7o<\/p>\n\n\n\n<p>\u00c9 importante observar que o c\u00f3digo diz que esse prazo n\u00e3o ser\u00e1 aplicado nos casos em que o defeito seja em um produto essencial \u2013 como alimentos, medicamentos, equipamentos de aux\u00edlio \u00e0 locomo\u00e7\u00e3o, \u00e0 comunica\u00e7\u00e3o, \u00e0 audi\u00e7\u00e3o ou \u00e0 vis\u00e3o, devendo a devolu\u00e7\u00e3o da quantia paga ou troca do produto ser feita de imediato.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Compras na internet<\/h2>\n\n\n\n<p>Caso o presente tenha sido comprado pela internet, a legisla\u00e7\u00e3o garante ao consumidor o direito de arrependimento no prazo de at\u00e9 sete dias, a contar da data do recebimento.<\/p>\n\n\n\n<p>Al\u00e9m disso, h\u00e1 a possibilidade de o produto chegar danificado ou n\u00e3o corresponder ao pedido feito. A devolu\u00e7\u00e3o, nesses casos, pode ser feita e o dinheiro pago deve ser restitu\u00eddo \u2013 inclusive o frete.<\/p>\n\n\n\n<p>Por isso \u00e9 importante guardar uma c\u00f3pia dos contatos de <em>e-mail<\/em> e protocolos de liga\u00e7\u00f5es telef\u00f4nicas, possibilitando a resolu\u00e7\u00e3o de demandas.<\/p>\n\n\n\n<p>Se o consumidor n\u00e3o conseguir resolver o problema, a recomenda\u00e7\u00e3o \u00e9 que ele procure o Procon do seu estado. Tamb\u00e9m \u00e9 poss\u00edvel registrar uma reclama\u00e7\u00e3o por meio da <a href=\"https:\/\/consumidor.gov.br\/pages\/principal\/?1640710269331\" target=\"_blank\" rel=\"noreferrer noopener\">plataforma <em>online<\/em> de reclama\u00e7\u00f5es<\/a> do governo federal.<\/p>\n\n\n\n<p>A iniciativa, lan\u00e7ada em 2014, permite a interlocu\u00e7\u00e3o direta entre consumidores e empresas para solu\u00e7\u00e3o alternativa de conflitos de consumo pela internet. Na plataforma, o consumidor manda a reclama\u00e7\u00e3o diretamente com as empresas participantes, que se comprometem a receber, analisar e responder as reclama\u00e7\u00f5es de seus consumidores em at\u00e9 dez dias.<\/p>\n\n\n\n<p>Em seguida, o consumidor tem at\u00e9 20 dias para comentar e avaliar a resposta da empresa, informando se sua reclama\u00e7\u00e3o foi Resolvida ou N\u00e3o Resolvida, e ainda indicar seu n\u00edvel de satisfa\u00e7\u00e3o com o atendimento recebido.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Edi\u00e7\u00e3o: Denise Griesinger-Publicado em 28\/12\/2021 &#8211; 14:08 Por Luciano Nascimento \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-2077347051\"><div id=\"jorna-2273649041\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>H\u00e1 situa\u00e7\u00f5es em que a troca \u00e9 obrigat\u00f3ria; em outras depende da loja Presente \u00e9&#8230;<\/p>\n","protected":false},"author":2,"featured_media":10864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-10863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10863"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10863\/revisions"}],"predecessor-version":[{"id":10865,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10863\/revisions\/10865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/10864"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}