{"id":11534,"date":"2022-01-21T14:36:50","date_gmt":"2022-01-21T17:36:50","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=11534"},"modified":"2022-01-21T14:36:51","modified_gmt":"2022-01-21T17:36:51","slug":"experiencia-ajudou-brasil-a-tomar-medidas-contra-inflacao-diz-guedes","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2022\/01\/21\/experiencia-ajudou-brasil-a-tomar-medidas-contra-inflacao-diz-guedes\/","title":{"rendered":"Experi\u00eancia ajudou Brasil a tomar medidas contra infla\u00e7\u00e3o, diz Guedes"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Ministro da Economia participou do F\u00f3rum Econ\u00f4mico Mundial<\/h1>\n\n\n\n<p>O Ministro da Economia, Paulo Guedes, disse hoje (21), durante sua participa\u00e7\u00e3o no F\u00f3rum Econ\u00f4mico Mundial, que a infla\u00e7\u00e3o ser\u00e1 \u201cum verdadeiro problema\u201d para o mundo ocidental, mas que o Brasil, devido \u00e0s experi\u00eancias anteriores de conv\u00edvio e combate a altas taxas inflacion\u00e1rias, foi mais r\u00e1pido que outros pa\u00edses no sentido de adotar medidas contra a alta de pre\u00e7os.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1437982&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1437982&amp;o=node\"><\/p>\n\n\n\n<p>A fala do ministro foi feita ap\u00f3s participa\u00e7\u00f5es de autoridades do Fundo Monet\u00e1rio Internacional (FMI) e do Banco Central Europeu, no painel Perspectivas Econ\u00f4micas Globais, que teve como tema principal a influ\u00eancia da pandemia no aumento dos \u00edndices inflacion\u00e1rios.<\/p>\n\n\n\n<p>Na avalia\u00e7\u00e3o da diretora de Gest\u00e3o do FMI, Kristalina Georgieva, \u00e9 fundamental entender que a infla\u00e7\u00e3o est\u00e1 mais alta e persistente em alguns pa\u00edses, e que este \u00e9 \u201cum problema espec\u00edfico a cada pa\u00eds\u201d. Segundo ela, essas especificidades marcar\u00e3o o ano de 2022.<\/p>\n\n\n\n<p>\u201cN\u00e3o ser\u00e1 poss\u00edvel manter todas as pol\u00edticas em todas as partes, o que far\u00e1 o combate mais complicado em alguns pa\u00edses\u201d, disse Georgieva.<\/p>\n\n\n\n<p>A presidente do Banco Central Europeu, Christine Lagarde, acrescentou que a autoridade monet\u00e1ria precisa estar atenta \u201c\u00e0s cifras apresentadas em cada pa\u00eds\u201d, e que em muitos casos a supera\u00e7\u00e3o e a conserva\u00e7\u00e3o de empregos foi subestimada, disse ela ao defender aten\u00e7\u00e3o a problemas relativos ao mercado de trabalho.<\/p>\n\n\n\n<p>\u201cNa Fran\u00e7a vemos indicadores espec\u00edficos como negocia\u00e7\u00f5es coletivas de sal\u00e1rios na qual empregadores e sindicatos levam em conta os \u00edndices de infla\u00e7\u00e3o. No entanto, em outros pa\u00edses n\u00e3o estamos vendo essas negocia\u00e7\u00f5es avan\u00e7arem\u201d, disse Lagarde.<\/p>\n\n\n\n<p>\u201cEst\u00e1vamos acostumados a n\u00edveis baixos de infla\u00e7\u00e3o. E agora temos de ver quanto isso vai durar, e vai durar\u201d, acrescentou.<\/p>\n\n\n\n<p>Em seu discurso, o ministro Paulo Guedes disse que \u201ca infla\u00e7\u00e3o ser\u00e1 um verdadeiro problema para o mundo ocidental\u201d, exatamente por n\u00e3o estarem acostumados a lidar com esse tipo de problema. \u201cO Brasil, devido \u00e0 experi\u00eancia tr\u00e1gica pr\u00e9via com infla\u00e7\u00e3o, se mobilizou de forma mais r\u00e1pida\u201d, disse o ministro.<\/p>\n\n\n\n<p>\u201cMeu medo agora \u00e9 que a besta est\u00e1 fora da garrafa [nos pa\u00edses ocidentais]. N\u00e3o acredito que a infla\u00e7\u00e3o seja transit\u00f3ria. Penso que os elementos adversos que alimentam a infla\u00e7\u00e3o v\u00e3o diminuir gradualmente, mas n\u00e3o h\u00e1 mais arbitragem a ser explorada pelo ocidente. Penso que os bancos centrais est\u00e3o dormindo enquanto dirigem. Eles t\u00eam de ficar atento porque a infla\u00e7\u00e3o ser\u00e1 um problema real em breve para o ocidente\u201d, argumentou.<\/p>\n\n\n\n<p>Referindo-se ao coment\u00e1rio de Lagarde sobre os governos terem de ficar atentos ao que ocorre no mercado de trabalho, Guedes lembrou que, em 2019, o mundo estava, segundo diversas autoridades monet\u00e1rias em uma \u201cdesacelera\u00e7\u00e3o sincronizada\u201d.<\/p>\n\n\n\n<p>\u201cFomos ent\u00e3o afetados pela covid-19 e respondemos [no Brasil] de forma a evitar uma grande depress\u00e3o. Agora estamos de volta \u00e0 situa\u00e7\u00e3o de desacelera\u00e7\u00e3o sincronizada e avan\u00e7o de economias. Mas agora a infla\u00e7\u00e3o est\u00e1 a\u00ed. A quest\u00e3o \u00e9 saber o qu\u00e3o transit\u00f3rios s\u00e3o esses fatores\u201d, completou o ministro brasileiro.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Edi\u00e7\u00e3o: Denise Griesinger-Publicado em 21\/01\/2022 &#8211; 13:43 Por Pedro Peduzzi \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-422656572\"><div id=\"jorna-120708790\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ministro da Economia participou do F\u00f3rum Econ\u00f4mico Mundial O Ministro da Economia, Paulo Guedes, disse&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11535,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9,2],"tags":[],"class_list":["post-11534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11534"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11534\/revisions"}],"predecessor-version":[{"id":11536,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11534\/revisions\/11536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/11535"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}