{"id":11546,"date":"2022-01-24T18:14:34","date_gmt":"2022-01-24T21:14:34","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=11546"},"modified":"2022-01-24T18:14:35","modified_gmt":"2022-01-24T21:14:35","slug":"chuvas-provocam-perdas-de-119-mil-hectares-de-lavouras-de-minas-gerais","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2022\/01\/24\/chuvas-provocam-perdas-de-119-mil-hectares-de-lavouras-de-minas-gerais\/","title":{"rendered":"Chuvas provocam perdas de 119 mil hectares de lavouras de Minas Gerais"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Balan\u00e7o foi feito pela Emater-MG<\/h1>\n\n\n\n<p>As&nbsp;chuvas que ca\u00edram em Minas Gerais nas \u00faltimas semanas&nbsp;deixaram preju\u00edzo nas planta\u00e7\u00f5es. Segundo balan\u00e7o da Empresa de Assist\u00eancia T\u00e9cnica e Extens\u00e3o Rural de Minas Gerais (Emater-MG), 119 mil hectares de lavouras foram perdidos. A maior parte do preju\u00edzo foi na produ\u00e7\u00e3o de gr\u00e3os (74,5 mil hectares) e hortali\u00e7as (3,4 mil hectares).<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1438375&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1438375&amp;o=node\"><\/p>\n\n\n\n<p>Milho, feij\u00e3o e hortali\u00e7as foram as culturas mais afetadas pelo excesso de chuvas no estado. Cerca de&nbsp;37,5 mil hectares de planta\u00e7\u00e3o de milho foram perdidos, o equivalente a 4% de toda a \u00e1rea cultivada no estado, estimada em 851,5 mil hectares. A cultura do feij\u00e3o sofreu uma perda de 20,5 mil hectares. A \u00e1rea equivale a 15% do total plantado em Minas Gerais, de 133,2 mil hectares.<\/p>\n\n\n\n<p>As maiores perdas ocorreram na regi\u00e3o central e no norte do estado. E foi isso que reduziu o preju\u00edzo no setor, visto que as principais regi\u00f5es produtoras de milho e feij\u00e3o, como o Noroeste, Tri\u00e2ngulo Mineiro e Sul de Minas n\u00e3o sofreram tanto com as chuvas.<\/p>\n\n\n\n<p>As planta\u00e7\u00f5es de hortali\u00e7as tamb\u00e9m foram afetadas. A chuva causou preju\u00edzos principalmente na produ\u00e7\u00e3o da regi\u00e3o metropolitana de Belo Horizonte, al\u00e9m das regi\u00f5es Norte, Central e Leste de Minas. As culturas com a maior \u00e1rea perdida foram a de alface (416 hectares), tomate (365 hectares) e quiabo (236 hectares).<\/p>\n\n\n\n<p>A redu\u00e7\u00e3o da oferta de hortali\u00e7as, t\u00edpica nos per\u00edodos chuvosos, provocou aumento de pre\u00e7os. Na primeira quinzena&nbsp;de janeiro&nbsp;deste ano, houve no atacado um aumento nos pre\u00e7os das hortali\u00e7as de 21,2% e frutas de 4,4%, na compara\u00e7\u00e3o com o mesmo per\u00edodo de 2021.<\/p>\n\n\n\n<p>\u201cO importante para o consumidor agora, \u00e9 n\u00e3o cair na especula\u00e7\u00e3o e pesquisar os pre\u00e7os no mercado varejista, aproveitando as promo\u00e7\u00f5es e valores mais competitivos. Al\u00e9m disso, existem altera\u00e7\u00f5es de pre\u00e7os que s\u00e3o comuns nesta \u00e9poca, por casa da sazonalidade de alguns produtos\u201d, orientou o presidente da Emater-MG, Ot\u00e1vio Maia.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Edi\u00e7\u00e3o: L\u00edlian Beraldo-Publicado em 24\/01\/2022 &#8211; 15:35 Por Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-455539236\"><div id=\"jorna-1150121709\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Balan\u00e7o foi feito pela Emater-MG As&nbsp;chuvas que ca\u00edram em Minas Gerais nas \u00faltimas semanas&nbsp;deixaram preju\u00edzo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-11546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11546"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11546\/revisions"}],"predecessor-version":[{"id":11548,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11546\/revisions\/11548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/11547"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}