{"id":11654,"date":"2022-02-03T18:42:25","date_gmt":"2022-02-03T21:42:25","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=11654"},"modified":"2022-02-03T18:42:28","modified_gmt":"2022-02-03T21:42:28","slug":"bc-comunica-vazamento-de-dados-de-21-mil-chaves-pix","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2022\/02\/03\/bc-comunica-vazamento-de-dados-de-21-mil-chaves-pix\/","title":{"rendered":"BC comunica vazamento de dados de 2,1 mil chaves Pix"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Foram vazados dados cadastrais da Logbank Pagamentos<\/h1>\n\n\n\n<p>Um total de 2.112 clientes da Logbank Solu\u00e7\u00f5es em Pagamentos tiveram dados das chaves Pix vazadas, informou hoje (3) o Banco Central (BC). Esse foi o terceiro vazamento de dados desde o lan\u00e7amento do sistema instant\u00e2neo de pagamentos, em novembro de 2020.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1440236&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1440236&amp;o=node\"><\/p>\n\n\n\n<p>Segundo o BC, o vazamento ocorreu em dados cadastrais, que n\u00e3o afetam a movimenta\u00e7\u00e3o de dinheiro. Dados protegidos pelo sigilo banc\u00e1rio, como saldos, senhas e extratos n\u00e3o foram expostos.<\/p>\n\n\n\n<p>O incidente ocorreu em 24 e 25 de janeiro e exp\u00f4s os seguintes dados: nome do usu\u00e1rio, Cadastro de Pessoas F\u00edsicas (CPF), institui\u00e7\u00e3o de relacionamento e n\u00famero da conta. Todas as pessoas que tiveram informa\u00e7\u00f5es expostas receber\u00e3o avisos, mas o BC n\u00e3o informou como as v\u00edtimas ser\u00e3o notificadas. Segundo o BC, a Ag\u00eancia Nacional de Prote\u00e7\u00e3o de Dados (ANPD) tamb\u00e9m foi avisada.<\/p>\n\n\n\n<p>A exposi\u00e7\u00e3o de dados n\u00e3o significa necessariamente que todas as informa\u00e7\u00f5es tenham vazado, mas que ficaram vis\u00edveis para terceiros durante algum tempo e podem ter sido capturadas. O BC informou que o caso ser\u00e1 investigado e que san\u00e7\u00f5es poder\u00e3o ser aplicadas, como multa, suspens\u00e3o ou at\u00e9 a exclus\u00e3o da Logbank do sistema do Pix.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resposta<\/h2>\n\n\n\n<p>A LogBank \u00e9 uma empresa de meios eletr\u00f4nicos de pagamentos que atua no segmento Business-to-Business-to-Consumer (B2B2C, na sigla em ingl\u00eas). Nesse modelo, a ind\u00fastria vende diretamente ao consumidor, mas a venda \u00e9 facilitada por outro neg\u00f3cio (distribuidor, varejista ou atacadista), incluindo toda a cadeia comercial.<\/p>\n\n\n\n<p>Por meio de nota, a Logbank informou que sofreu uma tentativa de invas\u00e3o em suas plataformas digitais em 24 e 25 de janeiro. No entanto, a empresa informou que o ataque aos dados foi contido pelas equipes de seguran\u00e7a e que nenhum cliente sofreu preju\u00edzo financeiro. A empresa ressaltou os investimentos em seguran\u00e7a e tecnologia e disse que os recursos dos clientes &#8220;est\u00e3o e sempre estiveram sob m\u00e1xima vigil\u00e2ncia e seguran\u00e7a&#8221;.<\/p>\n\n\n\n<p>&#8220;O incidente foi detectado e controlado instantaneamente pelas ferramentas e equipes de seguran\u00e7a. Nenhum dado sens\u00edvel foi vazado e n\u00e3o houve qualquer movimenta\u00e7\u00e3o financeira indevida ou preju\u00edzo financeiro para os clientes relacionados com este incidente, cujo alcance permaneceu extremamente limitado\u201d, destacou a companhia.<\/p>\n\n\n\n<p>Esse foi o terceiro incidente de vazamentos de dados do Pix desde a cria\u00e7\u00e3o do sistema, em novembro de 2020. Em agosto, <a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2021-09\/banese-sofre-falha-de-seguranca-e-invasores-acessam-chaves-pix\" target=\"_blank\" rel=\"noreferrer noopener\">ocorreu o vazamento<\/a> de dados 414,5 mil chaves Pix por n\u00famero telef\u00f4nico do Banco do Estado de Sergipe (Banese).<\/p>\n\n\n\n<p>No \u00faltimo dia 21, foi a vez de 160,1 mil clientes da Acesso Solu\u00e7\u00f5es de Pagamento <a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2022-01\/bc-comunica-vazamento-de-dados-de-1601-mil-chaves-pix\" target=\"_blank\" rel=\"noreferrer noopener\">terem informa\u00e7\u00f5es vazadas<\/a>. Nos dois casos, na ocasi\u00e3o foram vazados dados cadastrais, sem a exposi\u00e7\u00e3o de senhas e de saldos banc\u00e1rios.<\/p>\n\n\n\n<p>Inicialmente, o BC tinha divulgado que o vazamento no Banese tinha atingido 395 mil chaves, mas o n\u00famero foi revisado mais tarde. Por determina\u00e7\u00e3o da Lei Geral de Prote\u00e7\u00e3o de Dados, a autoridade monet\u00e1ria <a href=\"https:\/\/www.bcb.gov.br\/acessoinformacao\/lgpd?modalAberto=registro_de_incidentes_com_dados_pessoais>&#8221; target=&#8221;_blank&#8221; rel=&#8221;noreferrer noopener&#8221;>mant\u00e9m uma p\u00e1gina<\/a> em que os cidad\u00e3os podem acompanhar incidentes relacionados com a chave Pix ou demais dados pessoais em poder do BC.<\/p>\n\n\n\n<p><em>Mat\u00e9ria atualizada \u00e0s 18h30 para acr\u00e9scimo do posicionamento da LogBank.<\/em><\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Denise Griesinger- <\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"block-3fb8692f-1483-4ee8-8fbf-77e429d37ed9\">Publicado em 03\/02\/2022 &#8211; 16:00 Por Wellton M\u00e1ximo \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<br>Atualizado em 03\/02\/2022 &#8211; 18:30<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-3801044048\"><div id=\"jorna-2406499752\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Foram vazados dados cadastrais da Logbank Pagamentos Um total de 2.112 clientes da Logbank Solu\u00e7\u00f5es&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-11654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11654"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11654\/revisions"}],"predecessor-version":[{"id":11656,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11654\/revisions\/11656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/11655"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}