{"id":11939,"date":"2022-02-17T10:34:44","date_gmt":"2022-02-17T13:34:44","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=11939"},"modified":"2022-02-17T10:34:46","modified_gmt":"2022-02-17T13:34:46","slug":"preso-pela-5a-vez-pastor-e-detido-por-discursar-a-caminhoneiros-no-canada","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2022\/02\/17\/preso-pela-5a-vez-pastor-e-detido-por-discursar-a-caminhoneiros-no-canada\/","title":{"rendered":"Preso pela 5\u00aa vez, pastor \u00e9 detido por discursar a caminhoneiros no Canad\u00e1"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ele est\u00e1 detido h\u00e1 quase duas semanas e permanece em confinamento solit\u00e1rio 23 horas por dia.<\/h2>\n\n\n\n<p>O <a href=\"https:\/\/guiame.com.br\/gospel\/noticias\/pastor-canadense-volta-ser-preso-apos-protesto-em-frente-casa-de-ministro-da-saude.html\"><strong>pastor Artur Pawlowski<\/strong><\/a> foi preso pela quinta vez no Canad\u00e1 \u2014 desta vez, por depois de discursar aos manifestantes do <a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/pastor-canadense-canta-amazing-grace-durante-protestos-por-passaporte-da-vacina.html\"><strong>bloqueio de caminhoneiros<\/strong><\/a> ao longo da fronteira com os Estados Unidos.<\/p>\n\n\n\n<p>Pawlowski foi preso na segunda-feira passada (7) e passou a \u00faltima semana detido no Calgary Remand Center, um pres\u00eddio na prov\u00edncia de Alberta. Seu advogado informou \u00e0 Fox News que o pastor permanece em confinamento solit\u00e1rio durante 23 horas por dia.<\/p>\n\n\n\n<p>Durante um discurso de 20 minutos para os caminhoneiros, em 3 de fevereiro, o pastor os exortou a \u201cmanter a linha\u201d contra o exagero do governo, sem recorrer \u00e0 viol\u00eancia.&nbsp;<\/p>\n\n\n\n<p>Pawlowski comparou o Freedom Convoy (\u201c<a href=\"https:\/\/guiame.com.br\/gospel\/noticias\/sobreviventes-do-comunismo-dizem-que-estao-revivendo-o-regime-no-canada.html\"><strong>Comboio da Liberdade<\/strong><\/a>\u201d, nome que intitula os protestos) ao movimento Solidariedade na d\u00e9cada de 1980, que acabou levando \u00e0 liberta\u00e7\u00e3o da Pol\u00f4nia na era de repress\u00e3o do governo comunista.<\/p>\n\n\n\n<p>Pawlowski ganhou as manchetes internacionais pela primeira vez em abril de 2021, quando expulsou a pol\u00edcia de sua igreja ao tentar verificar as restri\u00e7\u00f5es da Covid-19 durante um culto de P\u00e1scoa.<\/p>\n\n\n\n<p>Depois de continuar realizando cultos presenciais na igreja, desafiando uma ordem judicial, ele enfrentou repetidas pris\u00f5es, inclusive no meio de uma rodovia e na pista do aeroporto da cidade de Calgary.<\/p>\n\n\n\n<p>No ano passado, ele realizou uma turn\u00ea de palestras pelos EUA, se reunindo com deputados americanos e espalhando o alerta de que os governos ocidentais se assemelham cada vez mais ao regime comunista da Pol\u00f4nia, do qual ele fugiu quando jovem.<\/p>\n\n\n\n<p><strong>\u201cN\u00e3o lutamos com armas e espadas\u201d<\/strong><\/p>\n\n\n\n<p>Pawlowski estava se preparando para retornar \u00e0 fronteira para fazer um culto na igreja e falar com os caminhoneiros na semana passada quando foi preso, de acordo com o filho do pastor, Nathaniel Pawlowski.<\/p>\n\n\n\n<p>&#8220;Havia uma van da pol\u00edcia disfar\u00e7ada, ve\u00edculos n\u00e3o identificados vigiando nossa casa. Ficamos supondo, por muitas, muitas horas, porque eles estavam do lado de fora por tanto tempo\u201d, disse Nathaniel \u00e0 Fox News.<\/p>\n\n\n\n<p>Pawlowski recebeu tr\u00eas acusa\u00e7\u00f5es: por danos acima de US$ 5.000, por ajudar no bloqueio de uma infraestrutura e por n\u00e3o &#8220;manter a paz&#8221; \u2014 uma condi\u00e7\u00e3o da liberdade condicional sob a qual ele foi colocado em outubro, depois de ser preso ap\u00f3s sua turn\u00ea pelos EUA.<\/p>\n\n\n\n<p>O pastor continua preso depois de ter negado a fian\u00e7a durante uma audi\u00eancia na quarta-feira passada (9), quando um promotor alegou que o discurso de Pawlowski aos caminhoneiros era uma \u201camea\u00e7a aberta de viol\u00eancia\u201d, segundo a CBC.<\/p>\n\n\n\n<p>Os v\u00eddeos, no entanto, mostram Pawlowski dizendo aos caminhoneiros duas vezes para n\u00e3o recorrer \u00e0 viol\u00eancia durante seus protestos.<\/p>\n\n\n\n<p><img decoding=\"async\" src=\"https:\/\/thumbor.guiame.com.br\/unsafe\/smart\/https:\/\/media.guiame.com.br\/archives\/2022\/02\/16\/2978444034-.png\" alt=\"\" width=\"600\"><br><sup>&#8216;Freedom Convoy&#8217;: Milhares protestam contra os passaportes da vacina em Ottawa. (Foto: Wikimedia Commons)<\/sup><\/p>\n\n\n\n<p>\u201cQue Deus ajude a todos n\u00f3s, porque n\u00e3o lutamos com armas e espadas\u201d, disse ele. \u201cN\u00f3s n\u00e3o lutamos com tasers (armas de eletrochoque) e com ve\u00edculos da pol\u00edcia. N\u00e3o! N\u00f3s s\u00f3 queremos voltar e trabalhar duro e conseguir algo e sustentar nossas fam\u00edlias. N\u00f3s s\u00f3 queremos ser deixados em paz!\u201d<\/p>\n\n\n\n<p>O pastor ent\u00e3o continuou: \u201cMais uma vez, n\u00e3o estou falando de viol\u00eancia, espadas e armas e todas essas coisas. Voc\u00eas t\u00eam as asas mais poderosas de todos os tempos. Quem pode mobilizar 1.000 caminh\u00f5es? Quem pode mobilizar 10.000 caminhoneiros com 100.000 apoiadores?\u201d<\/p>\n\n\n\n<p>Pawlowski enfrenta outra audi\u00eancia de fian\u00e7a nesta quarta-feira (16).<\/p>\n\n\n\n<p><strong>Ora\u00e7\u00f5es e jejuns na pris\u00e3o<\/strong><\/p>\n\n\n\n<p>Nathaniel Pawlowski disse que seu pai foi maltratado na pris\u00e3o, mas que ele permanece implac\u00e1vel e realizou dois jejuns baseados na tradi\u00e7\u00e3o b\u00edblica.<\/p>\n\n\n\n<p>\u201cEle terminou um jejum de tr\u00eas dias baseado na hist\u00f3ria de Ester, onde ela jejuou para que o inimigo fosse exposto\u201d, disse ele. &#8220;E agora ele est\u00e1 fazendo um jejum de Daniel de 21 dias, que \u00e9 basicamente comida leve, sem carne. Est\u00e1 comendo vegetais para que ele receba uma resposta de Deus.\u201d<\/p>\n\n\n\n<p>Vig\u00edlias de ora\u00e7\u00e3o pelo pastor Pawlowski foram planejadas nesta ter\u00e7a-feira (15) nos consulados canadenses em Nova York, Seattle, Los Angeles, Chicago e Las Vegas.<\/p>\n\n\n\n<p>Cindy Chafian, diretora executiva da Firebrand Action and Media, que est\u00e1 organizando as vig\u00edlias, acredita que \u201cn\u00e3o v\u00e3o deixar o Artur sair\u201d, mas \u00e9 importante levar seu caso ao conhecimento p\u00fablico.<\/p>\n\n\n\n<p>\u201cN\u00e3o \u00e9 apenas o que est\u00e1 acontecendo desde a Covid. Eles visam o pastor h\u00e1 muitos, muitos anos. Ele n\u00e3o \u00e9 uma pessoa amig\u00e1vel aos olhos do governo porque fala a verdade, e eles n\u00e3o gostam disso\u201d, afirma Chafian.<\/p>\n\n\n\n<p>A organiza\u00e7\u00e3o tamb\u00e9m est\u00e1 coletando assinaturas para uma carta, que ser\u00e1 enviada ao Congresso, sobre o tratamento de Pawlowski.&nbsp;&nbsp;<\/p>\n\n\n\n<p>O objetivo, segundo Chafian, \u00e9 denunciar n\u00e3o apenas o caso de Pawlowski, mas conscientizar sobre como outros l\u00edderes religiosos foram tratados durante a pandemia no Canad\u00e1.&nbsp;<\/p>\n\n\n\n<p>Igrejas em todo o Canad\u00e1 tiveram seus pastores presos, templos trancados, multas altas e interfer\u00eancia cont\u00ednua de funcion\u00e1rios do governo.<\/p>\n\n\n\n<p>Em junho, o senador Josh Hawley pediu \u00e0 Comiss\u00e3o Americana de Liberdade Religiosa Internacional (USCIRF) que considerasse adicionar o Canad\u00e1 \u00e0 sua lista especial de vigil\u00e2ncia, por causa de como os pastores est\u00e3o sendo tratados no pa\u00eds.<\/p>\n\n\n\n<p>\u201cEstamos em um ponto crucial da hist\u00f3ria e, se n\u00e3o pararmos com isso, vamos afundar ainda mais\u201d, disse Chafian. \u201cSe a gente pensa que isso n\u00e3o est\u00e1 vindo para os EUA, estamos muito enganados.\u201d<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Fonte:<\/strong> Guiame, com informa\u00e7\u00f5es da Fox News <strong>Atualizado: <\/strong>quarta-feira, 16 de fevereiro de 2022 12:22<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-3314931893\"><div id=\"jorna-917041554\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ele est\u00e1 detido h\u00e1 quase duas semanas e permanece em confinamento solit\u00e1rio 23 horas por&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-11939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-cristao"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11939"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11939\/revisions"}],"predecessor-version":[{"id":11941,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11939\/revisions\/11941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/11940"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}