{"id":13353,"date":"2022-04-07T10:32:00","date_gmt":"2022-04-07T13:32:00","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=13353"},"modified":"2022-04-07T10:32:02","modified_gmt":"2022-04-07T13:32:02","slug":"ibge-reduz-previsao-mas-brasil-deve-ter-safra-recorde-de-graos","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2022\/04\/07\/ibge-reduz-previsao-mas-brasil-deve-ter-safra-recorde-de-graos\/","title":{"rendered":"IBGE reduz previs\u00e3o, mas Brasil deve ter safra recorde de gr\u00e3os"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Produ\u00e7\u00e3o ter\u00e1 5,7 milh\u00f5es de toneladas a mais que em 2021<\/h2>\n\n\n\n<p>O Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) reduziu sua estimativa para a produ\u00e7\u00e3o de cereais, leguminosas e oleaginosas neste ano. Segundo o Levantamento Sistem\u00e1tico da Produ\u00e7\u00e3o Agr\u00edcola (LSPA), realizado em mar\u00e7o, a estimativa \u00e9 que o pa\u00eds feche 2022 com uma safra de 258,9 milh\u00f5es de toneladas, 1% abaixo (ou 2,7 milh\u00f5es de toneladas a menos) que o volume previsto na pesquisa de fevereiro.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1452770&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1452770&amp;o=node\"><\/p>\n\n\n\n<p>Mesmo com a redu\u00e7\u00e3o da previs\u00e3o de um m\u00eas para outro, o Brasil ainda deve ter safra recorde este ano, com uma produ\u00e7\u00e3o 2,3% acima (ou 5,7 milh\u00f5es de toneladas a mais) que no ano passado, de acordo com o IBGE.<\/p>\n\n\n\n<p>O recorde anterior havia ocorrido em 2020, quando foram produzidos 255,4 milh\u00f5es de toneladas de cereais, leguminosas e oleaginosas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Estimativas<\/h2>\n\n\n\n<p>A redu\u00e7\u00e3o da previs\u00e3o de fevereiro para mar\u00e7o foi puxada pelas quedas nas estimativas de produ\u00e7\u00e3o da soja (-5,6%), da primeira safra de milho (-3,8%), da uva (-9,5%) e do tomate (-1,9%).<\/p>\n\n\n\n<p>Apesar disso, nesse per\u00edodo houve melhoras nas estimativas de safra da segunda safra do milho (4,9%), algod\u00e3o herb\u00e1ceo (3,7%), feij\u00e3o (3%), aveia (3,3%), sorgo (0,5%) e trigo (9,6%). O arroz teve uma leve varia\u00e7\u00e3o de -0,1%.<\/p>\n\n\n\n<p>A \u00e1rea a ser colhida em 2022 deve chegar a 71,8 milh\u00f5es de hectares, segundo a pesquisa de mar\u00e7o, 0,8% acima da prevista em fevereiro e 4,7% acima da registrada no ano passado.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Edi\u00e7\u00e3o: Kleber Sampaio-Publicado em 07\/04\/2022 &#8211; 09:46 Por Vitor Abdala &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Rio de Janeiro<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-3422295013\"><div id=\"jorna-4002006485\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Produ\u00e7\u00e3o ter\u00e1 5,7 milh\u00f5es de toneladas a mais que em 2021 O Instituto Brasileiro de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":13354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9,2],"tags":[],"class_list":["post-13353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13353"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13353\/revisions"}],"predecessor-version":[{"id":13355,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13353\/revisions\/13355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/13354"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}