{"id":16892,"date":"2022-07-30T19:31:05","date_gmt":"2022-07-30T22:31:05","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=16892"},"modified":"2022-07-30T19:31:06","modified_gmt":"2022-07-30T22:31:06","slug":"tarcisio-oficializa-candidatura-em-evento-com-bolsonaro","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2022\/07\/30\/tarcisio-oficializa-candidatura-em-evento-com-bolsonaro\/","title":{"rendered":"Tarc\u00edsio oficializa candidatura em evento com Bolsonaro"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Conven\u00e7\u00e3o do Republicanos tamb\u00e9m formaliza apoio da legenda \u00e0 reelei\u00e7\u00e3o do presidente<\/h2>\n\n\n\n<p>O Republicanos oficializou neste s\u00e1bado (23), em conven\u00e7\u00e3o nacional na Expo Center Norte (SP), a candidatura de Tarc\u00edsio de Freitas ao governo do estado. O evento contou com a presen\u00e7a do presidente Jair Bolsonaro (PL), que busca impulsionar a campanha do seu ex-ministro. A ideia \u00e9 nacionalizar a disputa pelo Pal\u00e1cio dos Bandeirantes, sede do governo paulista, para atrair o voto dos apoiadores do chefe do Executivo.<\/p>\n\n\n\n<p>\u2013 No dia de hoje a gente d\u00e1 o primeiro passo de uma longa caminhada. Uma caminhada na dire\u00e7\u00e3o de uma nova era. Uma era de esperan\u00e7a, uma era de acolhimento das pessoas, que precisam do suporte do Estado. Uma era de inova\u00e7\u00e3o, uma era de sustentabilidade, uma era de cuidado e suporte com as pessoas, de respeito aos empreendedores, uma era de transforma\u00e7\u00e3o \u2013 disse Tarc\u00edsio durante seu discurso na conven\u00e7\u00e3o.<\/p>\n\n\n\n<p>Al\u00e9m da oficializa\u00e7\u00e3o da candidatura ao governo, foi formalizado apoio da legenda \u00e0 reelei\u00e7\u00e3o de Bolsonaro e homologada a coliga\u00e7\u00e3o \u201cS\u00e3o Paulo pode mais\u201d, que conta com os partidos PSD, PTB, PSC e PL em torno de Tarc\u00edsio. A chapa ter\u00e1 o ex-prefeito de S\u00e3o Jos\u00e9 dos Campos Fel\u00edcio Ramuth (PSD) como candidato a vice e o astronauta Marcos Pontes (PL) ao Senado. A supl\u00eancia ainda est\u00e1 em aberto e h\u00e1 possibilidade de indicar um nome evang\u00e9lico.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-incorporar-manipulador wp-block-embed-incorporar-manipulador wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"CONVEN\u00c7\u00c3O NACIONAL E ESTADUAL REPUBLICANOS\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/8-_kYpwa3PA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Recentemente, Bolsonaro e Tarc\u00edsio estiveram juntos em eventos p\u00fablicos em S\u00e3o Paulo. Em seus discursos, o presidente tem elogiado a performance do seu ex-ministro \u00e0 frente da pasta da Infraestrutura. Internamente avalia-se que os eleitores de Bolsonaro s\u00e3o fundamentais para a campanha de Tarc\u00edsio.<\/p>\n\n\n\n<p>Apesar de aliar-se a um candidato apoiado por Bolsonaro, Kassab mant\u00e9m-se distante do chefe do Executivo e n\u00e3o deve comparecer ao evento deste s\u00e1bado. Como mostrou a coluna do Jogo Pol\u00edtico, o dirigente deve passar o dia viajando pelo Brasil para prestigiar o lan\u00e7amento de tr\u00eas candidaturas do PSD a governos estaduais: Ratinho J\u00fanior (PR), Marquinhos Trad (MS) e Edivaldo Holanda J\u00fanior (MA).<\/p>\n\n\n\n<p>O PSD assumiu posi\u00e7\u00e3o de neutralidade no primeiro turno da disputa pelo Planalto, mas Kassab tem dado sinais de prefer\u00eancia pessoal pelo ex-presidente Luiz In\u00e1cio Lula da Silva (PT).<\/p>\n\n\n\n<p><strong>HIST\u00d3RICO<\/strong><br>Al\u00e9m de ter sido ministro da Infraestrutura no governo de Bolsonaro, Tarc\u00edsio atuou como diretor executivo do Departamento Nacional de Infraestrutura e Transportes (DNIT), em 2011, durante a gest\u00e3o da ex-presidente Dilma Rousseff (PT). O ex-ministro tamb\u00e9m foi secret\u00e1rio da Coordena\u00e7\u00e3o de Projetos da Secretaria Especial do Programa de Parceria de Investimentos (PPI), no governo do ex-presidente Michel Temer (MDB).<\/p>\n\n\n\n<p>Nascido no Rio de Janeiro, a campanha do seu advers\u00e1rio Rodrigo Garcia (PSDB) criou o mote \u201cpaulista raiz\u201d para critic\u00e1-lo por ser de fora de S\u00e3o Paulo.<\/p>\n\n\n\n<p>De acordo com o \u00faltimo Datafolha estadual, divulgado no fim do m\u00eas passado, Tarc\u00edsio e Garcia estavam empatados com 13%. O candidato ao governo pelo PT, Fernando Haddad, aparecia na lideran\u00e7a, com 34%.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Pleno.News &#8211; 30\/07\/2022 12h23 | atualizado em 30\/07\/2022 12h43<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-3883814480\"><div id=\"jorna-1376528622\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Conven\u00e7\u00e3o do Republicanos tamb\u00e9m formaliza apoio da legenda \u00e0 reelei\u00e7\u00e3o do presidente O Republicanos oficializou&#8230;<\/p>\n","protected":false},"author":2,"featured_media":16894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,13],"tags":[],"class_list":["post-16892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-politica"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16892"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16892\/revisions"}],"predecessor-version":[{"id":16895,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16892\/revisions\/16895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/16894"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}