{"id":17162,"date":"2022-08-03T20:48:24","date_gmt":"2022-08-03T23:48:24","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=17162"},"modified":"2022-08-03T20:48:51","modified_gmt":"2022-08-03T23:48:51","slug":"camara-aprova-projeto-que-extingue-saidas-temporarias-de-presos","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2022\/08\/03\/camara-aprova-projeto-que-extingue-saidas-temporarias-de-presos\/","title":{"rendered":"C\u00e2mara aprova projeto que extingue sa\u00eddas tempor\u00e1rias de presos"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Proposta inicial limitava o benef\u00edcio, mas deputados o extinguiram<\/h2>\n\n\n\n<p>A C\u00e2mara dos Deputados aprovou nesta quarta-feira (3) o projeto que acaba com sa\u00eddas tempor\u00e1rias de presos dos estabelecimentos prisionais. A mat\u00e9ria segue para an\u00e1lise do\u00a0Senado.<\/p>\n\n\n\n<p>A proposta teve origem no Senado e previa apenas que as sa\u00eddas tempor\u00e1rias fossem limitadas. No entanto, ao tramitar na C\u00e2mara, deputados decidiram extinguir&nbsp;o benef\u00edcio. O texto aprovado prev\u00ea a revoga\u00e7\u00e3o de todas as possibilidades de sa\u00edda, que atualmente est\u00e3o dispon\u00edveis para condenados em regime semiaberto, como visita \u00e0 fam\u00edlia durante feriados, frequ\u00eancia a cursos e participa\u00e7\u00e3o em atividades.<\/p>\n\n\n\n<p>Para o relator,&nbsp;Capit\u00e3o Derrite (PL-SP), a exist\u00eancia do benef\u00edcio da sa\u00edda tempor\u00e1ria burla a pr\u00f3pria lei penal, ao frustrar a proporcionalidade no cumprimento da pena. Al\u00e9m disso, ele destacou que muitos presos n\u00e3o retornam ao sistema prisional ap\u00f3s a sa\u00edda.<\/p>\n\n\n\n<p>\u201cA Secretaria da Administra\u00e7\u00e3o Penitenci\u00e1ria (SAP) de S\u00e3o Paulo informou que&nbsp;na passagem de 2021 para 2022, 1.628 presos que deixaram as penitenci\u00e1rias do estado, durante a chamada \u2018saidinha tempor\u00e1ria de fim de ano\u2019, n\u00e3o retornaram ao sistema prisional paulista\u201d, argumentou o deputado. \u201cJ\u00e1 existe a previs\u00e3o legal de cumprimento de pena e progress\u00e3o de regime de forma proporcional, a sa\u00edda tempor\u00e1ria causa a todos um sentimento de impunidade diante da percep\u00e7\u00e3o de que as pessoas condenadas n\u00e3o cumprem suas penas, e o pior, de que o crime compensa\u201d, acrescentou.<\/p>\n\n\n\n<p>O texto aprovado tamb\u00e9m obriga a realiza\u00e7\u00e3o de exame criminol\u00f3gico como requisito para a progress\u00e3o de regime e para a autoriza\u00e7\u00e3o de regime semiaberto. A an\u00e1lise dever\u00e1 comprovar que o detento tem condi\u00e7\u00f5es de se adaptar ao novo regime com autodisciplina, baixa periculosidade e senso de responsabilidade.<\/p>\n\n\n\n<p>\u201cO exame criminol\u00f3gico&nbsp;consistente na emiss\u00e3o de um parecer t\u00e9cnico de uma equipe multidisciplinar, constitui ferramenta muito mais efetiva para aferir a capacidade do condenado de adaptar-se ou n\u00e3o a regime menos rigoroso do que uma constata\u00e7\u00e3o de boa conduta carcer\u00e1ria comprovada apenas pelo diretor do estabelecimento, tal qual \u00e9 previsto pela legisla\u00e7\u00e3o vigente\u201d, argumentou o relator.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ressocializa\u00e7\u00e3o<\/h2>\n\n\n\n<p>A deputada Erika Kokay (PT-DF) criticou a aprova\u00e7\u00e3o da mat\u00e9ria. Segundo ela, as sa\u00eddas tempor\u00e1rias s\u00e3o um processo de ressocializa\u00e7\u00e3o, \u00e9 a forma da lei assegurar que a pessoa esteja apta ao conv\u00edvio da sociedade, passando por uma prova.<\/p>\n\n\n\n<p>&#8220;O que s\u00e3o as sa\u00eddas tempor\u00e1rias? Primeiro, elas s\u00f3 s\u00e3o devidas a quem est\u00e1 em regime semiaberto. Portanto, as pessoas que t\u00eam direito \u00e0 sa\u00edda tempor\u00e1ria&nbsp;j\u00e1 est\u00e3o na&nbsp;semiliberdade. Elas j\u00e1 est\u00e3o em conv\u00edvio com a sociedade. Elas j\u00e1 podem sair o dia inteiro e apenas dormir dentro da unidade prisional.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Edi\u00e7\u00e3o: Aline Leal-Publicado em 03\/08\/2022 &#8211; 20:38 Por Heloisa Cristaldo &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-1043209082\"><div id=\"jorna-3586637889\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Proposta inicial limitava o benef\u00edcio, mas deputados o extinguiram A C\u00e2mara dos Deputados aprovou nesta&#8230;<\/p>\n","protected":false},"author":2,"featured_media":17163,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-17162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=17162"}],"version-history":[{"count":2,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17162\/revisions"}],"predecessor-version":[{"id":17165,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17162\/revisions\/17165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/17163"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=17162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=17162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=17162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}