{"id":18964,"date":"2022-10-06T17:21:29","date_gmt":"2022-10-06T20:21:29","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=18964"},"modified":"2022-10-06T17:21:30","modified_gmt":"2022-10-06T20:21:30","slug":"satanista-critica-pt-por-censura-de-seus-videos-exijo-retratacao","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2022\/10\/06\/satanista-critica-pt-por-censura-de-seus-videos-exijo-retratacao\/","title":{"rendered":"Satanista critica PT por censura de seus v\u00eddeos: \u201cExijo retrata\u00e7\u00e3o\u201d"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">&#8220;Que liberdade de express\u00e3o \u00e9 essa que essa suposta esquerda defende?&#8221;, questionou Vicky Vanilla<\/h2>\n\n\n\n<p>O ministro Paulo Sanseverino, do Tribunal Superior Eleitoral (TSE), determinou na quarta-feira (5) a remo\u00e7\u00e3o de publica\u00e7\u00f5es que associam o ex-presidente Luiz In\u00e1cio Lula da Silva (PT) ao satanismo. A ordem \u00e9 para TikTok, Twitter, YouTube, Instagram, Facebook e Gettr apagarem as postagens. A multa di\u00e1ria em caso de descumprimento \u00e9 de R$ 50 mil.<\/p>\n\n\n\n<p>O ministro tamb\u00e9m determinou que o TikTok, plataforma na qual a publica\u00e7\u00e3o foi veiculada originalmente, informe os dados cadastrais da conta respons\u00e1vel pela postagem. O objetivo \u00e9 identificar o administrador do perfil @vicky_vanilla_official.<\/p>\n\n\n\n<p>No s\u00e1bado (1\u00ba), o satanista Vicky Vanilla, famoso nas redes sociais por compartilhar suas cren\u00e7as para os mais jovens, declarou em uma live que satanistas e seguidores da bruxaria se reuniram para pedir aos seus deuses pela vit\u00f3ria do ex-presidente Lula (PT).<\/p>\n\n\n\n<p>\u2013 Voc\u00eas v\u00e3o comer o p\u00e3o que o Satan\u00e1s amassou. N\u00f3s nos unimos esse tempo todo, os terreiros de quimbanda, os terreiros de ax\u00e9, as irmandades luciferianas do pa\u00eds, os segmentos satanistas, os satanistas ate\u00edstas, os satanistas gn\u00f3sticos, os luciferianos ate\u00edstas, os luciferianos gn\u00f3sticos, espiritualistas, o pessoal da bruxaria natural, o pessoal da wicca, o pessoal da magia draconiana, n\u00f3s nos unimos \u2013 diz, na grava\u00e7\u00e3o.<\/p>\n\n\n\n<p>O ministro atendeu a um pedido feito pela campanha do ex-presidente. A coliga\u00e7\u00e3o Brasil da Esperan\u00e7a diz que houve propaganda difamat\u00f3ria e injuriosa. Os advogados afirmam ainda que o mesmo homem do v\u00eddeo apareceu criticando Lula duas semanas antes, em outra grava\u00e7\u00e3o.<\/p>\n\n\n\n<p>No TikTok, Vicky Vanilla se manifestou contra a decis\u00e3o do STF.<\/p>\n\n\n\n<p>\u2013 Acabei de entrar aqui no TikTok e tive a not\u00edcia de que o STF derrubou todos os meus v\u00eddeos de apoio ao Lula sem nem me notificar. (\u2026) Detalhe: eu nunca falei que o Lula tinha qualquer rela\u00e7\u00e3o espiritual com a casa. (\u2026) Que liberdade de express\u00e3o \u00e9 essa que essa suposta esquerda defende? (\u2026) E com as outras religi\u00f5es ocultistas, como \u00e9 que fica essa representatividade? \u2013 questionou.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"589\" data-id=\"18965\" src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2022\/10\/Sem-Titulo-1-3.jpg\" alt=\"\" class=\"wp-image-18965\" srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2022\/10\/Sem-Titulo-1-3.jpg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2022\/10\/Sem-Titulo-1-3-300x173.jpg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2022\/10\/Sem-Titulo-1-3-768x442.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">V\u00eddeo indispon\u00edvel<\/h2>\n\n\n\n<h6 class=\"wp-block-heading\">Pleno.News &#8211; 06\/10\/2022 11h57 | atualizado em 06\/10\/2022 12h30<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-3115430072\"><div id=\"jorna-2627750380\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>&#8220;Que liberdade de express\u00e3o \u00e9 essa que essa suposta esquerda defende?&#8221;, questionou Vicky Vanilla O&#8230;<\/p>\n","protected":false},"author":2,"featured_media":18966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,13],"tags":[],"class_list":["post-18964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-politica"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=18964"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18964\/revisions"}],"predecessor-version":[{"id":18967,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18964\/revisions\/18967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/18966"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=18964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=18964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=18964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}