{"id":1918,"date":"2020-09-21T16:01:32","date_gmt":"2020-09-21T19:01:32","guid":{"rendered":"http:\/\/jornalvaleevangelico.com.br\/?p=1918"},"modified":"2020-09-21T16:01:41","modified_gmt":"2020-09-21T19:01:41","slug":"bolsonaro-recebe-credenciais-de-cinco-novos-embaixadores-no-brasil","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2020\/09\/21\/bolsonaro-recebe-credenciais-de-cinco-novos-embaixadores-no-brasil\/","title":{"rendered":"Bolsonaro recebe credenciais de cinco novos embaixadores no Brasil"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Documento garante prerrogativas de atua\u00e7\u00e3o do diplomata em outro pa\u00eds<\/h3>\n\n\n\n<p>O presidente Jair Bolsonaro recebeu hoje (21) as credenciais de cinco novos embaixadores no Brasil, em cerim\u00f4nia reservada no Pal\u00e1cio do Planalto. A partir de agora, est\u00e3o habilitados a despachar no pa\u00eds os representantes de Chipre, Evagoras Vryonides; do Uruguai, Guillermo Valles Galm\u00e9s; do Paquist\u00e3o, Ahmad Hussain Dayo; da \u00cdndia, Suresh K. Reddy; e dos Emirados \u00c1rabes Unidos, Saleh Ahmad Salem Alzaraim Al-Suwaidi.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1388499&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1388499&amp;o=node\"><\/p>\n\n\n\n<p>Tradicionalmente, um embaixador assume o posto ap\u00f3s a entrega de documentos enviados pelo presidente de seu pa\u00eds ao governo do pa\u00eds onde atuar\u00e1.<\/p>\n\n\n\n<p>A apresenta\u00e7\u00e3o das cartas credenciais ao presidente da Rep\u00fablica \u00e9 uma formalidade que aumenta as prerrogativas de atua\u00e7\u00e3o do diplomata no Brasil. Caso a credencial n\u00e3o seja recebida pelo presidente, o embaixador n\u00e3o pode representar seu pa\u00eds em audi\u00eancias ou solenidades oficiais.<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: N\u00e1dia Franco &#8211; Publicado em 21\/09\/2020 &#8211; 14:21 Por Andreia Verd\u00e9lio \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/p>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-780840647\"><div id=\"jorna-1875829098\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Documento garante prerrogativas de atua\u00e7\u00e3o do diplomata em outro pa\u00eds O presidente Jair Bolsonaro recebeu&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1918"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1918\/revisions"}],"predecessor-version":[{"id":1920,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1918\/revisions\/1920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/1919"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}