{"id":2171,"date":"2020-10-10T14:07:32","date_gmt":"2020-10-10T17:07:32","guid":{"rendered":"http:\/\/jornalvaleevangelico.com.br\/?p=2171"},"modified":"2020-10-10T14:07:33","modified_gmt":"2020-10-10T17:07:33","slug":"salles-sobrevoa-parque-nacional-da-chapada-dos-veadeiros","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2020\/10\/10\/salles-sobrevoa-parque-nacional-da-chapada-dos-veadeiros\/","title":{"rendered":"Salles sobrevoa Parque Nacional da Chapada dos Veadeiros"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Com a chuva deste s\u00e1bado, expectativa \u00e9 que o fogo seja extinto<\/h3>\n\n\n\n<p>O ministro do Meio Ambiente, Ricardo Salles, sobrevoou hoje (10) a \u00e1rea do Parque Nacional da Chapada dos Veadeiros atingida por um&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/geral\/noticia\/2020-10\/incendio-atinge-parque-nacional-da-chapada-dos-veadeiros\" target=\"_blank\" rel=\"noreferrer noopener\">inc\u00eandio<\/a>&nbsp;desde o in\u00edcio do m\u00eas. De acordo com o ministro, a expectativa \u00e9 que, com a chuva que caiu na manh\u00e3 deste s\u00e1bado, o fogo seja extinto.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1390324&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1390324&amp;o=node\"><\/p>\n\n\n\n<p>\u201cA nossa expectativa \u00e9 que hoje mesmo, se formos ajudados pela chuva, possamos extinguir os focos de inc\u00eandio na Chapada dos Veadeiros, mas foram tr\u00eas, quatro dias de combate muito intensos\u201d, disse Salles em entrevista \u00e0&nbsp;<strong>TV Brasil<\/strong>.<\/p>\n\n\n\n<p>Ontem (9), o ministro j\u00e1 havia realizado um sobrevoo na \u00e1rea e acompanhado o trabalho das equipes no combate aos inc\u00eandios. Nos \u00faltimos dias, o trabalho conjunto das equipes do Corpo de Bombeiros de Goi\u00e1s, do Instituto Brasileiro do Meio Ambiente e dos Recursos Naturais Renov\u00e1veis (Ibama), do Instituto Chico Mendes de Biodiversidade (ICMBio), da Rede Contrafogo (formada por brigadistas volunt\u00e1rios para combater inc\u00eandios na regi\u00e3o) e da Secretaria de Meio Ambiente e Desenvolvimento Sustent\u00e1vel de Goi\u00e1s (Semad) conseguiu controlar a maior parte do&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/geral\/noticia\/2020-10\/maior-parte-do-incendio-na-chapada-dos-veadeiros-e-controlada\" target=\"_blank\" rel=\"noreferrer noopener\">fogo<\/a>.<\/p>\n\n\n\n<p>Al\u00e9m deles, cinco aeronaves do tipo Air Tractor e cerca de 100 brigadistas federais tamb\u00e9m ajudaram na opera\u00e7\u00e3o de combate aos inc\u00eandios. Os avi\u00f5es s\u00e3o capazes de carregar \u00e1gua em um reservat\u00f3rio para despejar o l\u00edquido em locais de dif\u00edcil acesso. Salles disse que foi adicionado um produto \u201cretardante de fogo\u201d \u00e0&nbsp;\u00e1gua, que potencializa em cinco vezes a capacidade de resposta no combate \u00e0s chamas.<\/p>\n\n\n\n<p>O fogo teve in\u00edcio no dia 25 de setembro&nbsp;em uma propriedade rural no munic\u00edpio de Cavalcante, no interior da \u00c1rea de Prote\u00e7\u00e3o Ambienta (APA)&nbsp;do Pouso Alto. A baixa umidade e alta temperatura na regi\u00e3o contribu\u00edram para o fogo se espalhar.<\/p>\n\n\n\n<p>Segundo o ministro, ainda n\u00e3o \u00e9 poss\u00edvel afirmar qual a extens\u00e3o da \u00e1rea atingida pelo fogo. De acordo com o boletim do Comando Unificado (Corpo de Bombeiros de Goi\u00e1s e ICMBio) , na quarta-feira (7), o fogo havia atingido quase 70 mil hectares.<\/p>\n\n\n\n<p>Destes, 17 mil atingiram o interior do Parque Nacional da Chapada dos Veadeiros, o equivalente a cerca de 7% da \u00e1rea protegida. Mais 50 mil hectares queimados est\u00e3o dentro da \u00c1rea de Prote\u00e7\u00e3o Ambiental (APA) do Pouso Alto, o que corresponde a 5,7% do territ\u00f3rio.<\/p>\n\n\n\n<p>\u201cMas esse n\u00famero pode ser bem maior&nbsp;na hora que eles terminarem a consolida\u00e7\u00e3o\u201d, disse Salles. \u201cCom os ventos que est\u00e3o aqui, a prolifera\u00e7\u00e3o do fogo \u00e9 muito r\u00e1pida. Como a vegeta\u00e7\u00e3o est\u00e1 muito seca, qualquer excesso de calor, qualquer fa\u00edsca serve de igni\u00e7\u00e3o para novos pontos [de inc\u00eandio]. Essa talvez seja a maior dificuldade: voc\u00ea apaga o inc\u00eandio de um lado e est\u00e1 nascendo um foco em outro local\u201d.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Edi\u00e7\u00e3o: Maria Claudia-Publicado em 10\/10\/2020 &#8211; 10:40 Por Luciano Nascimento &#8211; Rep\u00f3rter da Ag\u00eancia Brasi &#8211; Bras\u00edlia<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-490767182\"><div id=\"jorna-2962395684\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Com a chuva deste s\u00e1bado, expectativa \u00e9 que o fogo seja extinto O ministro do&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2171"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2171\/revisions"}],"predecessor-version":[{"id":2173,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2171\/revisions\/2173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/2172"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}