{"id":2214,"date":"2020-10-15T07:53:12","date_gmt":"2020-10-15T10:53:12","guid":{"rendered":"http:\/\/jornalvaleevangelico.com.br\/?p=2214"},"modified":"2020-10-15T07:53:13","modified_gmt":"2020-10-15T10:53:13","slug":"lei-que-altera-codigo-de-transito-e-sancionada-por-bolsonaro","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2020\/10\/15\/lei-que-altera-codigo-de-transito-e-sancionada-por-bolsonaro\/","title":{"rendered":"Lei que altera C\u00f3digo de Tr\u00e2nsito \u00e9 sancionada por Bolsonaro"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Regras come\u00e7am a valer em 180 dias<\/h3>\n\n\n\n<p>O presidente Jair Bolsonaro sancionou nesta ter\u00e7a-feira (13), durante uma live transmitida nas redes sociais, o Projeto de Lei 3267\/19, que altera o C\u00f3digo de Tr\u00e2nsito Brasileiro. O texto foi uma iniciativa do pr\u00f3prio governo federal, apresentada no ano passado, e foi aprovado pelo Congresso Nacional no&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/politica\/noticia\/2020-09\/camara-aprova-alteracoes-no-codigo-de-transito-texto-vai-sancao\" target=\"_blank\" rel=\"noreferrer noopener\">\u00faltimo dia 22 de setembro<\/a>. A lei est\u00e1 publicada no&nbsp;<a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/lei-n-14.071-de-13-de-outubro-de-2020-282461197\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Di\u00e1rio Oficial da Uni\u00e3o<\/em><\/a>&nbsp;desta quarta-feira (14).<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1390539&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1390539&amp;o=node\"><\/p>\n\n\n\n<p>A principal mudan\u00e7a \u00e9 o aumento na validade da Carteira Nacional de Habilita\u00e7\u00e3o (CNH) para dez anos para condutores com menos de 50 anos de idade. A nova lei tamb\u00e9m torna todas as multas leves e m\u00e9dias pun\u00edveis apenas com advert\u00eancia, caso o condutor n\u00e3o seja reincidente na mesma infra\u00e7\u00e3o nos \u00faltimos 12 meses. O projeto cria o Registro Nacional Positivo de Condutores (RNPC), uma esp\u00e9cie de listagem de bons condutores.<\/p>\n\n\n\n<p>&#8220;N\u00e3o era aquilo que n\u00f3s quer\u00edamos, mas houve algum avan\u00e7o. Com toda a certeza, no ano que vem a gente pode apresentar novo projeto buscando corrigir mais alguma coisa. A inten\u00e7\u00e3o nossa \u00e9 facilitar a vida do motorista&#8221;, afirmou o presidente, durante a live, ao lado do ministro da Infraestrutura, Tarc\u00edsio Freitas.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/imagens.ebc.com.br\/_DhXWwEarBU19Wkd0OWUlkGCnws=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/live_bolsonaro_e_tarcisio.jpg?itok=Ny7m1pqw\" alt=\"Presidente Jair Bolsonaro participa de transmiss\u00e3o ao vivo ao lado do ministro da Infraestrutura, Tarc\u00edsio Freitas. \" title=\"Reprodu\u00e7\u00e3o Youtube\"\/><\/figure>\n\n\n\n<h6 class=\"wp-block-heading\">Presidente Jair Bolsonaro participa de transmiss\u00e3o ao vivo ao lado do ministro da Infraestrutura, Tarc\u00edsio Freitas. &#8211;&nbsp;<strong>Reprodu\u00e7\u00e3o Youtube<\/strong><\/h6>\n\n\n\n<p>As novas regras come\u00e7am a valer depois de 180 dias a partir da publica\u00e7\u00e3o da lei. Outra mudan\u00e7a importante da nova lei \u00e9 o dispositivo que estabelece uma grada\u00e7\u00e3o de 20, 30 ou 40 pontos em 12 meses conforme haja infra\u00e7\u00f5es grav\u00edssimas ou n\u00e3o. Atualmente, a suspens\u00e3o ocorre com 20 pontos, independentemente do tipo de infra\u00e7\u00e3o.<\/p>\n\n\n\n<p>Dessa forma, o condutor ser\u00e1 suspenso com 20 pontos se tiver cometido duas ou mais infra\u00e7\u00f5es grav\u00edssimas; com 30 pontos se tiver uma infra\u00e7\u00e3o grav\u00edssima; e com 40 pontos se n\u00e3o tiver cometido infra\u00e7\u00e3o grav\u00edssima no per\u00edodo de 12 meses.<\/p>\n\n\n\n<p>Os condutores que exercem atividades remuneradas ter\u00e3o seu documento suspenso com 40 pontos, independentemente da natureza das infra\u00e7\u00f5es. Essa regra atinge motoristas de \u00f4nibus ou caminh\u00f5es, taxistas, motoristas de aplicativo ou moto-taxistas. Se esses condutores participarem de curso preventivo de reciclagem ao atingir 30 pontos, em 12 meses, toda a pontua\u00e7\u00e3o ser\u00e1 zerada.&nbsp;<\/p>\n\n\n\n<p>A Secretaria Geral da Presid\u00eancia informou que o presidente vetou alguns pontos da nova lei, mas, at\u00e9 o fechamento da mat\u00e9ria, esses vetos ainda n\u00e3o haviam sido detalhados.<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Aline Leal- Publicado em 13\/10\/2020 &#8211; 20:46 Por Pedro Rafael Vilela &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/p>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-653626182\"><div id=\"jorna-3088375223\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Regras come\u00e7am a valer em 180 dias O presidente Jair Bolsonaro sancionou nesta ter\u00e7a-feira (13),&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[12,2],"tags":[],"class_list":["post-2214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2214"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2214\/revisions"}],"predecessor-version":[{"id":2216,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2214\/revisions\/2216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/2215"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}