{"id":22311,"date":"2023-02-02T09:12:04","date_gmt":"2023-02-02T12:12:04","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=22311"},"modified":"2023-02-02T09:12:06","modified_gmt":"2023-02-02T12:12:06","slug":"pastor-apos-vitoria-de-pacheco-serao-os-quatro-anos-mais-dificeis-da-republica","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2023\/02\/02\/pastor-apos-vitoria-de-pacheco-serao-os-quatro-anos-mais-dificeis-da-republica\/","title":{"rendered":"Pastor ap\u00f3s vit\u00f3ria de Pacheco: \u201cSer\u00e3o os quatro anos mais dif\u00edceis da Rep\u00fablica\u201d"},"content":{"rendered":"\n<p>Aguardada por muitos como a mais importante elei\u00e7\u00e3o para a presid\u00eancia do Senado da hist\u00f3ria do Brasil, a vota\u00e7\u00e3o que cravou o nome vitorioso chegou ao fim, e o resultado n\u00e3o foi o que aliados do ex-presidente Jair Bolsonaro esperavam: Rodrigo Pacheco foi reeleito com 49 votos!<\/p>\n\n\n\n<p>Pacheco derrotou o seu principal rival, o ex-ministro Rog\u00e9rio Marinho, que obteve 32 votos. Ap\u00f3s o encerramento da vota\u00e7\u00e3o e a divulga\u00e7\u00e3o do resultado nesta quarta-feira (1\u00b0), v\u00e1rias personalidades se manifestaram por meio das redes sociais, incluindo o renomado pastor e escritor Geremias Couto.<\/p>\n\n\n\n<p>Segundo o l\u00edder religioso, com a reelei\u00e7\u00e3o de Pacheco na presid\u00eancia do Senado fica \u201ccada vez mais dif\u00edcil o exerc\u00edcio da liberdade no Brasil\u201d, pois o \u201cSTF continuar\u00e1 a nadar de bra\u00e7adas\u201d, acredita o pastor, em refer\u00eancia \u00e0s acusa\u00e7\u00f5es de ativismo judicial por parte de ministros do Supremo.<\/p>\n\n\n\n<p>O atual presidente do Senado \u00e9 criticado por sua omiss\u00e3o diante dos supostos arb\u00edtrios de ministros do STF. Assim, Geremias Couto acredita que os magistrados continuar\u00e3o \u201clegislando em lugar do Legislativo e tomando decis\u00f5es ao arrepio da lei.\u201d<\/p>\n\n\n\n<p>Mais do que isso, diz o pastor, a oposi\u00e7\u00e3o tamb\u00e9m ser\u00e1 \u201ccerceada por todos os meios e modos. Ser\u00e3o os quatro anos mais dif\u00edceis da Rep\u00fablica\u201d, afirma Geremias por meio dos seus perfis nas&nbsp;<a href=\"https:\/\/twitter.com\/pastorgeremias\/status\/1620897730095898624\">redes sociais<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u201cO Brasil acabou\u201d<\/h2>\n\n\n\n<p>Outro renomado te\u00f3logo que tamb\u00e9m vem assumindo posi\u00e7\u00f5es contundentes no tocante ao cen\u00e1rio pol\u00edtico brasileiro \u00e9 o pastor, conferencista e escritor Renato Vargens. Ele foi mais um entre os l\u00edderes protestantes lamentaram a vit\u00f3ria de Pacheco no Senado.<\/p>\n\n\n\n<p>\u201cO Brasil acabou!\u201d,&nbsp;<a href=\"https:\/\/twitter.com\/renatovargens\/status\/1620894478834995200\">postou<\/a>&nbsp;Vargens nas redes sociais. \u201cEstamos testemunhando o fim do Brasil. Entregues a maldade e estatiza\u00e7\u00e3o da desgra\u00e7a\u201d, acrescentou, afirmando em outra publica\u00e7\u00e3o que \u201cos pol\u00edticos sempre foram inimigos do povo. Eles pensam neles e nunca na na\u00e7\u00e3o.\u201d<\/p>\n\n\n\n<p>Tamb\u00e9m entre os nomes mais influentes no cen\u00e1rio pol\u00edtico nacional no tocante \u00e0 lideran\u00e7a evang\u00e9lica, o pastor<a href=\"https:\/\/noticias.gospelmais.com.br\/malafaia-chama-moraes-ditador-critica-imprensa-158523.html\">\u00a0Silas Malafaia<\/a>\u00a0reagiu em tom de desafio ao presidente reeleito do Senado.<\/p>\n\n\n\n<p>O pastor\u00a0<a href=\"https:\/\/twitter.com\/PastorMalafaia\/status\/1620890485782106113\">afirmou<\/a>\u00a0que em breve o Brasil saber\u00e1 se \u201cteremos um senado soberano como poder legislativo que representa o povo ou um senado comprado na sua maioria pelo governo, capacho de Alexandre de Moraes\u201d. <\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong><a href=\"https:\/\/noticias.gospelmais.com.br\/author\/willfilho\">WILL R. FILHO<\/a><\/strong>10 HORAS ATR\u00c1S-noticias.gospelmais<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-3324575534\"><div id=\"jorna-657393397\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Aguardada por muitos como a mais importante elei\u00e7\u00e3o para a presid\u00eancia do Senado da hist\u00f3ria&#8230;<\/p>\n","protected":false},"author":2,"featured_media":22312,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15,13],"tags":[],"class_list":["post-22311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-cristao","category-politica"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/22311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=22311"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/22311\/revisions"}],"predecessor-version":[{"id":22313,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/22311\/revisions\/22313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/22312"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=22311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=22311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=22311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}