{"id":24980,"date":"2023-05-29T12:47:10","date_gmt":"2023-05-29T15:47:10","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=24980"},"modified":"2023-05-29T12:47:10","modified_gmt":"2023-05-29T15:47:10","slug":"sinais-do-fim-gastos-com-guerras-no-mundo-atingem-recorde-de-us-2-trilhoes","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2023\/05\/29\/sinais-do-fim-gastos-com-guerras-no-mundo-atingem-recorde-de-us-2-trilhoes\/","title":{"rendered":"Sinais do fim? Gastos com guerras no mundo atingem recorde de US$ 2 trilh\u00f5es"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u201cMesmo em meio \u00e0s consequ\u00eancias econ\u00f4micas da pandemia por Covid-19, os gastos militares mundiais atingiram n\u00edveis recordes\u201d, disse um especialista.<\/h2>\n\n\n\n<p>Enquanto as na\u00e7\u00f5es&nbsp;<a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/acredito-que-igreja-esteja-vivendo-seu-ultimo-ciclo-aqui-na-terra-diz-escritor.html\"><strong>clamam por paz<\/strong><\/a>, alimenta\u00e7\u00e3o, \u00e1gua, seguran\u00e7a, dignidade e amor, super pot\u00eancias mundiais investem cada vez mais na guerra.&nbsp;<\/p>\n\n\n\n<p>De acordo com um relat\u00f3rio publicado pelo Stockholm International Peace Research Institute (SIPRI), no ano passado, os&nbsp;<a href=\"https:\/\/guiame.com.br\/gospel\/noticias\/ira-revela-nova-doutrina-militar-e-parece-se-preparar-para-guerra-um-mar-de-sangue.html\"><strong>gastos militares mundiais<\/strong><\/a>&nbsp;ultrapassaram a marca de US$ 2 trilh\u00f5es (equivalente a&nbsp;\u20ac 1,8 trilh\u00e3o ou R$ 10 trilh\u00f5es).<\/p>\n\n\n\n<p>Comparado com os anos anteriores, este foi o maior n\u00famero de gastos b\u00e9licos desde 2021, quando os gastos globais totais com defesa atingiram US$ 2,113 trilh\u00f5es, ou seja, 0,7% a mais do que em 2020 e 12% a mais do que em 2012, conforme a DW.<\/p>\n\n\n\n<p>\u201cMesmo em meio \u00e0s consequ\u00eancias econ\u00f4micas da pandemia por Covid-19, os gastos militares mundiais atingiram n\u00edveis recordes\u201d, disse Diego Lopes da Silva, pesquisador s\u00eanior do Programa de Despesas Militares e Produ\u00e7\u00e3o de Armas do SIPRI.<\/p>\n\n\n\n<p><strong>Quais na\u00e7\u00f5es investem mais em guerras?<\/strong><\/p>\n\n\n\n<p>O relat\u00f3rio aponta para os pa\u00edses que mais&nbsp;<a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/estamos-no-principio-das-dores-pastor-avalia-que-nada-se-compara-com-o-que-vira.html\"><strong>esbanjam dinheiro com as guerras<\/strong><\/a>&nbsp;\u2014 Estados Unidos, China, \u00cdndia, Reino Unido e R\u00fassia, que juntos representaram 62% do total gasto, conforme dados de 2021.<\/p>\n\n\n\n<p>Somente os EUA e a China responderam por 52% dos gastos, segundo o SIPRI. \u201cOs gastos da China aumentaram pelo 27\u00ba ano consecutivo, atingindo US$ 293 bilh\u00f5es, enquanto os gastos da R\u00fassia cresceram pelo terceiro ano consecutivo em 2021\u201d, diz a organiza\u00e7\u00e3o.<\/p>\n\n\n\n<p>Os gastos da R\u00fassia em 2021 aumentaram 2,9%, atingindo US$ 65,9 bilh\u00f5es, ou 4,1% de seu PIB, segundo o relat\u00f3rio. O aumento russo nos gastos foi auxiliado por pre\u00e7os mais altos para as exporta\u00e7\u00f5es russas de combust\u00edvel e ocorreu em um momento em que se preparava para invadir a Ucr\u00e2nia, disseram especialistas do SIPRI.<\/p>\n\n\n\n<p>Os gastos militares da Ucr\u00e2nia aumentaram 72% desde a anexa\u00e7\u00e3o da Crimeia em 2014. Foram gastos US$ 5,9 bilh\u00f5es, ou 3,2% do PIB do pa\u00eds, em 2021.<\/p>\n\n\n\n<p><strong>Quem gasta mais com guerras na Europa?<\/strong><\/p>\n\n\n\n<p>De acordo com o relat\u00f3rio, a Alemanha \u00e9 o terceiro pa\u00eds que mais gasta na Europa: \u201cOs gastos militares totais na Europa em 2021 totalizaram US$ 418 bilh\u00f5es, 3% a mais do que em 2020 e 19% a mais do que em 2012\u201d.<\/p>\n\n\n\n<p>Os outros dois pa\u00edses s\u00e3o Reino Unido e Fran\u00e7a. Os gastos tamb\u00e9m aumentaram na \u00c1sia e Oceania. J\u00e1 no Oriente M\u00e9dio houve uma queda no investimento com guerras em -3,3% e nas Am\u00e9ricas em -1,2%.<\/p>\n\n\n\n<p>Uma das mudan\u00e7as mais not\u00e1veis \u200b\u200bnos gastos com defesa veio do Ir\u00e3, onde o or\u00e7amento militar do pa\u00eds aumentou pela primeira vez em quatro anos, chegando a US$ 24,6 bilh\u00f5es. O financiamento para o Corpo da Guarda Revolucion\u00e1ria Isl\u00e2mica, em particular, cresceu 14% em compara\u00e7\u00e3o com 2020.<\/p>\n\n\n\n<p><strong>O que a B\u00edblia diz sobre as guerras?<\/strong><\/p>\n\n\n\n<p>Conforme Daniel 8.19, quando as na\u00e7\u00f5es lutam umas contra as outras apontam para o \u201ctempo do fim\u201d e conforme Jesus no Serm\u00e3o do Monte, em Mateus 24, esse tempo seria marcado por v\u00e1rios sinais, entre eles, \u201cguerras e rumores de guerras\u201d.&nbsp;<\/p>\n\n\n\n<p>H\u00e1 especialistas que consideram a possibilidade de uma&nbsp;<a href=\"https:\/\/guiame.com.br\/gospel\/noticias\/estamos-beira-de-uma-terceira-guerra-mundial-diz-aliado-de-putin.html\"><strong>Terceira Guerra Mundial<\/strong><\/a>, at\u00e9 mesmo a&nbsp;<a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/5-bilhoes-da-populacao-mundial-morreria-se-houvesse-uma-guerra-nuclear-diz-estudo.html\"><strong>n\u00edvel nuclear<\/strong><\/a>, mas alguns pastores descartam essa hip\u00f3tese dizendo que n\u00e3o \u00e9 isso o que a B\u00edblia afirma.<\/p>\n\n\n\n<p>O pastor e te\u00f3logo Augustus Nicodemus, por exemplo, disse que&nbsp;<a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/5-bilhoes-da-populacao-mundial-morreria-se-houvesse-uma-guerra-nuclear-diz-estudo.html\"><strong>\u201co mundo n\u00e3o vai acabar numa guerra nuclear\u201d<\/strong><\/a>. Ele enfatizou esse pensamento atrav\u00e9s das palavras de Jesus: \u201cAinda n\u00e3o \u00e9 o fim\u201d, em Mateus 24.<\/p>\n\n\n\n<p>\u201cAs guerras s\u00e3o necess\u00e1rias para mostrar a nossa impot\u00eancia de resolver os problemas. O homem n\u00e3o consegue viver em paz h\u00e1 mais de dois mil anos\u201d, disse ao sublinhar que nunca houve um ano sequer sem \u201cuma na\u00e7\u00e3o brigando com a outra em alguma parte desse planeta\u201d.<\/p>\n\n\n\n<p>\u201cQuando eu olho para as guerras, meu cora\u00e7\u00e3o se entristece, eu fico temeroso, mas eu sei que ainda n\u00e3o \u00e9 o fim. Isso s\u00f3 prova que Jesus falou a verdade e isso mostra o quanto precisamos que Ele venha para instalar a&nbsp;<a href=\"https:\/\/guiame.com.br\/colunistas\/cris-beloni\/humanidade-vai-alcancar-tao-desejada-paz-mundial-veja-o-que-biblia-diz-sobre-isso.html\"><strong>paz verdadeira<\/strong><\/a>\u201d, disse.<\/p>\n\n\n\n<p>Nicodemus lembra que a humanidade ainda ver\u00e1 muitas calamidades, fomes, cat\u00e1strofes naturais,\u00a0<a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/quais-sao-os-sinais-da-vinda-de-jesus-e-do-fim-dos-tempos-pastor-aponta-para-os-detalhes.html\"><strong>terremotos e pestes<\/strong><\/a>. \u201cEle disse que tudo isso aconteceria em v\u00e1rios lugares e assim tem acontecido\u201d, concluiu o pastor ao citar Jesus.<\/p>\n\n\n\n<p><strong>FONTE:<\/strong>\u00a0GUIAME, COM INFORMA\u00c7\u00d5ES DA DW <strong>ATUALIZADO:\u00a0<\/strong>SEXTA-FEIRA, 26 DE MAIO DE 2023 \u00c0S 13:54<\/p>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-51714195\"><div id=\"jorna-4125253758\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u201cMesmo em meio \u00e0s consequ\u00eancias econ\u00f4micas da pandemia por Covid-19, os gastos militares mundiais atingiram&#8230;<\/p>\n","protected":false},"author":2,"featured_media":24981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3,15],"tags":[],"class_list":["post-24980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo","category-mundo-cristao"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=24980"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24980\/revisions"}],"predecessor-version":[{"id":24982,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24980\/revisions\/24982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/24981"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=24980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=24980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=24980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}