{"id":25933,"date":"2023-07-14T14:12:37","date_gmt":"2023-07-14T17:12:37","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=25933"},"modified":"2023-07-14T14:12:37","modified_gmt":"2023-07-14T17:12:37","slug":"25933","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2023\/07\/14\/25933\/","title":{"rendered":""},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">CNJ puniu magistrados por falas mais \u201cbrandas\u201d que a de Barroso<\/h1>\n\n\n\n<p>Ju\u00edzes e desembargadores que fizeram manifesta\u00e7\u00f5es pol\u00edticas foram punidos recentemente<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/api.whatsapp.com\/send?text=CNJ%20puniu%20magistrados%20por%20falas%20mais%20%E2%80%9Cbrandas%E2%80%9D%20que%20a%20de%20Barroso%20https:\/\/pleno.news\/brasil\/politica-nacional\/cnj-puniu-magistrados-por-falas-mais-brandas-que-a-de-barroso.html\"><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/pleno.news\/brasil\/politica-nacional\/cnj-puniu-magistrados-por-falas-mais-brandas-que-a-de-barroso.html#!\"><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/pleno.news\/brasil\/politica-nacional\/cnj-puniu-magistrados-por-falas-mais-brandas-que-a-de-barroso.html#!\"><\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Paulo Moura &#8211;&nbsp;14\/07\/2023&nbsp;08h37 | atualizado em 14\/07\/2023 11h14<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/static.cdn.pleno.news\/2023\/01\/CNJ-bloqueou-credencial-que-registrou-mandado-contra-Moraes-e1672941639596-1024x690.jpg\" alt=\"\" class=\"wp-image-1068414\"\/><figcaption class=\"wp-element-caption\">Plen\u00e1rio do CNJ&nbsp;Foto: R\u00f4mulo Serpa\/Ag\u00eancia CNJ<\/figcaption><\/figure>\n\n\n\n<p>A declara\u00e7\u00e3o feita na \u00faltima quarta-feira (12) pelo ministro Lu\u00eds Roberto Barroso, do Supremo Tribunal Federal (<a href=\"http:\/\/pleno.news\/tag\/stf\" target=\"_blank\" rel=\"noreferrer noopener\">STF<\/a>), sobre a derrota do \u201cbolsonarismo\u201d, certamente poderia ser alvo de puni\u00e7\u00e3o no Conselho Nacional de Justi\u00e7a (<a href=\"http:\/\/pleno.news\/tag\/cnj\" target=\"_blank\" rel=\"noreferrer noopener\">CNJ<\/a>) se fosse aplicado o hist\u00f3rico recente de rigidez nas puni\u00e7\u00f5es aplicadas contra outros magistrados ao redor do pa\u00eds.<\/p>\n\n\n\n<p>O \u00f3rg\u00e3o, estabelecido na Constitui\u00e7\u00e3o para \u201czelar pelo controle da atua\u00e7\u00e3o administrativa\u201d do Poder Judici\u00e1rio, tem adotado uma pol\u00edtica de punir manifesta\u00e7\u00f5es pol\u00edticas feitas por ju\u00edzes e desembargadores. Um dos casos recentes foi o do juiz da Vara de Execu\u00e7\u00f5es Penais de Manaus, no Amazonas, Luis Carlos Valois.<\/p>\n\n\n\n<p>Em janeiro, o magistrado teve as contas suspensas nas redes sociais. Em postagens, afirmou que a ex-presidente Dilma Rousseff n\u00e3o cometeu crime de responsabilidade, concluindo que o impeachment n\u00e3o teve \u201cpressuposto legal\u201d. Valois tamb\u00e9m chegou a postar uma charge que ironizava os atos do dia 8 de janeiro.<\/p>\n\n\n\n<p>Na decis\u00e3o que levou \u00e0 derrubada dos perfis do juiz, o corregedor nacional de Justi\u00e7a, Luis Felipe Salom\u00e3o, se baseou no artigo 95 da Constitui\u00e7\u00e3o Federal, que veda a ju\u00edzes \u201cdedicar-se \u00e0 atividade pol\u00edtico-partid\u00e1ria\u201d. Salom\u00e3o disse na decis\u00e3o que \u201ca conduta individual do magistrado com conte\u00fado pol\u00edtico-partid\u00e1rio macula a confian\u00e7a da sociedade em rela\u00e7\u00e3o \u00e0 credibilidade\u201d da Justi\u00e7a.<\/p>\n\n\n\n<p>J\u00e1 em dezembro do ano passado, Salom\u00e3o bloqueou os perfis da desembargadora federal Maria do Carmo Cardoso, do Tribunal Regional Federal da 1\u00aa Regi\u00e3o (TRF-1), por ter elogiado as manifesta\u00e7\u00f5es que ocorriam diante dos quart\u00e9is ap\u00f3s a vit\u00f3ria eleitoral do presidente Luiz In\u00e1cio Lula da Silva (PT).<\/p>\n\n\n\n<p>\u2013 Copa a gente v\u00ea depois, 99% dos jogadores do Brasil vivem na Europa, o t\u00e9cnico \u00e9 petista e a Globolixo \u00e9 de esquerda, nossa Sele\u00e7\u00e3o verdadeira est\u00e1 na frente dos quart\u00e9is \u2013 escreveu a magistrada, na publica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Em novembro de 2022, o CNJ aplicou pena de censura \u00e0 ju\u00edza Regiane Tonet dos Santos, do Tribunal de Justi\u00e7a do Paran\u00e1 (TJPR), por postagens, feitas em 2017 e 2018, com cr\u00edticas ao STF, \u00e0 presidente do PT, Gleisi Hoffmann, e ao ex-presidente do partido Jos\u00e9 Dirceu.<\/p>\n\n\n\n<p>J\u00e1 durante o per\u00edodo eleitoral, em outubro do ano passado, Salom\u00e3o determinou a suspens\u00e3o das redes de dois magistrados por manifesta\u00e7\u00f5es pol\u00edticas. Uma delas foi do desembargador Marcelo Buhatem, do Tribunal de Justi\u00e7a do Rio de Janeiro (TJRJ), por ter postado que o hoje presidente Lula era \u201cconvidado de honra do Comando Vermelho\u201d.<\/p>\n\n\n\n<p>Na mesma sess\u00e3o, tamb\u00e9m foi tomada a decis\u00e3o de suspender do Twitter a ju\u00edza Ros\u00e1lia Sarmento, do Tribunal de Justi\u00e7a do Amazonas (TJAM), por publicar dezenas de mensagens declarando e pedindo voto em Lula e com cr\u00edticas a Bolsonaro.<\/p>\n\n\n\n<p>\u2013 A conduta individual do magistrado com conte\u00fado pol\u00edtico-partid\u00e1rio arru\u00edna a confian\u00e7a da sociedade em rela\u00e7\u00e3o \u00e0 credibilidade, \u00e0 legitimidade e \u00e0 respeitabilidade da atua\u00e7\u00e3o da Justi\u00e7a, atingindo o pr\u00f3prio Estado de Direito que a Constitui\u00e7\u00e3o objetiva resguardar \u2013 destacou Salom\u00e3o, na ocasi\u00e3o.<\/p>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-2159952900\"><div id=\"jorna-75783838\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>CNJ puniu magistrados por falas mais \u201cbrandas\u201d que a de Barroso Ju\u00edzes e desembargadores que&#8230;<\/p>\n","protected":false},"author":2,"featured_media":25934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,13],"tags":[],"class_list":["post-25933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-politica"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=25933"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25933\/revisions"}],"predecessor-version":[{"id":25935,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25933\/revisions\/25935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/25934"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=25933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=25933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=25933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}