{"id":26460,"date":"2023-07-24T12:29:21","date_gmt":"2023-07-24T15:29:21","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=26460"},"modified":"2023-07-24T12:30:16","modified_gmt":"2023-07-24T15:30:16","slug":"16-000-grupos-de-oracao-surgem-em-taiwan-em-meio-as-ameacas-da-china","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2023\/07\/24\/16-000-grupos-de-oracao-surgem-em-taiwan-em-meio-as-ameacas-da-china\/","title":{"rendered":"16.000 grupos de ora\u00e7\u00e3o surgem em Taiwan, em meio \u00e0s amea\u00e7as da China"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ap\u00f3s a invas\u00e3o da Ucr\u00e2nia pela R\u00fassia, o temor de que Xi Jinping possa &#8220;anexar\u201d Taiwan aumentou, assim como uma poss\u00edvel guerra na regi\u00e3o.<\/h2>\n\n\n\n<p>As amea\u00e7as de invas\u00e3o de\u00a0<strong><a href=\"https:\/\/guiame.com.br\/gospel\/noticias\/exercicios-militares-da-china-em-taiwan-ha-algum-papel-no-fim-dos-tempos.html\">Taiwan<\/a><\/strong>\u00a0pela China v\u00eam aumentando h\u00e1 meses, gerando grandes protestos na ilha asi\u00e1tica, al\u00e9m de alertas internacionais<\/p>\n\n\n\n<p>Segundo um relat\u00f3rio do WION News, &#8220;as tens\u00f5es est\u00e3o chegando ao auge. A beliger\u00e2ncia de Pequim est\u00e1 mais uma vez deixando Taipei [capital de Taiwan] nervosa&#8221;.<\/p>\n\n\n\n<p>Recentemente, militares chineses divulgaram imagens mostrando como seriam os ataques simulados a Taiwan.<\/p>\n\n\n\n<p>Um outro relat\u00f3rio, da SkyNews London, alerta que uma guerra em Taiwan \u201cteria consequ\u00eancias econ\u00f4micas catastr\u00f3ficas n\u00e3o apenas para esta ilha, mas para todo o mundo&#8221;.<\/p>\n\n\n\n<p>Diante do ass\u00e9dio militar chin\u00eas quase que diariamente, a pequena ilha na costa continental est\u00e1 \u201crefor\u00e7ando suas for\u00e7as armadas e treinando com novas armas dos EUA&#8221;. As informa\u00e7\u00f5es da rede norte-americana CBS News, tamb\u00e9m s\u00e3o de que as for\u00e7as armadas dos EUA se preparam para uma poss\u00edvel guerra em grande escala.<\/p>\n\n\n\n<p>&#8220;Para ser claro, n\u00e3o buscamos conflito ou confronto, mas n\u00e3o recuaremos diante de bullying ou coer\u00e7\u00e3o&#8221;, disse o desafiador secret\u00e1rio de Defesa dos EUA, Lloyd Austin.<\/p>\n\n\n\n<p><strong>Crist\u00e3os de Joelhos<\/strong><\/p>\n\n\n\n<p>Diante das tens\u00f5es e amea\u00e7as de guerra alardeadas durante o dia, os crist\u00e3os de Taiwan est\u00e3o de joelhos \u00e0 noite.<\/p>\n\n\n\n<p>&#8220;As&nbsp;<strong><a href=\"https:\/\/guiame.com.br\/gospel\/testemunhos\/familia-escapa-de-incendio-milagrosamente-nunca-vamos-parar-de-dar-gloria-deus.html\">ora\u00e7\u00f5es<\/a><\/strong>&nbsp;unidas e ora\u00e7\u00f5es de jejum das igrejas em Taiwan s\u00e3o muito mais [intensas] do que nunca. \u00c9 um movimento de ora\u00e7\u00e3o sem precedentes&#8221;, disse Brian Lu, pastor da Shekinah House of Bread of Life em Taipei, \u00e0 CBN News.<\/p>\n\n\n\n<p>O pastor diz que por toda a ilha, as pessoas se re\u00fanem diariamente, 24 horas por dia, para orar por reavivamento, unidade, arrependimento e prote\u00e7\u00e3o de seu pa\u00eds.<\/p>\n\n\n\n<p>Gordon Huang, um proeminente l\u00edder da igreja aqui, disse acreditar \u201cque algo t\u00e3o simples est\u00e1 come\u00e7ando a ter um impacto t\u00e3o grande sobre as pessoas na igreja e tamb\u00e9m sobre as pessoas ao redor da igreja&#8221;.<\/p>\n\n\n\n<p>Huang \u00e9 l\u00edder de uma das denomina\u00e7\u00f5es mais conhecidas de Taiwan, com sua igreja instalada no topo do marco ic\u00f4nico conhecido como Taipei 101, no cora\u00e7\u00e3o da capital.<\/p>\n\n\n\n<p>Seu temor \u00e9 de que a guerra com a China esteja pr\u00f3xima e diz desejar que os crist\u00e3os estejam prontos.<\/p>\n\n\n\n<p>&#8220;Acho que uma coisa com certeza \u00e9 que as pessoas v\u00e3o ficar t\u00e3o abaladas e v\u00e3o querer ouvir o Evangelho. Voc\u00ea est\u00e1 pronto ou vai fugir?&#8221;, questionou Huang em sua entrevista \u00e0 CBN News.<\/p>\n\n\n\n<p><strong>\u2018Orar \u00e9 urgente\u2019<\/strong><\/p>\n\n\n\n<p>Don Young, que serviu como mission\u00e1rio americano na&nbsp;<strong><a href=\"https:\/\/guiame.com.br\/gospel\/missoes-acao-social\/seca-afeta-o-trabalho-de-traducao-biblica-na-africa-ore-por-nos.html\">\u00c1frica Ocidental<\/a><\/strong>&nbsp;por 15 anos, conta que esse tema de agita\u00e7\u00e3o tomou conta de suas preocupa\u00e7\u00f5es h\u00e1 dois anos. \u201cEu tinha ouvido do Senhor: &#8216;O tempo \u00e9 curto, a hora \u00e9 urgente, \u00e9 hora de orar&#8217;\u201d, recorda-se.<\/p>\n\n\n\n<p>Atualmente, ele tem viajado pelo mundo ensinando aos crist\u00e3os como ter uma jornada de ora\u00e7\u00e3o mais profunda com Deus.<\/p>\n\n\n\n<p>Em maio de 2021, o pastor Young relatou que recebeu uma revela\u00e7\u00e3o do Senhor, na qual foi transmitida uma mensagem sobre um evento s\u00edsmico que afetaria profundamente a na\u00e7\u00e3o. Ele compartilhou essa mensagem com os l\u00edderes da igreja na ilha, desencadeando assim um poderoso movimento de ora\u00e7\u00e3o que se espalhou por Taiwan desde ent\u00e3o.<\/p>\n\n\n\n<p><strong>\u2018Movimento de ora\u00e7\u00e3o\u2019<\/strong><\/p>\n\n\n\n<p>O movimento RPG (Revival Prayer Group) teve in\u00edcio com a uni\u00e3o de algumas pessoas em pequenos grupos dedicados a orar por Taiwan. Eles se comprometeram a manter uma corrente de ora\u00e7\u00e3o ininterrupta durante as 24 horas do dia em prol da na\u00e7\u00e3o taiwanesa.<\/p>\n\n\n\n<p>&#8220;A ora\u00e7\u00e3o \u00e9 a \u00fanica maneira pela qual voc\u00ea pode superar qualquer coisa que estreme\u00e7a&#8221;, disse Young, que agora trabalha no College of Prayer International, com sede na Ge\u00f3rgia.<\/p>\n\n\n\n<p>&#8220;Jesus disse tudo pela ora\u00e7\u00e3o. Ele n\u00e3o fez nada al\u00e9m da ora\u00e7\u00e3o. Antes era apenas um momento com Deus, todos n\u00f3s os temos, mas agora estava se transformando em um movimento para Deus. H\u00e1 uma grande diferen\u00e7a entre um momento e um movimento.&#8221;<\/p>\n\n\n\n<p>\u201cComo o RPG tem duas ou tr\u00eas pessoas em um grupo, se um dia acontecer uma guerra e n\u00e3o houver edif\u00edcios f\u00edsicos onde as pessoas possam se encontrar, ainda podemos orar em pequenos grupos para que a igreja n\u00e3o seja afetada\u201d, disse o pastor Lu.<\/p>\n\n\n\n<p>Desde 1978, Peter Yang tem exercido o pastorado e plantado igrejas em Taiwan. Segundo ele, nunca viu o tipo de unidade como est\u00e1 acontecendo agora, com igrejas de diversas linhas denominacionais unidas no mesmo prop\u00f3sito.<\/p>\n\n\n\n<p>&#8220;O que est\u00e1 acontecendo hoje \u00e9 t\u00e3o raro&#8221;, disse o reverendo Yang, que lidera a Alian\u00e7a Crist\u00e3 de Taiwan. &#8220;Todos os dias, todas as semanas, me junto a pastores de outras igrejas, outras denomina\u00e7\u00f5es, e oramos por nossas cidades, por nossa na\u00e7\u00e3o por outros pa\u00edses. \u00c9 incr\u00edvel, \u00e9 claramente obra de Deus. A unidade ser\u00e1 o legado deste movimento.&#8221;<\/p>\n\n\n\n<p><strong>Milhares de grupos de ora\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>O movimento dez surgiu mais de 16.000 Grupos de Ora\u00e7\u00e3o de Avivamento, que tem inclusive a participa\u00e7\u00e3o de membros da&nbsp;<strong><a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/igreja-clandestina-prospera-em-hong-kong-em-meio-perseguicao.html\">igreja clandestina<\/a><\/strong>&nbsp;chinesa.<\/p>\n\n\n\n<p>\u201cQueremos ter 300.000 grupos de RPG onde tamb\u00e9m nos unimos com igrejas na China, reunindo todos os l\u00edderes e membros, de ambos os lados, para que possamos orar com o objetivo de impactar a China tamb\u00e9m\u201d, disse Yang.<\/p>\n\n\n\n<p><strong>A ora\u00e7\u00e3o faz a diferen\u00e7a<\/strong><\/p>\n\n\n\n<p>A&nbsp;<strong><a href=\"https:\/\/guiame.com.br\/gospel\/noticias\/russia-ataca-ucrania-e-desperta-temores-de-uma-terceira-guerra-mundial.html\">invas\u00e3o da Ucr\u00e2nia pela R\u00fassia<\/a><\/strong>&nbsp;no ano passado causou grande apreens\u00e3o na ilha de 23 milh\u00f5es de pessoas, com muitas compara\u00e7\u00f5es entre a obsess\u00e3o de Putin em assumir o controle da Ucr\u00e2nia e a determina\u00e7\u00e3o de Xi Jinping de &#8220;anexar&#8221; Taiwan.<\/p>\n\n\n\n<p>H\u00e1 um temor crescente de que uma guerra possa eclodir tamb\u00e9m em Taiawan sem aviso pr\u00e9vio, o que est\u00e1 levando muitas pessoas a buscar ativamente a paz em meio \u00e0s cont\u00ednuas amea\u00e7as que chegam de Pequim.<\/p>\n\n\n\n<p>\u201cMuitas pessoas vieram e se juntaram ao RPG porque ouviram testemunhos de como Deus est\u00e1 respondendo \u00e0s ora\u00e7\u00f5es, ent\u00e3o voc\u00ea tem muitas pessoas incr\u00e9dulas se juntando ao RPG e, ao abrirem suas bocas e orarem, elas experimentam o Senhor, ent\u00e3o tamb\u00e9m est\u00e3o vindo ao Senhor\u201d, disse o pastor Huang.<\/p>\n\n\n\n<p>Muitos l\u00edderes religiosos disseram \u00e0 CBN News que um poss\u00edvel confronto entre Taiwan e China seria como Davi enfrentando Golias, que produziria uma devasta\u00e7\u00e3o incalcul\u00e1vel, al\u00e9m de perda de vidas.<\/p>\n\n\n\n<p>Para eles, a ora\u00e7\u00e3o pode fazer a diferen\u00e7a entre a guerra e a paz.&nbsp;<\/p>\n\n\n\n<p>\u201cPedimos \u00e0s igrejas de todo o mundo que orem por este lugar mais perigoso do mundo hoje, para que a paz de Deus possa vir sobre as rela\u00e7\u00f5es atrav\u00e9s do Estreito\u201d, disse o pastor Lu.<\/p>\n\n\n\n<p>\u201cOs chineses \u00e9tnicos n\u00e3o devem matar uns aos outros, mas, em vez disso, devemos cumprir juntos o movimento de miss\u00f5es do fim dos tempos, para trazer o\u00a0<strong><a href=\"https:\/\/guiame.com.br\/gospel\/missoes-acao-social\/casal-que-compartilha-o-evangelho-com-criancas-escapa-de-prisao-na-china.html\">Evangelho<\/a><\/strong>\u00a0de volta a Jerusal\u00e9m\u201d.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>FONTE:<\/strong>\u00a0GUIAME, COM INFORMA\u00c7\u00d5ES DA CBN NEWS <strong>ATUALIZADO:\u00a0<\/strong>SEGUNDA-FEIRA, 24 DE JULHO DE 2023 \u00c0S 09:54<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-2040686601\"><div id=\"jorna-1872101916\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a invas\u00e3o da Ucr\u00e2nia pela R\u00fassia, o temor de que Xi Jinping possa &#8220;anexar\u201d&#8230;<\/p>\n","protected":false},"author":2,"featured_media":26461,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8,15,2],"tags":[],"class_list":["post-26460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","category-mundo-cristao","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=26460"}],"version-history":[{"count":2,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26460\/revisions"}],"predecessor-version":[{"id":26463,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26460\/revisions\/26463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/26461"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=26460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=26460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=26460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}