{"id":27357,"date":"2023-09-02T23:19:22","date_gmt":"2023-09-03T02:19:22","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=27357"},"modified":"2023-09-02T23:19:50","modified_gmt":"2023-09-03T02:19:50","slug":"74-dos-adolescentes-brasileiros-acreditam-em-jesus-diz-pesquisa","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2023\/09\/02\/74-dos-adolescentes-brasileiros-acreditam-em-jesus-diz-pesquisa\/","title":{"rendered":"74% dos adolescentes brasileiros acreditam em Jesus, diz pesquisa"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">O objetivo do estudo realizado pelo Grupo Barna foi de ajudar os l\u00edderes da igreja a compreender como alcan\u00e7ar os adolescentes.<\/h2>\n\n\n\n<p>Um novo estudo, que enfatiza o acompanhamento das percep\u00e7\u00f5es e do envolvimento dos adolescentes na Am\u00e9rica Latina com tr\u00eas elementos cruciais da f\u00e9 crist\u00e3: Jesus, a B\u00edblia e a justi\u00e7a, mostrou que milhares est\u00e3o se comprometendo com o cristianismo.&nbsp;<\/p>\n\n\n\n<p>A&nbsp;<a href=\"https:\/\/www.guiame.com.br\/gospel\/noticias\/brasil-e-um-dos-paises-que-mais-acredita-em-deus-revela-pesquisa.html\"><strong>pesquisa&nbsp;<\/strong><\/a>recente \u201cThe Open Generation Survey\u201d (<em>\u201cGera\u00e7\u00e3o Aberta\u201d<\/em>), realizada pelo Grupo Barna, revela que a Am\u00e9rica Latina \u00e9 o ber\u00e7o de uma gera\u00e7\u00e3o que est\u00e1 ativamente envolvida com a igreja e aprendendo mais sobre Jesus Cristo.<\/p>\n\n\n\n<p>Segundo a institui\u00e7\u00e3o, os adolescentes foram recrutados para participar da pesquisa quantitativa por meio de seus pais.&nbsp;<\/p>\n\n\n\n<p>Esses dados foram reunidos \u201cno maior estudo da hist\u00f3ria da organiza\u00e7\u00e3o\u201d com o objetivo de ajudar os l\u00edderes da igreja a compreender como alcan\u00e7ar os adolescentes.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"764\" height=\"405\" data-id=\"27358\" src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/09\/Untitled-1.jpg\" alt=\"\" class=\"wp-image-27358\" srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/09\/Untitled-1.jpg 764w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/09\/Untitled-1-300x159.jpg 300w\" sizes=\"(max-width: 764px) 100vw, 764px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><sup><strong>Jovens crist\u00e3os no Brasil. (Foto: Instagram\/Dunamis Movement)<\/strong><\/sup><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Gera\u00e7\u00e3o rendida a Jesus<\/strong><\/p>\n\n\n\n<p>De acordo com o Barna, a \u201cGera\u00e7\u00e3o Aberta\u201d admira Jesus por sua compaix\u00e3o, perd\u00e3o e cuidado com os outros. Eles tamb\u00e9m se preocupam com a justi\u00e7a e est\u00e3o empenhados na leitura das Escrituras.<\/p>\n\n\n\n<p>Os jovens do Brasil, Honduras, M\u00e9xico e Col\u00f4mbia demonstraram maior compreens\u00e3o de Cristo e da B\u00edblia.<\/p>\n\n\n\n<p>Cerca de 74% dos adolescentes&nbsp;<a href=\"https:\/\/www.guiame.com.br\/gospel\/mundo-cristao\/evangelicos-acreditam-que-sua-fe-ainda-tem-um-papel-positivo-na-sociedade.html\"><strong>brasileiros&nbsp;<\/strong><\/a>disseram acreditar que Jesus oferece esperan\u00e7a \u00e0s pessoas. 60% afirmaram que Ele faz uma diferen\u00e7a real no mundo de hoje e 70% acreditam que Cristo voltar\u00e1 um dia.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o aos adolescentes brasileiros que acreditam que Jesus era Deus em forma humana, o estudo contabilizou 55% dos entrevistados.<\/p>\n\n\n\n<p>Um total de 24.557 entrevistados, com idades entre 13 e 17 anos, em 26 pa\u00edses foram entrevistados, entre 21 de julho de 2021 e 24 de agosto de 2021. Outras 313 respostas foram coletadas em fevereiro de 2022 na Nova Zel\u00e2ndia.&nbsp;<\/p>\n\n\n\n<p>Segundo o portal de not\u00edcias Economist, o cristianismo evang\u00e9lico est\u00e1 crescendo rapidamente no Brasil e poder\u00e1 em breve substituir o catolicismo at\u00e9 2030.<\/p>\n\n\n\n<p><strong>No Brasil<\/strong><\/p>\n\n\n\n<p>A evangelista Christine Caine contou que teve o privil\u00e9gio de realizar reuni\u00f5es de jovens ao redor do mundo e confirmou que os adolescentes est\u00e3o procurando uma conex\u00e3o aut\u00eantica e genu\u00edna com Jesus.&nbsp;<\/p>\n\n\n\n<p>&#8220;H\u00e1 um desespero. Uma sensa\u00e7\u00e3o de &#8216;Nosso mundo est\u00e1 fora de controle e precisamos de algo maior do que n\u00f3s mesmos para intervir nisso. N\u00e3o queremos religi\u00e3o, n\u00e3o queremos guerras culturais. Queremos um encontro radical com um Deus vivo que far\u00e1 a diferen\u00e7a na minha vida cotidiana'&#8221;, explicou ela ao Barna.&nbsp;<\/p>\n\n\n\n<p>De acordo com a Global Gospel Coalition\u00a0\u2014\u00a0um minist\u00e9rio evangel\u00edstico voltado para os jovens no\u00a0<a href=\"https:\/\/www.guiame.com.br\/busca?termo=Brasil\"><strong>Brasil<\/strong><\/a>\u00a0\u2014\u00a0centenas de estudantes ouviram o Evangelho em 10 escolas diferentes em Manacapuru, cidade no Amazonas.\u00a0<\/p>\n\n\n\n<p>\u201cEm cada evangeliza\u00e7\u00e3o, compartilhamos o Evangelho, convidamos os alunos a entregar suas vidas a Jesus e orarmos por eles\u201d, escreveram.<br>O Evangelista Rubens Cunha ministrou em um&nbsp;dos evento em Manacapuru, e contou: \u201cConsidero um grande privil\u00e9gio poder alcan\u00e7ar crian\u00e7as e adolescentes em escolas p\u00fablicas no Brasil&#8221;.<\/p>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-4022359745\"><div id=\"jorna-3882248997\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O objetivo do estudo realizado pelo Grupo Barna foi de ajudar os l\u00edderes da igreja&#8230;<\/p>\n","protected":false},"author":2,"featured_media":27359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,15],"tags":[],"class_list":["post-27357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-missoes","category-mundo-cristao"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27357"}],"version-history":[{"count":2,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27357\/revisions"}],"predecessor-version":[{"id":27362,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27357\/revisions\/27362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/27359"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}