{"id":29183,"date":"2023-10-25T14:20:34","date_gmt":"2023-10-25T17:20:34","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=29183"},"modified":"2023-10-25T14:20:34","modified_gmt":"2023-10-25T17:20:34","slug":"sancionada-lei-que-compensa-estados-por-perdas-com-icms","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2023\/10\/25\/sancionada-lei-que-compensa-estados-por-perdas-com-icms\/","title":{"rendered":"Sancionada Lei que Compensa Estados por Perdas com ICMS"},"content":{"rendered":"\n<p>O presidente Luiz In\u00e1cio Lula da Silva sancionou, com veto, a lei que prev\u00ea a compensa\u00e7\u00e3o de R$ 27 bilh\u00f5es da Uni\u00e3o aos estados e ao Distrito Federal pela perda de receita provocada pela redu\u00e7\u00e3o do Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Presta\u00e7\u00e3o de Servi\u00e7os (ICMS) incidente sobre combust\u00edveis em 2022. O repasse dos valores come\u00e7a ainda este ano e termina em 2025. A Lei Complementar 201, de 2023, publicada nesta quarta-feira (25) no Di\u00e1rio Oficial da Uni\u00e3o, j\u00e1 est\u00e1 em vigor.<\/p>\n\n\n\n<p>Essa norma se originou do Projeto de Lei Complementar (PLP) 136\/2023, proposto pela Presid\u00eancia da Rep\u00fablica. Segundo o governo, a proposta foi resultado de um acordo entre a Uni\u00e3o e os estados, ap\u00f3s os entes federativos ajuizarem diversas a\u00e7\u00f5es no Supremo Tribunal Federal (STF) para deduzirem de suas d\u00edvidas com a Uni\u00e3o o valor que deixou de ser arrecadado com os tributos sobre combust\u00edveis entre junho e dezembro de 2022. A redu\u00e7\u00e3o ocorreu com a Lei Complementar 194, de 2022, que considerou diversos setores como bens e servi\u00e7os essenciais, proibindo a aplica\u00e7\u00e3o de al\u00edquotas superiores \u00e0 al\u00edquota padr\u00e3o do ICMS (17% ou 18%).<\/p>\n\n\n\n<p>No Senado, o relat\u00f3rio do senador Veneziano Vital do R\u00eago (MDB-PB) foi aprovado em 4 de outubro com as altera\u00e7\u00f5es propostas pela C\u00e2mara dos Deputados. Para ele, a lei servir\u00e1 para &#8220;equilibrar as rela\u00e7\u00f5es financeiras entre a Uni\u00e3o e os estados&#8221;.<\/p>\n\n\n\n<p>Valores que j\u00e1 foram abatidos de d\u00edvidas dos estados com a Uni\u00e3o em 2022, devido a decis\u00f5es judiciais, mesmo que n\u00e3o definitivas, ser\u00e3o descontados dos direitos a receber. O dinheiro obtido com as liminares entrar\u00e1 nas estat\u00edsticas oficiais de 2022 e ser\u00e1 contado como receita para todos os fins no respectivo exerc\u00edcio. O montante restante ser\u00e1 repassado em parcelas mensais at\u00e9 o fim de 2023 e tamb\u00e9m em 2025.<\/p>\n\n\n\n<p>Ap\u00f3s negocia\u00e7\u00f5es com associa\u00e7\u00f5es de munic\u00edpios, o governo concordou em antecipar para este ano parte dos repasses que estavam previstos para 2024, o que envolve cerca de R$ 10 bilh\u00f5es. Do total antecipado do pr\u00f3ximo ano ser\u00e3o descontados os valores j\u00e1 pagos por meio de liminar e as parcelas de d\u00edvida a vencer. Desse total, 25% ficar\u00e3o com os munic\u00edpios por for\u00e7a constitucional.<\/p>\n\n\n\n<p>O presidente da Rep\u00fablica vetou um trecho que obrigaria a Uni\u00e3o a assumir repasses para os munic\u00edpios e para o Fundo de Manuten\u00e7\u00e3o e Desenvolvimento da Educa\u00e7\u00e3o B\u00e1sica e de Valoriza\u00e7\u00e3o dos Profissionais da Educa\u00e7\u00e3o (Fundeb) se os estados n\u00e3o fizerem isso, alegando falta de previs\u00e3o or\u00e7ament\u00e1ria e financeira. Esse veto ainda ser\u00e1 analisado pelo Congresso Nacional.<\/p>\n\n\n\n<p>O texto considera as transfer\u00eancias diretas dos valores referentes a 2023 como urgentes e imprevis\u00edveis, justificando a abertura de cr\u00e9dito extraordin\u00e1rio neste ano para quita\u00e7\u00e3o. Como a Constitui\u00e7\u00e3o determina aos estados o repasse de 25% da arrecada\u00e7\u00e3o do ICMS aos munic\u00edpios de seu territ\u00f3rio, esse percentual incidir\u00e1 tamb\u00e9m nos ressarcimentos. Os estados dever\u00e3o comprovar mensalmente \u00e0 Secretaria do Tesouro Nacional essa transfer\u00eancia, sob pena de suspens\u00e3o dos abatimentos da d\u00edvida ou das transfer\u00eancias diretas. Se a comprova\u00e7\u00e3o ocorrer ap\u00f3s o prazo, somente no m\u00eas seguinte ser\u00e3o feitos os repasses acumulados.<\/p>\n\n\n\n<p>Quando os valores das liminares a serem repassados pelos estados aos munic\u00edpios superarem os 25% aplicados sobre o valor total fixado no acordo, a diferen\u00e7a ser\u00e1 abatida em 12 meses da cota municipal do ICMS nesse per\u00edodo. Dever\u00e1 ser publicado um extrato indicando os valores repassados em raz\u00e3o da liminar e os valores devidos em raz\u00e3o do acordo.<\/p>\n\n\n\n<p>Al\u00e9m disso, o acordo prev\u00ea a revoga\u00e7\u00e3o de trechos da lei complementar que impunham travas \u00e0s al\u00edquotas do ICMS sobre combust\u00edveis. O projeto retira a car\u00eancia de 12 meses entre a primeira fixa\u00e7\u00e3o das al\u00edquotas monof\u00e1sicas e o primeiro reajuste delas, assim como intervalos de seis meses entre um reajuste e outro. Os estados n\u00e3o precisar\u00e3o mais manter o peso proporcional do tributo na forma\u00e7\u00e3o do pre\u00e7o final ao consumidor. A lei tamb\u00e9m retoma a possibilidade de fixa\u00e7\u00e3o de al\u00edquotas reduzidas sobre combust\u00edveis, energia el\u00e9trica e g\u00e1s natural em patamares maiores que aqueles vigentes em junho de 2022.<\/p>\n\n\n\n<p>O texto prev\u00ea ainda transfer\u00eancias ao Fundo de Participa\u00e7\u00e3o dos Munic\u00edpios (FPM) e ao Fundo de Participa\u00e7\u00e3o dos Estados (FPE) para recuperar perdas de 2023 em rela\u00e7\u00e3o a 2022. A Uni\u00e3o depositar\u00e1 no FPE a diferen\u00e7a entre os repasses de julho e agosto de 2022 e os repasses de julho e agosto de 2023. No caso do FPM, a sistem\u00e1tica ser\u00e1 a mesma, envolvendo os meses de julho, agosto e setembro dos dois anos, mas o valor de 2022 ser\u00e1 corrigido pelo \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (IPCA) para fins de compara\u00e7\u00e3o. Se 2023 tiver repasse menor que 2022, a Uni\u00e3o transferir\u00e1 a diferen\u00e7a aos munic\u00edpios.<\/p>\n\n\n\n<p>Fonte: Ag\u00eancia Senado<\/p>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-111906539\"><div id=\"jorna-2755523148\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O presidente Luiz In\u00e1cio Lula da Silva sancionou, com veto, a lei que prev\u00ea a&#8230;<\/p>\n","protected":false},"author":2,"featured_media":29184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9,2,13],"tags":[],"class_list":["post-29183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-noticia","category-politica"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=29183"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29183\/revisions"}],"predecessor-version":[{"id":29185,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29183\/revisions\/29185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/29184"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=29183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=29183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=29183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}