{"id":3065,"date":"2020-12-03T09:14:08","date_gmt":"2020-12-03T12:14:08","guid":{"rendered":"http:\/\/jornalvaleevangelico.com.br\/?p=3065"},"modified":"2020-12-03T09:14:09","modified_gmt":"2020-12-03T12:14:09","slug":"organizacoes-de-direitos-humanos-alertam-para-avanco-do-genocidio-cristao-na-africa","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2020\/12\/03\/organizacoes-de-direitos-humanos-alertam-para-avanco-do-genocidio-cristao-na-africa\/","title":{"rendered":"Organiza\u00e7\u00f5es de Direitos Humanos alertam para avan\u00e7o do \u2018genoc\u00eddio crist\u00e3o\u2019 na \u00c1frica"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Representantes de organiza\u00e7\u00f5es como a Portas Abertas e a International Christian Concern comentaram a gravidade da persegui\u00e7\u00e3o aos crist\u00e3os na \u00c1frica.<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/thumbor.guiame.com.br\/unsafe\/840x500\/smart\/https:\/\/media.guiame.com.br\/archives\/2020\/12\/02\/2703018027-funeral-nigeria.jpg\" alt=\"Funeral em massa ocorre ap\u00f3s terroristas promoverem massacres em vilas crist\u00e3s na Nig\u00e9ria. (Foto: Reuters)\"\/><figcaption>Funeral em massa ocorre ap\u00f3s terroristas promoverem massacres em vilas crist\u00e3s na Nig\u00e9ria. (Foto: Reuters)<\/figcaption><\/figure>\n\n\n\n<p>Grupos terroristas mu\u00e7ulmanos est\u00e3o lan\u00e7ando ataques em v\u00e1rias na\u00e7\u00f5es africanas. A situa\u00e7\u00e3o mais grave do continente africano \u00e9 a&nbsp;<strong><a href=\"https:\/\/guiame.com.br\/gospel\/missoes-acao-social\/mais-de-3500-cristaos-foram-assassinados-por-grupo-terrorista-em-quatro-anos-na-nigeria.html\">Nig\u00e9ria<\/a><\/strong>, onde dezenas de milhares de crist\u00e3os morreram como parte do que os ativistas de direitos humanos chamam de genoc\u00eddio crist\u00e3o em todo o continente.<\/p>\n\n\n\n<p>O Ex\u00e9rcito da Nig\u00e9ria lan\u00e7ou recentemente um p\u00f4ster de seus 100 principais alvos terroristas. Entre eles: o homem mais procurado da \u00c1frica, Abubakar Shekau, chefe do grupo terrorista isl\u00e2mico Boko Haram.PUBLICIDADE<\/p>\n\n\n\n<figure><iframe><\/iframe><\/figure>\n\n\n\n<p>&#8220;Esta pessoa tem sido perturbadora, n\u00e3o apenas no norte da Nig\u00e9ria, mas em toda uma regi\u00e3o&#8221;, disse o Dr. David Curry, presidente da Portas Abertas (EUA).<\/p>\n\n\n\n<p>Em um v\u00eddeo obtido por um jornal nigeriano, o l\u00edder do Boko Haram, cercado por guarda-costas, se gaba de que nunca ser\u00e1 pego porque est\u00e1 \u201cfazendo o trabalho de Al\u00e1\u201d.<\/p>\n\n\n\n<p>Shekau acrescenta que a guerra na Nig\u00e9ria continuar\u00e1 mesmo depois dele. Dr. David tamb\u00e9m disse que o governo nigeriano precisa adotar um posicionamento firme contra o grupo terrorista.<\/p>\n\n\n\n<p>\u201cEu acho que se ele n\u00e3o for colocado sob controle do governo da Nig\u00e9ria, isso certamente pode virar uma ideia do tipo califado, como vimos com o Estado Isl\u00e2mico na S\u00edria e no Iraque\u201d, advertiu Curry.<\/p>\n\n\n\n<p>A brutal insurg\u00eancia de Shekau matou milhares e deixou milh\u00f5es de desabrigados.<\/p>\n\n\n\n<p>&#8220;Se voc\u00ea observar o que est\u00e1 acontecendo l\u00e1, ver\u00e1 que s\u00e3o ataques massivos exclusivamente contra os crist\u00e3os&#8221;, disse Jeff King, presidente da International Christian Concern. &#8220;50 a 70 mil foram assassinados&#8221;.<\/p>\n\n\n\n<p>A miss\u00e3o de Shekau \u00e9: Tornar o pa\u00eds mais populoso da \u00c1frica (Nig\u00e9ria) isl\u00e2mico, e for\u00e7ar os crist\u00e3os, que constituem a metade da popula\u00e7\u00e3o, a partir, se converter ao Isl\u00e3 ou morrer.<\/p>\n\n\n\n<p><strong>O Genoc\u00eddio Crist\u00e3o na \u00c1frica<\/strong><\/p>\n\n\n\n<p>Johnnie Moore, um crist\u00e3o, e Abraham Cooper, um judeu ortodoxo, s\u00e3o co-autores do novo livro, \u201cThe Next Jihad: Stop the Christian Genocide in Africa\u201d (\u201cA Pr\u00f3xima Jihad: Parem o Genoc\u00eddio Crist\u00e3o na \u00c1frica\u201d).<\/p>\n\n\n\n<p>&#8220;Os terroristas na Nig\u00e9ria e nos pa\u00edses vizinhos ao redor da Nig\u00e9ria, com essas outras insurg\u00eancias ocorrendo, est\u00e3o absolutamente tentando cometer genoc\u00eddio contra as comunidades crist\u00e3s, eles querem extermin\u00e1-los todos&#8221;, disse o reverendo Johnnie Moore.<br><br>Moore e Cooper viajaram juntos para a Nig\u00e9ria no in\u00edcio deste ano, encontrando dezenas de v\u00edtimas crist\u00e3s da persegui\u00e7\u00e3o mu\u00e7ulmana.<\/p>\n\n\n\n<p>&#8220;Muitos deles se sentem desamparados neste ponto, voc\u00ea nunca sabe onde isso vai acontecer em seguida&#8221;, disse o rabino Abraham Cooper, reitor associado e diretor da Agenda de A\u00e7\u00e3o Social Global do Simon Wiesenthal Center, ao CBN News. &#8220;Sua f\u00e9, no entanto, permanece inabal\u00e1vel, e falando como um rabino judeu, um ortodoxo, fui muito inspirado por sua f\u00e9&#8221;.<\/p>\n\n\n\n<p>Para piorar esse cen\u00e1rio, na regi\u00e3o do chamado &#8220;Cintur\u00e3o M\u00e9dio&#8221; da Nig\u00e9ria, onde o Norte Mu\u00e7ulmano encontra o Sul Crist\u00e3o, outro grupo terrorista formado por militantes Fulani Mu\u00e7ulmanos tamb\u00e9m est\u00e1 aterrorizando Crist\u00e3os.<\/p>\n\n\n\n<p>Mais de 1.400 crist\u00e3os foram mortos por terroristas apenas nos primeiros sete meses de 2020 por militantes Fulani.<\/p>\n\n\n\n<p>&#8220;Eles v\u00eam no meio da noite, entrando em vilas crist\u00e3s, incendiando as casas, matando as pessoas, \u00e9 simplesmente horr\u00edvel&#8221;, disse Cooper.<\/p>\n\n\n\n<p>O Wall Street Journal relatou como grupos jihadistas montaram postos de controle aleat\u00f3rios em rodovias, em busca de crist\u00e3os para sequestrar pessoas em troca de um resgate pago ou simplesmente para matar na beira da estrada.<\/p>\n\n\n\n<p>Um dos raptados, Polycarp Zongo, pastor de uma igreja a leste de Abuja, a capital do pa\u00eds.<\/p>\n\n\n\n<p>O grupo terrorista divulgou um v\u00eddeo do pastor Zongo apelando por sua liberta\u00e7\u00e3o.<\/p>\n\n\n\n<p>&#8220;Eles tamb\u00e9m capturaram duas mulheres crist\u00e3s que tamb\u00e9m est\u00e3o aqui comigo&#8221;, disse o pastor Zongo no v\u00eddeo. &#8220;Estou apelando para que todos voc\u00eas fa\u00e7am tudo o que for poss\u00edvel para garantir nossa liberta\u00e7\u00e3o do cativeiro&#8221;.<\/p>\n\n\n\n<p>Os ataques terroristas contra crist\u00e3os est\u00e3o aumentando sob a gest\u00e3o do presidente da Nig\u00e9ria, Muhammadu Buhari.<\/p>\n\n\n\n<p>Ele \u00e9 um mu\u00e7ulmano da tribo Fulani. Os l\u00edderes crist\u00e3os nigerianos acusam o presidente Buhari de fazer pouco para impedir o derramamento de sangue.<\/p>\n\n\n\n<p>A CBN News entrou em contato com o embaixador da Nig\u00e9ria em Washington, DC, para comentar sobre a persegui\u00e7\u00e3o em curso aos crist\u00e3os em seu pa\u00eds, mas n\u00e3o obteve resposta.<br><br>&#8220;Uma coisa \u00e9 quando a Coreia do Norte ou o Ir\u00e3 fazem isso, mas isso \u00e9 uma democracia, tem que haver um estado de direito no pa\u00eds&#8221;, disse Moore.<br><br><strong>Continente africano<\/strong><\/p>\n\n\n\n<p>Depois de perder terreno na S\u00edria e no Iraque, o principal general do Comando de Opera\u00e7\u00f5es Especiais dos EUA na \u00c1frica est\u00e1 alertando que a Al Qaeda, o Estado Isl\u00e2mico e outros grupos terroristas isl\u00e2micos est\u00e3o ganhando terreno no continente.<\/p>\n\n\n\n<p>O general Dagvin Anderson diz que os terroristas mu\u00e7ulmanos est\u00e3o de olho nas regi\u00f5es sul e noroeste da Nig\u00e9ria e os EUA agora est\u00e3o compartilhando intelig\u00eancia espec\u00edfica com o pa\u00eds.<br><br>&#8220;Este compartilhamento de intelig\u00eancia \u00e9 absolutamente vital e estamos totalmente engajados com o governo da Nig\u00e9ria para fornecer a eles compreens\u00e3o sobre o que esses terroristas est\u00e3o fazendo&#8221;, disse o major-general Anderson a rep\u00f3rteres.<\/p>\n\n\n\n<p>Em 10 de novembro, terroristas ligados ao Estado Isl\u00e2mico atacaram uma cidade remota no norte de Mo\u00e7ambique,&nbsp;<strong><a href=\"https:\/\/guiame.com.br\/gospel\/noticias\/terroristas-usam-campo-de-futebol-para-decapitar-mais-de-50-pessoas-em-mocambique.html\">decapitando 50 pessoas em um est\u00e1dio de futebol<\/a><\/strong>&nbsp;e sequestrando dezenas de mulheres.<\/p>\n\n\n\n<p>No segundo semestre de 2020, uma s\u00e9rie de ataques jihadistas ocorreu no N\u00edger, Chade, Camar\u00f5es, Burkina Faso, Mali, Tanz\u00e2nia, Qu\u00eania e Rep\u00fablica Democr\u00e1tica do Congo.<br><br>Mas Moore diz que para os jihadistas radicais, a Nig\u00e9ria continua sendo o grande pr\u00eamio.<br><br>\u201cEste \u00e9 o pa\u00eds mais importante da \u00c1frica, a d\u00e9cima maior reserva de petr\u00f3leo do mundo, a maior economia do continente\u201d, disse Moore.<\/p>\n\n\n\n<p>O Dr. David Curry, cujo grupo Portas Abertas listou a Nig\u00e9ria como o 12\u00ba pior lugar do mundo para os crist\u00e3os, est\u00e1 pedindo ao pr\u00f3ximo governo dos Estados Unidos que fa\u00e7a da Nig\u00e9ria uma prioridade m\u00e1xima.<\/p>\n\n\n\n<p>\u201cIsso tem implica\u00e7\u00f5es internacionais massivas para todo o continente\u201d, advertiu Curry. &#8220;Precisamos nos concentrar no que est\u00e1 acontecendo na Nig\u00e9ria, caso contr\u00e1rio, poder\u00edamos ter uma grande reviravolta naquele lugar t\u00e3o importante do mundo.&#8221;<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">FONTE: GUIAME, COM INFORMA\u00c7\u00d5ES DA CBN NEWS ATUALIZADO: QUARTA-FEIRA, 2 DEZEMBRO DE 2020 AS 8:29<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-1383132236\"><div id=\"jorna-1764731762\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Representantes de organiza\u00e7\u00f5es como a Portas Abertas e a International Christian Concern comentaram a gravidade&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[17,7,15],"tags":[],"class_list":["post-3065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acao-social","category-missoes","category-mundo-cristao"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3065"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3065\/revisions"}],"predecessor-version":[{"id":3067,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3065\/revisions\/3067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/3066"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}