{"id":34543,"date":"2024-06-14T15:44:59","date_gmt":"2024-06-14T18:44:59","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=34543"},"modified":"2024-06-14T15:49:37","modified_gmt":"2024-06-14T18:49:37","slug":"pf-poe-presidente-do-solidariedade-na-lista-vermelha-da-interpol","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2024\/06\/14\/pf-poe-presidente-do-solidariedade-na-lista-vermelha-da-interpol\/","title":{"rendered":"PF p\u00f5e presidente do Solidariedade na lista vermelha da Interpol"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Eur\u00edpedes J\u00fanior segue foragido ap\u00f3s ser alvo da Opera\u00e7\u00e3o Fundo no Po\u00e7o<\/h2>\n\n\n\n<p>A Pol\u00edcia Federal (PF) incluiu o presidente do Solidariedade, Eur\u00edpedes Gomes Macedo J\u00fanior, na difus\u00e3o vermelha da Organiza\u00e7\u00e3o Internacional de Pol\u00edcia Criminal (Interpol), nome dado para a lista de fugitivos mais procurados em n\u00edvel internacional. Com isso, Eur\u00edpedes pode ser preso se for localizado em um pa\u00eds com atua\u00e7\u00e3o da entidade.<\/p>\n\n\n\n<p>Eur\u00edpedes \u00e9 considerado foragido da Opera\u00e7\u00e3o Fundo no Po\u00e7o, investiga\u00e7\u00e3o sobre suposto desvio de R$ 36 milh\u00f5es do Fundo Partid\u00e1rio do Solidariedade. A opera\u00e7\u00e3o foi deflagrada pela PF na \u00faltima quarta-feira (12).<\/p>\n\n\n\n<p>Recaem sobre o presidente do partido acusa\u00e7\u00f5es de candidaturas laranja, uso do dinheiro da legenda para passeios internacionais de seus familiares, eventual envolvimento no sumi\u00e7o de um helic\u00f3ptero do PROS, avaliado em R$ 3,5 milh\u00f5es, e ainda o \u201cdesmonte\u201d da sede e do parque gr\u00e1fico do partido.<\/p>\n\n\n\n<p>A lista de suspeitas que pesam sobre Eur\u00edpedes consta da decis\u00e3o judicial que colocou a PF em seu encal\u00e7o. Na ocasi\u00e3o, seis investigados foram presos, mas Eur\u00edpedes n\u00e3o foi localizado pelos investigadores.<\/p>\n\n\n\n<p>A opera\u00e7\u00e3o foi autorizada pelo juiz Lizandro Garcia Gomes Filho, da 1\u00aa Zona Eleitoral de Bras\u00edlia. Ao decretar a pris\u00e3o preventiva do dirigente partid\u00e1rio, o magistrado destacou ind\u00edcios que apontam para desvios de recursos dos fundos partid\u00e1rio e eleitoral, em benef\u00edcio do pr\u00f3prio Eur\u00edpedes e de familiares e aliados dele.<\/p>\n\n\n\n<p>A PF atribui a ele o papel de chefe de uma organiza\u00e7\u00e3o criminosa \u201cestruturalmente ordenada com o objetivo de desviar e se apropriar de recursos do Fundo Partid\u00e1rio e Eleitoral\u201d.<\/p>\n\n\n\n<p>Segundo relat\u00f3rio da Opera\u00e7\u00e3o Fundo no Po\u00e7o, o presidente do Solidariedade \u201cgere o partido pol\u00edtico como um bem particular, auferindo enriquecimento il\u00edcito pessoal e familiar por meio do desvio e apropria\u00e7\u00e3o dos recursos p\u00fablicos destinados \u00e0 atividade pol\u00edtico-partid\u00e1ria\u201d.<\/p>\n\n\n\n<p>Pleno.News &#8211;\u00a014\/06\/2024\u00a013h55 | atualizado em 14\/06\/2024 14h19<\/p>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-3511822643\"><div id=\"jorna-324718475\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Eur\u00edpedes J\u00fanior segue foragido ap\u00f3s ser alvo da Opera\u00e7\u00e3o Fundo no Po\u00e7o A Pol\u00edcia Federal&#8230;<\/p>\n","protected":false},"author":2,"featured_media":34544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-34543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=34543"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34543\/revisions"}],"predecessor-version":[{"id":34545,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34543\/revisions\/34545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/34544"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=34543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=34543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=34543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}