{"id":43926,"date":"2025-10-29T02:13:05","date_gmt":"2025-10-29T05:13:05","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=43926"},"modified":"2025-10-29T02:22:34","modified_gmt":"2025-10-29T05:22:34","slug":"mais-de-1-500-igrejas-passarao-72-horas-em-oracao-durante-o-halloween-no-reino-unido","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2025\/10\/29\/mais-de-1-500-igrejas-passarao-72-horas-em-oracao-durante-o-halloween-no-reino-unido\/","title":{"rendered":"Mais de 1.500 igrejas passar\u00e3o 72 horas em ora\u00e7\u00e3o durante o Halloween no Reino Unido"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">A vig\u00edlia, promovida pelo Dia Nacional de Ora\u00e7\u00e3o e Adora\u00e7\u00e3o, come\u00e7a \u00e0 meia-noite de quinta-feira (30\/10) e segue at\u00e9 a meia-noite de domingo (2\/11).<\/h2>\n\n\n\n<p>Mais de 1.500 igrejas no&nbsp;<strong><a href=\"https:\/\/www.guiame.com.br\/gospel\/mundo-cristao\/igreja-que-mais-cresce-no-reino-unido-tem-sede-na-nigeria-pais-que-persegue-cristaos.html\">Reino Unido<\/a><\/strong>&nbsp;e na Irlanda j\u00e1 confirmaram participa\u00e7\u00e3o na vig\u00edlia de ora\u00e7\u00e3o de 72 horas durante o Halloween.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o faz parte da campanha evangel\u00edstica &#8220;Shine Your Light&#8221; (Brilhe Sua Luz, em portugu\u00eas), promovida pelo Dia Nacional de Ora\u00e7\u00e3o e Adora\u00e7\u00e3o (NDOPW).<\/p>\n\n\n\n<p>De acordo com a organiza\u00e7\u00e3o, o objetivo \u00e9 mobilizar comunidades crist\u00e3s para afastar a escurid\u00e3o e irradiar a luz de Cristo sobre as na\u00e7\u00f5es por meio de ora\u00e7\u00e3o cont\u00ednua ao longo do fim de semana.<\/p>\n\n\n\n<p>A vig\u00edlia come\u00e7a \u00e0 meia-noite de quinta-feira, 30 de outubro, e se estende at\u00e9 a meia-noite de domingo, 2 de novembro.<\/p>\n\n\n\n<p>Idealizador da campanha, o pastor Jonathan Oloyede cita o&nbsp;<strong><a href=\"https:\/\/www.guiame.com.br\/gospel\/mundo-cristao\/maior-pagina-da-biblia-do-mundo-e-impressa-na-alemanha.html\">Evangelho de Jo\u00e3o<\/a><\/strong>&nbsp;cap\u00edtulo 1, vers\u00edculo 5: \u201cA luz brilha nas trevas, e as trevas n\u00e3o a venceram\u201d.<\/p>\n\n\n\n<p>Segundo Oloyede, este \u00e9 um momento em que o pa\u00eds clama pela luz de Cristo. Em seu chamado, ele conclama o Corpo de Cristo \u2013 cada crente, intercessor e adorador \u2013 a assumir sua posi\u00e7\u00e3o na muralha espiritual e se unir em ora\u00e7\u00e3o.<\/p>\n\n\n\n<p>\u201cVamos nos unir por um despertar espiritual em nosso pa\u00eds. Vamos preencher estas 72 horas com cora\u00e7\u00f5es fervorosos, ora\u00e7\u00f5es poderosas e a certeza da f\u00e9 de que Jesus \u00e9 o Senhor de cada casa, de cada rua e de cada cora\u00e7\u00e3o\u201d, continua ele.<\/p>\n\n\n\n<p>Essa mobiliza\u00e7\u00e3o de ora\u00e7\u00e3o tamb\u00e9m serve como prepara\u00e7\u00e3o para o evento principal, \u201cBrilhe Sua Luz 2025\u201d, marcado para os dias 12 a 14 de dezembro.<\/p>\n\n\n\n<p>Durante esse fim de semana, as igrejas voltar\u00e3o a se reunir em uma nova mobiliza\u00e7\u00e3o, com tr\u00eas dias dedicados \u00e0 ora\u00e7\u00e3o, louvor e a\u00e7\u00f5es evangel\u00edsticas em espa\u00e7os p\u00fablicos.<\/p>\n\n\n\n<p>Na edi\u00e7\u00e3o anterior, aproximadamente 100 mil crist\u00e3os levaram a mensagem do Evangelho a mais de um milh\u00e3o de pessoas em espa\u00e7os p\u00fablicos como ruas, centros comerciais e mercados.<\/p>\n\n\n\n<p>Para este ano, os organizadores pretendem dobrar esse impacto, com aten\u00e7\u00e3o especial \u00e0 participa\u00e7\u00e3o dos jovens e ao fortalecimento da campanha nas redes sociais.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Fonte:<\/strong>\u00a0Guiame, com informa\u00e7\u00f5es do NDOPW <strong>Atualizado:\u00a0<\/strong>ter\u00e7a-feira, 28 de outubro de 2025 \u00e0s 09:52<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-1180317618\"><div id=\"jorna-1691512111\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A vig\u00edlia, promovida pelo Dia Nacional de Ora\u00e7\u00e3o e Adora\u00e7\u00e3o, come\u00e7a \u00e0 meia-noite de quinta-feira&#8230;<\/p>\n","protected":false},"author":2,"featured_media":43927,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15,2],"tags":[],"class_list":["post-43926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-cristao","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=43926"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43926\/revisions"}],"predecessor-version":[{"id":43928,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43926\/revisions\/43928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/43927"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=43926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=43926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=43926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}