{"id":4636,"date":"2021-03-29T12:43:16","date_gmt":"2021-03-29T15:43:16","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=4636"},"modified":"2021-03-29T12:43:17","modified_gmt":"2021-03-29T15:43:17","slug":"ministro-ernesto-araujo-pede-demissao-do-cargo","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/03\/29\/ministro-ernesto-araujo-pede-demissao-do-cargo\/","title":{"rendered":"Ministro Ernesto Ara\u00fajo pede demiss\u00e3o do cargo"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Chefe da pasta de Rela\u00e7\u00f5es Exteriores estava pressionado pelo Senado<\/h2>\n\n\n\n<p>O ministro das Rela\u00e7\u00f5es Exteriores, Ernesto Ara\u00fajo, pediu demiss\u00e3o do cargo nesta segunda-feira (29). A informa\u00e7\u00e3o teria sido repassada pelo pr\u00f3prio chanceler a seus subordinados, de acordo com informa\u00e7\u00f5es do jornal O Globo.<\/p>\n\n\n\n<p>Ernesto vinha sofrendo forte press\u00e3o do Senado nas \u00faltimas semanas. Parlamentares pressionaram o governo a demitir o ministro sob a amea\u00e7a de inviabilizar a pasta bloqueando as medidas relacionadas \u00e0s rela\u00e7\u00f5es internacionais no Congresso.<\/p>\n\n\n\n<p>Interlocutores do presidente do Senado, Rodrigo Pacheco (DEM-MG), afirmaram que o parlamentar procurou, no in\u00edcio da manh\u00e3, o presidente Jair Bolsonaro para pedir a sa\u00edda de Ernesto. Na conversa, disse a Bolsonaro que, se o Executivo n\u00e3o tomar uma iniciativa sobre o ministro, o Senado a tomaria.<\/p>\n\n\n\n<p>Em meio \u00e0 rela\u00e7\u00e3o conflituosa com o Senado, o ministro escreveu, no fim de semana, que, em um almo\u00e7o no in\u00edcio de mar\u00e7o, a senadora K\u00e1tia Abreu (PP-TO), que \u00e9 presidente da comiss\u00e3o de rela\u00e7\u00f5es exteriores, lhe disse que ele seria o \u201crei do Senado se fizesse um gesto em rela\u00e7\u00e3o ao 5G\u201d.<\/p>\n\n\n\n<p>Paulo Moura &#8211;\u00a029\/03\/2021\u00a012h28-Pleno. news<\/p>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-1227200156\"><div id=\"jorna-3552398770\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Chefe da pasta de Rela\u00e7\u00f5es Exteriores estava pressionado pelo Senado O ministro das Rela\u00e7\u00f5es Exteriores,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,13],"tags":[],"class_list":["post-4636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-politica"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4636"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4636\/revisions"}],"predecessor-version":[{"id":4638,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4636\/revisions\/4638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/4637"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}