{"id":4639,"date":"2021-03-29T12:53:34","date_gmt":"2021-03-29T15:53:34","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=4639"},"modified":"2021-03-29T12:53:36","modified_gmt":"2021-03-29T15:53:36","slug":"nao-entrei-na-pm-para-prender-pai-de-familia-disse-soldado-wesley","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/03\/29\/nao-entrei-na-pm-para-prender-pai-de-familia-disse-soldado-wesley\/","title":{"rendered":"\u201cN\u00e3o entrei na PM para prender pai de fam\u00edlia\u201d, disse soldado Wesley"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">PM foi morto ap\u00f3s ser atingido por tiros de policiais enquanto protestava no Farol da Barra<\/h2>\n\n\n\n<p>O policial militar Wesley Soares G\u00f3es, morto a tiros em Salvador (BA) ap\u00f3s protestar ao longo da tarde de domingo (28) na regi\u00e3o do Farol da Barra, gritou diversas palavras de ordem falando em desonra e viola\u00e7\u00e3o da dignidade dos policiais. Com o rosto pintado de verde e amarelo, Wesley disse que n\u00e3o deixaria que a dignidade e honra do trabalhador fossem violadas.<\/p>\n\n\n\n<p>\u2013 Comunidade, venham testemunhar a honra ou a desonra do policial militar do estado da Bahia [\u2026] N\u00e3o vou deixar, n\u00e3o vou permitir que violem a dignidade e honra do trabalhador \u2013 disse.<\/p>\n\n\n\n<p>Em outro momento do protesto, o policial afirmou que n\u00e3o iria mais prender trabalhador e que gostaria de \u201ctrabalhar com dignidade\u201d. No protesto, classificado pela Secretaria de Seguran\u00e7a da Bahia como um \u201csurto psicol\u00f3gico\u201d, o policial ainda lan\u00e7ou bicicletas e itens de ambulantes ao mar.<\/p>\n\n\n\n<p>\u2013 Eu&nbsp;quero&nbsp;trabalhar&nbsp;com&nbsp;honra,&nbsp;com&nbsp;dignidade.&nbsp;Eu&nbsp;n\u00e3o vou mais prender trabalhador, n\u00e3o entrei na pol\u00edcia para prender pai de fam\u00edlia.&nbsp;Quero&nbsp;trabalhar&nbsp;com&nbsp;dignidade, porque sou policial militar da Bahia \u2013 declarou.<\/p>\n\n\n\n<p><strong>O CASO<br><\/strong>O policial militar Wesley Soares G\u00f3es, que protestou na tarde de domingo (28), na regi\u00e3o do Farol da Barra, em Salvador (BA), morreu ap\u00f3s ser baleado depois de mais de tr\u00eas horas de negocia\u00e7\u00e3o com equipes do Batalh\u00e3o de Opera\u00e7\u00f5es Policiais Especiais (BOPE).<\/p>\n\n\n\n<p>A Secretaria de Seguran\u00e7a P\u00fablica (SSP-BA) afirmou que PM teve um \u201csurto\u201d. Wesley protestava contra em defesa dos trabalhadores que est\u00e3o sem poder trabalhar e deu tiros para cima. Ele era solteiro e trabalhava na 72\u00aa CIPM h\u00e1 pelo menos quatro anos.<\/p>\n\n\n\n<p>A fam\u00edlia disse que Wesley G\u00f3es nunca tinha apresentado surtos. De acordo com o portal Bahia Not\u00edcias, o soldado dirigiu de Itacar\u00e9 at\u00e9 Salvador, onde ocupou a regi\u00e3o do Farol da Barra e chegou a dizer: \u201cSeus filhos est\u00e3o presenciando sua covardia, policiais militares do estado da Bahia\u201d.<\/p>\n\n\n\n<p>A Secretaria de Seguran\u00e7a P\u00fablica (SSP-BA) disse que o policial foi baleado ap\u00f3s disparar com fuzil contra guarni\u00e7\u00f5es do Batalh\u00e3o de Opera\u00e7\u00f5es Policiais Especiais e terminou neutralizado.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Paulo Moura &#8211;\u00a029\/03\/2021\u00a008h27 | atualizado em 29\/03\/2021 08h37-Pleno. news<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-2880016617\"><div id=\"jorna-3837894908\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>PM foi morto ap\u00f3s ser atingido por tiros de policiais enquanto protestava no Farol da&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4639"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4639\/revisions"}],"predecessor-version":[{"id":4641,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4639\/revisions\/4641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/4640"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}