{"id":4731,"date":"2021-04-07T09:41:50","date_gmt":"2021-04-07T12:41:50","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=4731"},"modified":"2021-04-07T09:41:51","modified_gmt":"2021-04-07T12:41:51","slug":"supremo-julga-hoje-a-liberacao-de-cultos-e-missas-na-pandemia","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/07\/supremo-julga-hoje-a-liberacao-de-cultos-e-missas-na-pandemia\/","title":{"rendered":"Supremo julga hoje a libera\u00e7\u00e3o de cultos e missas na pandemia"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Julgamento acontece ap\u00f3s decis\u00f5es antag\u00f4nicas sobre o tema serem tomadas pelos ministros Nunes Marques e Gilmar Mendes<\/h3>\n\n\n\n<p>O plen\u00e1rio do Supremo Tribunal Federal (<a href=\"https:\/\/pleno.news\/tag\/stf\" target=\"_blank\" rel=\"noreferrer noopener\">STF<\/a>) decide a partir das 14h desta quarta-feira (7) se libera, ou n\u00e3o, a realiza\u00e7\u00e3o de missas e cultos presenciais diante da atual situa\u00e7\u00e3o da pandemia de Covid-19 no pa\u00eds. O julgamento acontece ap\u00f3s os ministros Nunes Marques e&nbsp;<a href=\"https:\/\/pleno.news\/tag\/gilmar-mendes\" target=\"_blank\" rel=\"noreferrer noopener\">Gilmar Mendes<\/a>&nbsp;tomarem decis\u00f5es antag\u00f4nicas em rela\u00e7\u00e3o ao tema nos \u00faltimos dias.<\/p>\n\n\n\n<p>No s\u00e1bado (3), Nunes Marques autorizou celebra\u00e7\u00f5es religiosas com a presen\u00e7a de fi\u00e9is mesmo ap\u00f3s governadores e prefeitos determinarem o fechamento de templos sob a alega\u00e7\u00e3o de conter a dissemina\u00e7\u00e3o do coronav\u00edrus. Dois dias depois, Gilmar vetou eventos religiosos em S\u00e3o Paulo, e enviou o caso para delibera\u00e7\u00e3o da Corte.<\/p>\n\n\n\n<p>Em sua decis\u00e3o, Nunes Marques disse que a abertura de templos deveria ser feita \u201cde forma prudente e cautelosa, com respeito a par\u00e2metros m\u00ednimos que observem o distanciamento social e que n\u00e3o estimulem aglomera\u00e7\u00f5es desnecess\u00e1rias\u201d. O ministro estabeleceu que deveria haver janelas abertas, uso de m\u00e1scaras e \u00e1lcool em gel nos locais e que a lota\u00e7\u00e3o n\u00e3o poderia exceder os 25%.<\/p>\n\n\n\n<p>J\u00e1 em sua decis\u00e3o, proferida na segunda-feira, Gilmar Mendes afirmou que \u201capenas uma postura negacionista\u201d permitira uma \u201cexce\u00e7\u00e3o\u201d das regras sanit\u00e1rias para cultos religiosos. O ministro reclamou que a \u201cideologia\u201d tem tomado o lugar dos dados cientificamente comprov\u00e1veis.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Paulo Moura &#8211;\u00a007\/04\/2021\u00a009h22-Pleno. news<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-3648395198\"><div id=\"jorna-2037654577\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Julgamento acontece ap\u00f3s decis\u00f5es antag\u00f4nicas sobre o tema serem tomadas pelos ministros Nunes Marques e&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4732,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4731"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4731\/revisions"}],"predecessor-version":[{"id":4733,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4731\/revisions\/4733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/4732"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}