{"id":4787,"date":"2021-04-12T12:25:41","date_gmt":"2021-04-12T15:25:41","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=4787"},"modified":"2021-04-12T12:25:42","modified_gmt":"2021-04-12T15:25:42","slug":"china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/12\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/","title":{"rendered":"China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Declara\u00e7\u00e3o \u00e9 do chanceler chin\u00eas Wang Yi<\/h3>\n\n\n\n<p>O conselheiro de Estado e ministro das Rela\u00e7\u00f5es Exteriores da China, Wang Yi, disse neste s\u00e1bado (10) que a China quer trabalhar com o Brasil para promover sua parceria estrat\u00e9gica abrangente a fim de continuar fazendo novo progresso.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1406518&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1406518&amp;o=node\"><\/p>\n\n\n\n<p>Wang fez o coment\u00e1rio em uma conversa por telefone com Carlos Alberto Franco Fran\u00e7a, ministro das Rela\u00e7\u00f5es Exteriores do Brasil.<\/p>\n\n\n\n<p>Ao parabenizar Fran\u00e7a por sua nomea\u00e7\u00e3o como ministro das Rela\u00e7\u00f5es Exteriores, Wang disse que como grandes pa\u00edses em desenvolvimento, representantes das economias emergentes e parceiros no Brics, a China e o Brasil s\u00e3o for\u00e7as importantes impulsionando a multipolariza\u00e7\u00e3o do mundo e compartilhando interesses comuns extensivos e estreitos.<\/p>\n\n\n\n<p>A China, segundo Wang, sempre valoriza e desenvolve as rela\u00e7\u00f5es com o Brasil de uma perspectiva estrat\u00e9gica de longo prazo, colocando o Brasil em uma das dire\u00e7\u00f5es de prioridade para seus la\u00e7os estrangeiros.<\/p>\n\n\n\n<p>Ap\u00f3s o surto da pandemia da covid-19, a China e o Brasil t\u00eam combatido a pandemia com solidariedade e superado as dificuldades juntamente. Apesar da tend\u00eancia adversa, a coopera\u00e7\u00e3o pragm\u00e1tica tem crescido, com progresso est\u00e1vel em muitos projetos grandes, o que reflete completamente a forte resili\u00eancia da coopera\u00e7\u00e3o dos dois pa\u00edses, disse Wang.<\/p>\n\n\n\n<p>Ao indicar que o v\u00edrus \u00e9 o inimigo comum da humanidade, Wang disse que atualmente a pandemia no Brasil e outros pa\u00edses na Am\u00e9rica Latina est\u00e1 ainda muito severa.<\/p>\n\n\n\n<p>A China se compadece com o Brasil e apoia firmemente os esfor\u00e7os do governo brasileiro para conter a pandemia e restaurar sua economia, disse Wang, acrescentando que a China, dentro de sua capacidade, quer continuar com a coopera\u00e7\u00e3o de vacina com o Brasil para satisfazer sua necessidade urgente.<\/p>\n\n\n\n<p>Ele disse que as economias da China e do Brasil t\u00eam vantagens complementares \u00f3bvias e grande potencial de crescimento, e que a coopera\u00e7\u00e3o \u00e9 de interesse fundamental dos dois pa\u00edses e povos.<\/p>\n\n\n\n<p>Os dois lados devem promover o crescimento est\u00e1vel do com\u00e9rcio bilateral e expandir ativamente a coopera\u00e7\u00e3o em 5G, economia digital, intelig\u00eancia artificial e outras \u00e1reas. Acredita-se que o Brasil fornecer\u00e1 um ambiente de neg\u00f3cio justo e aberto para as empresas chinesas operando no pa\u00eds, disse Wang.<\/p>\n\n\n\n<p>Ao destacar que a China e o Brasil buscam pol\u00edticas estrangeiras independentes e respeitam a soberania e integridade territorial um do outro, Wang pediu que os dois pa\u00edses continuem a se entender e a se apoiar nos assuntos relacionados com seus interesses fundamentais respectivos.<\/p>\n\n\n\n<p>Mirando a nenhum terceiro lado, a coopera\u00e7\u00e3o China-Am\u00e9rica Latina se foca no desenvolvimento comum e coopera\u00e7\u00e3o pragm\u00e1tica, o que satisfaz as necessidades dos dois lados, disse Wang, indicando que o Brasil desempenhar\u00e1 um papel importante e ativo nesse respeito.<\/p>\n\n\n\n<p>Por sua parte, Fran\u00e7a, que agradeceu a Wang os parab\u00e9ns, assinalou que as rela\u00e7\u00f5es Brasil-China s\u00e3o de grande significado estrat\u00e9gico e que os dois pa\u00edses t\u00eam feito coopera\u00e7\u00e3o saud\u00e1vel em v\u00e1rias \u00e1reas.<\/p>\n\n\n\n<p>O chanceler brasileiro acredita que a conversa telef\u00f4nica injetar\u00e1 \u00edmpeto na coopera\u00e7\u00e3o bilateral.<\/p>\n\n\n\n<p>O Brasil espera desenvolver ainda mais as rela\u00e7\u00f5es harmoniosas com a China e realizar a coopera\u00e7\u00e3o a longo prazo, disse Franca, sugerindo que os dois pa\u00edses fa\u00e7am uso completo e melhorem os existentes canais de comunica\u00e7\u00e3o e mecanismos de coopera\u00e7\u00e3o bilateral, fortalecem seu di\u00e1logo estrat\u00e9gico e continuem a aprofundar suas rela\u00e7\u00f5es.<\/p>\n\n\n\n<p>Ao agradecer \u00e0 China sua ajuda generosa ao Brasil desde o surto da pandemia, Fran\u00e7a lembrou que a China \u00e9 um produtor importante de mat\u00e9rias-primas farmac\u00eauticas no mundo.<\/p>\n\n\n\n<p>Indicando que o Brasil est\u00e1 em necessidade urgente de vacinas e suprimentos m\u00e9dicos na luta contra a pandemia, Fran\u00e7a disse que seu pa\u00eds espera cont\u00ednuo suporte forte da China.<\/p>\n\n\n\n<p>A coopera\u00e7\u00e3o cient\u00edfica e tecnol\u00f3gica \u00e9 de grande significado aos dois pa\u00edses, e o Brasil quer fortalecer a coopera\u00e7\u00e3o com a China nas \u00e1reas como a economia digital e 5G, e manter a comunica\u00e7\u00e3o estreita com a China na promo\u00e7\u00e3o da coopera\u00e7\u00e3o China-Am\u00e9rica Latina, acrescentou Fran\u00e7a.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Publicado em 11\/04\/2021 &#8211; 11:50 Por Ag\u00eancia Xinhua &#8211; BEIJING<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-598175132\"><div id=\"jorna-3807820059\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Declara\u00e7\u00e3o \u00e9 do chanceler chin\u00eas Wang Yi O conselheiro de Estado e ministro das Rela\u00e7\u00f5es&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9,8],"tags":[],"class_list":["post-4787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-internacional"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4787"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4787\/revisions"}],"predecessor-version":[{"id":4789,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4787\/revisions\/4789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/4788"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}