{"id":4904,"date":"2021-04-16T15:49:02","date_gmt":"2021-04-16T18:49:02","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=4904"},"modified":"2021-04-16T15:49:04","modified_gmt":"2021-04-16T18:49:04","slug":"covid-19-contagio-nao-garante-aos-jovens-imunidade-para-reinfeccao","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/16\/covid-19-contagio-nao-garante-aos-jovens-imunidade-para-reinfeccao\/","title":{"rendered":"Covid-19: cont\u00e1gio n\u00e3o garante aos jovens imunidade para reinfec\u00e7\u00e3o"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Estudo foi publicado na revista The Lancet Respiratory Medicine<\/h3>\n\n\n\n<p>O cont\u00e1gio do novo coronav\u00edrus oferece alguma prote\u00e7\u00e3o \u00e0 popula\u00e7\u00e3o jovem, mas n\u00e3o garante completa imunidade contra uma reinfe\u00e7\u00e3o, segundo estudo publicado nessa&nbsp;quinta-feira (15) na revista cient\u00edfica&nbsp;<em>The Lancet Respiratory Medicine<\/em>.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1406989&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1406989&amp;o=node\"><\/p>\n\n\n\n<p>A pesquisa, com base em dados de mais de 3&nbsp;mil elementos saud\u00e1veis dos Marines norte-americanos, a maioria homens entre 18 e os 20 anos, concluiu que, ainda que se desenvolvam anticorpos ap\u00f3s a recupera\u00e7\u00e3o da covid-19, \u00e9 conveniente receber a vacina de modo a estimular a resposta imunit\u00e1ria e evitar reinfe\u00e7\u00f5es.<\/p>\n\n\n\n<p>Para o estudo, desenvolvido entre maio e novembro de 2020, os recrutas fizeram uma quarentena de quatro semanas antes de regressar&nbsp;aos treinos, realizaram testes para detectar anticorpos e cont\u00e1gios e preencheram um question\u00e1rio sobre sintomas de covid-19, entre outros dados m\u00e9dicos.<\/p>\n\n\n\n<p>De acordo com a pesquisa, de tipo &#8216;observacional&#8217;, 19 jovens, (10%) de 189 que j\u00e1 tinham superado a covid-19, ficaram novamente infectados, enquanto no grupo dos que n\u00e3o tinham contra\u00eddo o v\u00edrus, com 2.247 recrutas, contagiaram-se posteriormente 1.079, quase metade.<\/p>\n\n\n\n<p>Os autores da pesquisa&nbsp;constataram que os jovens que nunca tinham estado infectadas com o novo coronav\u00edrus tinham cinco vezes mais risco de se contagiarem, do que aqueles que j\u00e1 tinham contra\u00eddo a doen\u00e7a, ainda que os \u00faltimos n\u00e3o fossem completamente imunes.<\/p>\n\n\n\n<p>Os pesquisadores&nbsp;mostram&nbsp;que os jovens reinfectados tinham menos anticorpos do que aqueles que n\u00e3o voltaram a contrair o v\u00edrus, e a sua carga viral era dez vezes mais baixa do que a dos recrutas que tinham ficado infectados pela primeira vez.<\/p>\n\n\n\n<p>Segundo eles, isso significa que algumas pessoas reinfectadas podem transmitir o v\u00edrus, ainda que seja uma conclus\u00e3o que, advertem, requer mais investiga\u00e7\u00e3o para ser confirmada.<\/p>\n\n\n\n<p>&#8220;\u00c0 medida que as campanhas de vacina\u00e7\u00e3o v\u00e3o ganhando impulso, \u00e9 importante lembrar\u00a0que, apesar de uma infec\u00e7\u00e3o pr\u00e9via por covid-19, os jovens podem contrair o v\u00edrus novamente e transmiti-lo a outras pessoas&#8221;, afirma, em nota\u00a0um dos autores do estudo, Stuart Sealfon, da Escola de Medicina Icah, de Monte Sinai, nos Estados Unidos.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Publicado em 16\/04\/2021 &#8211; 08:50 Por RTP &#8211; Lisboa<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-3212712356\"><div id=\"jorna-1721048697\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Estudo foi publicado na revista The Lancet Respiratory Medicine O cont\u00e1gio do novo coronav\u00edrus oferece&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,10],"tags":[],"class_list":["post-4904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-saude"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4904"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4904\/revisions"}],"predecessor-version":[{"id":4906,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4904\/revisions\/4906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/4905"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}