{"id":4927,"date":"2021-04-18T10:34:18","date_gmt":"2021-04-18T13:34:18","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=4927"},"modified":"2021-04-18T10:34:19","modified_gmt":"2021-04-18T13:34:19","slug":"lutamos-em-oracao-diz-irma-de-gravida-que-sobreviveu-apos-dar-a-luz-durante-o-coma","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/18\/lutamos-em-oracao-diz-irma-de-gravida-que-sobreviveu-apos-dar-a-luz-durante-o-coma\/","title":{"rendered":"\u2018Lutamos em ora\u00e7\u00e3o\u2019, diz irm\u00e3 de gr\u00e1vida que sobreviveu ap\u00f3s dar \u00e0 luz durante o coma"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Angela Primachenko ficou em estado grave devido \u00e0 Covid-19 quando estava com 33 semanas de gesta\u00e7\u00e3o.<\/h2>\n\n\n\n<p>Em mar\u00e7o de 2020, Angela Primachenko deu entrada no hospital com febre e tosse persistente. Os m\u00e9dicos descobriram que ela havia sido infectada com Covid-19. Poucos dias depois, seus sintomas pioraram.<\/p>\n\n\n\n<p>\u00a0Para tornar as coisas mais dif\u00edceis, ela estava gr\u00e1vida de 33 semanas de uma menina. Segundo o m\u00e9dico, alguns procedimentos s\u00e3o fundamentais em uma gr\u00e1vida que tenha coronav\u00edrus.<\/p>\n\n\n\n<p>A presen\u00e7a do beb\u00ea \u00e0s 33 semanas coloca muito estresse no corpo da m\u00e3e, especialmente nos pulm\u00f5es. A vida da m\u00e3e e do beb\u00ea est\u00e3o em jogo. Assim, os m\u00e9dicos decidiram esperar o m\u00e1ximo poss\u00edvel para fazer o parto.<\/p>\n\n\n\n<p>No entanto, com o passar do tempo, os pulm\u00f5es da terapeuta respirat\u00f3rio de 27 anos enfraqueceram ainda mais. Ent\u00e3o, os m\u00e9dicos decidiram induzi-la ao coma e coloc\u00e1-la em um respirador.<\/p>\n\n\n\n<p>Quando a fam\u00edlia de Angela ouviu a not\u00edcia, eles lutaram em&nbsp;<strong><a href=\"https:\/\/guiame.com.br\/gospel\/noticias\/deus-tornou-possivel-diz-mae-de-gemeas-siamesas-apos-cirurgia-de-separacao-bem-sucedida.html\">ora\u00e7\u00e3o<\/a><\/strong>&nbsp;por um milagre. A comunidade de amigos e pessoas nas redes sociais tamb\u00e9m se junto a eles em ora\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Dar \u00e0 luz em coma<\/strong><\/p>\n\n\n\n<p>Em 1\u00ba de abril, apesar dos pulm\u00f5es enfraquecidos, o m\u00e9dico induziu o parto de Angela. Mesmo em coma, ela deu \u00e0 luz uma menina saud\u00e1vel &#8211; Ava. O nome, que &#8220;f\u00f4lego de vida&#8221;, j\u00e1 havia sido escolhido por Angela meses antes de ela ser contaminada pelo<strong>&nbsp;<a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/curado-da-covid-apos-174-dias-na-uti-cri-que-deus-ajudaria-ver-minha-familia-de-novo.html\">coronav\u00edrus<\/a><\/strong>.<\/p>\n\n\n\n<p>Uma semana antes da P\u00e1scoa, Angela come\u00e7ou a cair e todos se prepararam para o pior. Mas sua irm\u00e3 sempre se lembrava de que Deus pode&nbsp;<strong><a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/criancas-oram-por-doentes-em-frente-hospital-e-inspiram-com-sua-fe-assista.html\">fazer milagres<\/a><\/strong>. No dia seguinte, Angela j\u00e1 estava respirando sozinha.<\/p>\n\n\n\n<p>Ap\u00f3s 16 dias, os m\u00e9dicos finalmente deram alta a Angela do hospital. E duas semanas depois, ela j\u00e1 estava livre da Covid-19. O melhor momento para ela foi finalmente&nbsp;<strong><a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/vencemos-pelo-poder-da-oracao-diz-pastor-sobre-irma-apos-36-dias-na-uti-por-covid-19.html\">segurar o beb\u00ea pela primeira vez<\/a><\/strong>.<\/p>\n\n\n\n<p>\u201cEle esteve ao meu lado o tempo todo, mesmo quando eu me sentia sozinha. Mesmo quando eu estava literalmente sozinha, Deus ainda estava ao meu lado\u201d, observou Angela.<\/p>\n\n\n\n<p>\u201cDeus ouve nossas ora\u00e7\u00f5es. N\u00e3o h\u00e1 ora\u00e7\u00e3o que volte vazia. Cada ora\u00e7\u00e3o, Ele a mant\u00e9m perto de Seu cora\u00e7\u00e3o\u201d, disse a irm\u00e3 de Angela.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">FONTE: GUIAME, COM INFORMA\u00c7\u00d5ES DO GOD TV &#8211; ATUALIZADO: SEXTA-FEIRA, 16 ABRIL DE 2021 AS 10:06<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-2060291199\"><div id=\"jorna-2639502794\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Angela Primachenko ficou em estado grave devido \u00e0 Covid-19 quando estava com 33 semanas de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4928,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15,6],"tags":[],"class_list":["post-4927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-cristao","category-testemunho"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4927"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4927\/revisions"}],"predecessor-version":[{"id":4929,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4927\/revisions\/4929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/4928"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}