{"id":4931,"date":"2021-04-19T12:38:41","date_gmt":"2021-04-19T15:38:41","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=4931"},"modified":"2021-04-19T12:38:43","modified_gmt":"2021-04-19T15:38:43","slug":"covid-19-ipatinga-vacina-pessoas-de-64-e-65-anos","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/19\/covid-19-ipatinga-vacina-pessoas-de-64-e-65-anos\/","title":{"rendered":"Covid-19: Ipatinga vacina pessoas de 64 e 65 anos"},"content":{"rendered":"\n<p>Depois de receber, nesta segunda-feira (19), mais doses de imunizantes, a Prefeitura de Ipatinga inicia uma nova fase de vacina\u00e7\u00e3o contra a Covid-19. O atendimento passa a abranger pessoas com idades de 64 e 65 anos. Os agentes de sa\u00fade das Unidades B\u00e1sicas (UBS\u2019s) j\u00e1 est\u00e3o em contato com os mun\u00edcipes cadastrados em cada \u00e1rea de refer\u00eancia para o agendamento de data e hor\u00e1rio da imuniza\u00e7\u00e3o. Algumas Unidades est\u00e3o funcionando com hor\u00e1rio estendido at\u00e9 21h, para dar vaz\u00e3o \u00e0 demanda, j\u00e1 que \u00e9 grande o contingente populacional nesta faixa et\u00e1ria.<\/p>\n\n\n\n<p>Ipatinga j\u00e1 vacinou 31.104 pessoas com a primeira dose e a segunda dose foi aplicada em 7.745 pessoas. Essa semana al\u00e9m do p\u00fablico de 64 e 65 anos, o munic\u00edpio vai intensificar a aplica\u00e7\u00e3o da dose complementar.<\/p>\n\n\n\n<p>A Secretaria de Sa\u00fade esclarece que as doses referentes \u00e0 segunda aplica\u00e7\u00e3o s\u00e3o administradas segundo o intervalo estipulado pelos fabricantes para maior efic\u00e1cia dos imunizantes e em conformidade com cronograma estabelecido pelo munic\u00edpio.<\/p>\n\n\n\n<p>De acordo com a diretora do Departamento de Aten\u00e7\u00e3o B\u00e1sica (DAB), Elaine Cristina Vasconcelos, t\u00e3o logo a Superintend\u00eancia Regional de Sa\u00fade encaminha os imunizantes ao mun\u00edcipio, a Secretaria de Sa\u00fade providencia o cronograma de agendamentos das vacinas. \u201cOs imunizantes n\u00e3o ficam parados um \u00fanico dia na Central de Vacinas. Imediatamente ap\u00f3s o recebimento e cadastramentos, eles s\u00e3o enviados \u00e0s Unidades B\u00e1sicas para aplica\u00e7\u00e3o, de acordo com o p\u00fablico-alvo estabelecido\u201d, informa a diretora.<\/p>\n\n\n\n<p>Elaine esclarece n\u00e3o ser poss\u00edvel estabelecer um calend\u00e1rio pr\u00e9vio de faixa et\u00e1ria e data de vacina\u00e7\u00e3o porque o munic\u00edpio depende da disponibilidade de doses enviadas pela Secretaria de Estado.<\/p>\n\n\n\n<p><strong>Vacinados<\/strong><\/p>\n\n\n\n<p>Grande parte dos trabalhadores da Sa\u00fade, 100% das pessoas com defici\u00eancia em resid\u00eancias inclusivas, 100% dos idosos residentes em Institui\u00e7\u00f5es de Longa Perman\u00eancia e 96% das pessoas acima de 90 anos j\u00e1 receberam a segunda dose do imunizante.<\/p>\n\n\n\n<p>J\u00e1 foram garantidas vacinas ainda para todos os mun\u00edcipes idosos acima de 66 anos, salvo casos em que as equipes das Unidades B\u00e1sicas n\u00e3o conseguiram entrar em contato para agendar o atendimento.<\/p>\n\n\n\n<p>Foram vacinados, tamb\u00e9m, trabalhadores das Institui\u00e7\u00f5es de Longa Perman\u00eancia de idosos e de resid\u00eancias inclusivas para jovens e adultos com defici\u00eancia; trabalhadores dos servi\u00e7os de sa\u00fade p\u00fablicos e privados, tanto da urg\u00eancia quanto da aten\u00e7\u00e3o b\u00e1sica, envolvidos diretamente na aten\u00e7\u00e3o\/refer\u00eancia para os casos suspeitos e confirmados de Covid-19 e demais trabalhadores de sa\u00fade.<\/p>\n\n\n\n<p><strong>Agendamento<\/strong><\/p>\n\n\n\n<p>A Prefeitura de Ipatinga refor\u00e7a que o procedimento adotado para dar maior celeridade e transpar\u00eancia ao processo de vacina\u00e7\u00e3o \u00e9 o contato dos agentes de sa\u00fade das unidades de refer\u00eancia com os idosos cadastrados, agendando data e hor\u00e1rio de vacina\u00e7\u00e3o. Portanto, n\u00e3o h\u00e1 necessidade e \u00e9 desaconselh\u00e1vel o deslocamento \u00e0s Unidades sem o agendamento.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Secretaria de Comunica\u00e7\u00e3o Social da Prefeitura de Ipatinga<\/strong> Tel: 3829-8086 \/ 3829-8263 Avenida Maria Jorge Selim de Sales, 100 Centro\u00a0<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-550662080\"><div id=\"jorna-1480707134\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Depois de receber, nesta segunda-feira (19), mais doses de imunizantes, a Prefeitura de Ipatinga inicia&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11,10],"tags":[],"class_list":["post-4931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-saude"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4931"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4931\/revisions"}],"predecessor-version":[{"id":4933,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4931\/revisions\/4933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/4932"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}