{"id":4949,"date":"2021-04-23T09:39:50","date_gmt":"2021-04-23T12:39:50","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=4949"},"modified":"2021-04-23T09:39:52","modified_gmt":"2021-04-23T12:39:52","slug":"auxilio-emergencial-e-pago-a-beneficiarios-do-bolsa-familia-com-nis-5","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/23\/auxilio-emergencial-e-pago-a-beneficiarios-do-bolsa-familia-com-nis-5\/","title":{"rendered":"Aux\u00edlio emergencial \u00e9 pago a benefici\u00e1rios do Bolsa Fam\u00edlia com NIS 5"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Recursos podem ser movimentados pelo aplicativo Caixa Tem ou sacados<\/h3>\n\n\n\n<p>Os benefici\u00e1rios do Bolsa Fam\u00edlia com N\u00famero de Inscri\u00e7\u00e3o Social (NIS) terminado em 5 recebem&nbsp;hoje&nbsp;(23) a primeira parcela do aux\u00edlio emergencial 2021. Os recursos podem ser movimentados pelo aplicativo Caixa Tem, por quem recebe pela conta poupan\u00e7a social digital, ou sacados por meio do Cart\u00e3o Bolsa Fam\u00edlia ou do Cart\u00e3o Cidad\u00e3o.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1407611&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1407611&amp;o=node\"><\/p>\n\n\n\n<p>O recebimento dos recursos segue o calend\u00e1rio normal do Bolsa Fam\u00edlia, pago nos \u00faltimos dez dias \u00fateis de cada m\u00eas. A primeira parcela come\u00e7ou a ser depositada na \u00faltima&nbsp;sexta-feira (16) e ser\u00e1 paga at\u00e9&nbsp;30 de abril.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/imagens.ebc.com.br\/C3BYm65pHy6gc_JInbCiAsrz8bE=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/calendario_auxilio_parcelas_consolidado_bolsa-familia.png?itok=8dSYWK4C\" alt=\"Calend\u00e1rio de pagamento das parcelas do aux\u00edlio emergencial.\" title=\"Arte\/Ag\u00eancia Brasil\"\/><\/figure>\n\n\n\n<p>Calend\u00e1rio de pagamento das parcelas do aux\u00edlio emergencial para benefici\u00e1rios do Bolsa Fam\u00edlia&nbsp;&#8211;&nbsp;<strong>Arte\/Ag\u00eancia Brasil<\/strong><\/p>\n\n\n\n<p>Em caso de d\u00favidas, a central telef\u00f4nica 111 da Caixa funciona de&nbsp;segunda&nbsp;a&nbsp;domingo, das 7h \u00e0s 22h. Al\u00e9m disso, o benefici\u00e1rio pode consultar o&nbsp;<em>site<\/em>&nbsp;<a href=\"https:\/\/auxilio.caixa.gov.br\/#\/inicio\" target=\"_blank\" rel=\"noreferrer noopener\">auxilio.caixa.gov.br<\/a>.<br><br>O aux\u00edlio emergencial foi criado em abril do ano passado pelo governo federal para atender pessoas vulner\u00e1veis afetadas pela pandemia de covid-19. Ele foi pago em cinco parcelas de R$ 600 ou R$ 1,2 mil para m\u00e3es chefes de fam\u00edlia monoparental e, depois, estendido at\u00e9&nbsp;31 de dezembro&nbsp;de 2020 em at\u00e9 quatro parcelas de R$ 300 ou R$ 600 cada.<br><br>Neste ano, a nova rodada de pagamentos, durante quatro meses, prev\u00ea parcelas de R$ 150 a R$ 375, dependendo do perfil: as fam\u00edlias, em geral, recebem R$ 250; a fam\u00edlia monoparental, chefiada por uma mulher, recebe R$ 375; e pessoas que moram sozinhas recebem R$ 150.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Regras<\/h2>\n\n\n\n<p>Pelas regras estabelecidas, o aux\u00edlio \u00e9 pago \u00e0s fam\u00edlias com renda mensal total de at\u00e9 tr\u00eas sal\u00e1rios m\u00ednimos, desde que a renda por pessoa seja inferior a meio sal\u00e1rio m\u00ednimo. \u00c9 necess\u00e1rio que o benefici\u00e1rio j\u00e1 tenha sido considerado eleg\u00edvel at\u00e9 o m\u00eas&nbsp;de dezembro&nbsp;de 2020, pois n\u00e3o h\u00e1 nova fase de inscri\u00e7\u00f5es. Para quem recebe o Bolsa Fam\u00edlia, continua valendo a regra do valor mais vantajoso, seja a parcela paga no programa social, seja a do aux\u00edlio emergencial.<\/p>\n\n\n\n<p>Quem recebe na poupan\u00e7a social digital, pode movimentar os recursos pelo aplicativo Caixa Tem. Com ele, \u00e9 poss\u00edvel fazer compras na internet e nas maquininhas em diversos estabelecimentos comerciais, por meio do cart\u00e3o de d\u00e9bito virtual e QR Code. O benefici\u00e1rio tamb\u00e9m pode pagar boletos e contas, como \u00e1gua e telefone, pelo pr\u00f3prio aplicativo ou nas casas lot\u00e9ricas. A conta \u00e9 uma poupan\u00e7a simplificada, sem tarifas de manuten\u00e7\u00e3o, com limite mensal de movimenta\u00e7\u00e3o de R$ 5 mil.<\/p>\n\n\n\n<p>A&nbsp;<strong>Ag\u00eancia Brasil<\/strong>&nbsp;elaborou um&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2021-04\/agencia-brasil-explica-nova-rodada-do-auxilio-emergencial\" target=\"_blank\" rel=\"noreferrer noopener\">guia de perguntas e respostas<\/a>&nbsp;sobre o aux\u00edlio emergencial. Entre as d\u00favidas que o benefici\u00e1rio pode tirar est\u00e3o os crit\u00e9rios para receber o benef\u00edcio, a regulariza\u00e7\u00e3o do CPF e os crit\u00e9rios de desempate dentro da mesma fam\u00edlia para&nbsp;ter&nbsp;acesso ao aux\u00edlio.<br><br><em>* Colaborou Andreia Verd\u00e9lio<\/em><\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Edi\u00e7\u00e3o: Gra\u00e7a Adjuto- Publicado em 23\/04\/2021 &#8211; 06:00 Por *Wellton M\u00e1ximo &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-1091825058\"><div id=\"jorna-2541868071\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Recursos podem ser movimentados pelo aplicativo Caixa Tem ou sacados Os benefici\u00e1rios do Bolsa Fam\u00edlia&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9,2],"tags":[],"class_list":["post-4949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4949"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4949\/revisions"}],"predecessor-version":[{"id":4951,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4949\/revisions\/4951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/4950"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}