{"id":4966,"date":"2021-04-23T15:32:37","date_gmt":"2021-04-23T18:32:37","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=4966"},"modified":"2021-04-23T15:32:38","modified_gmt":"2021-04-23T18:32:38","slug":"malafaia-vou-presentear-boulos-com-um-tonel-de-oleo-de-peroba","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/23\/malafaia-vou-presentear-boulos-com-um-tonel-de-oleo-de-peroba\/","title":{"rendered":"Malafaia: \u201cVou presentear Boulos com um tonel de \u00f3leo de peroba\u201d"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Pastor reagiu a uma declara\u00e7\u00e3o de Boulos sobre tentativa de aproxima\u00e7\u00e3o ao segmento evang\u00e9lico<\/h2>\n\n\n\n<p>Nesta quinta-feira (22), o pastor Silas Malafaia usou as redes sociais para reagir a declara\u00e7\u00f5es dadas pelo coordenador nacional do Movimento dos Trabalhadores Sem Teto (MTST), Guilherme Boulos (PSOL), \u00e0 CNN. Na ter\u00e7a-feira (20), Boulos disse que seu encontro com o presidente do Republicanos, Marcos Pereira, teve como objetivo se aproximar do segmento evang\u00e9lico.PUBLICIDADE<\/p>\n\n\n\n<p>\u2013 N\u00e3o existe possibilidade de alian\u00e7a eleitoral com o Republicanos. O que estamos fazendo \u00e9 abrir um di\u00e1logo com evang\u00e9licos. \u00c9 importante quebrar as estigmatiza\u00e7\u00f5es que h\u00e1 dos dois lados \u2013 falou Boulos. O encontro aconteceu em uma resid\u00eancia, no bairro dos Jardins, na capital paulista.<\/p>\n\n\n\n<p>No Twitter, Malafaia deu a entender que o coordenador do MST \u00e9 \u2018cara de pau\u2019.<\/p>\n\n\n\n<p>Em sua avalia\u00e7\u00e3o, o pastor disse que um crist\u00e3o teria que negar a f\u00e9 para apoiar os ideais dos partidos de esquerda.  Povo aben\u00e7oado do Brasil, aten\u00e7\u00e3o. Eu vou falar aqui para verdadeiros crist\u00e3os. Boulos diz que tem que aproximar a esquerda dos evang\u00e9licos e tirar essa estigmatiza\u00e7\u00e3o que existe entre os dois lados. Voc\u00ea est\u00e1 enganado. N\u00e3o \u00e9 estigmatiza\u00e7\u00e3o, \u00e9 ideologia. Eu vou mostrar que a ideologia de voc\u00eas [da esquerda] \u00e9 totalmente contr\u00e1ria \u00e0 ideologia de um verdadeiro crist\u00e3o. <\/p>\n\n\n\n<p>O PSOL, seu partido, e a esquerda s\u00e3o a favor da descriminaliza\u00e7\u00e3o das drogas. Para n\u00f3s, essa praga que tem destru\u00eddo o ser humano destr\u00f3i o corpo que \u00e9 o templo do Esp\u00edrito Santo. E para um verdadeiro crist\u00e3o, tudo aquilo que escraviza o homem \u00e9 abomin\u00e1vel. Seu partido, como toda a esquerda, votou a favor da ideologia de g\u00eanero; n\u00e3o \u00e9 ci\u00eancia de g\u00eanero. Essa ideologia que quer dizer que o sexo n\u00e3o \u00e9 biol\u00f3gico, que o indiv\u00edduo n\u00e3o \u00e9 masculino nem feminino. Para n\u00f3s [evang\u00e9licos], Deus fez macho e f\u00eamea. (\u2026) Um verdadeiro crist\u00e3o, Boulos, tem que negar a sua f\u00e9 para abra\u00e7ar a ideologia de voc\u00eas. Eu quero lembrar que o PSOL \u00e9 puxadinho do PT. Governos Lula e Dilma foram respons\u00e1veis pela maior roubalheira da hist\u00f3ria pol\u00edtica do pa\u00eds. Saquearam a na\u00e7\u00e3o, [causaram] desemprego, destru\u00edram a quest\u00e3o da sa\u00fade. E voc\u00ea apoia isso. N\u00e3o d\u00e1! Eu quero tamb\u00e9m dizer, Boulos, \u00e9 que o que voc\u00ea sabe fazer \u00e9 invadir propriedade alheia. Procura a tua turma, segue seu caminho. Fico com vergonha de ver gente do nosso meio dando palco e holofote para voc\u00ea. Que Deus livre a nossa na\u00e7\u00e3o de voc\u00eas, e venham tempos de b\u00ean\u00e7\u00e3os e prosperidade para essa na\u00e7\u00e3o.<\/p>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-4157319130\"><div id=\"jorna-2557525976\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Pastor reagiu a uma declara\u00e7\u00e3o de Boulos sobre tentativa de aproxima\u00e7\u00e3o ao segmento evang\u00e9lico Nesta&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15,2],"tags":[],"class_list":["post-4966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-cristao","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4966"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4966\/revisions"}],"predecessor-version":[{"id":4968,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4966\/revisions\/4968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/4967"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}