{"id":4975,"date":"2021-04-26T14:56:43","date_gmt":"2021-04-26T17:56:43","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=4975"},"modified":"2021-04-26T14:56:44","modified_gmt":"2021-04-26T17:56:44","slug":"media-de-mortes-por-covid-19-cai-195-no-pais-em-duas-semanas","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/26\/media-de-mortes-por-covid-19-cai-195-no-pais-em-duas-semanas\/","title":{"rendered":"M\u00e9dia de mortes por covid-19 cai 19,5% no pa\u00eds em duas semanas"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">M\u00e9dia de \u00f3bitos recua de 3.101 em 11 de abril para 2.495, diz Fiocruz<\/h3>\n\n\n\n<p>O n\u00famero de mortes di\u00e1rias por covid-19 registradas no pa\u00eds, de acordo com a m\u00e9dia m\u00f3vel de sete dias, registrada pela Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz), recuou 19,5% no per\u00edodo de duas semanas. Segundo o boletim Monitora Covid, da Fiocruz, a m\u00e9dia de \u00f3bitos caiu de 3.101 em 11 de abril para 2.495 ontem (25).<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1407768&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1407768&amp;o=node\"><\/p>\n\n\n\n<p>Na compara\u00e7\u00e3o com o recorde de mortes, anotado em 12 de abril (3.124), a queda chegou a 20,1%. Apesar da trajet\u00f3ria de decl\u00ednio nessas duas semanas, a m\u00e9dia de \u00f3bitos ainda \u00e9 9,4% maior que a observada um m\u00eas antes (2.280). A situa\u00e7\u00e3o da pandemia neste momento tamb\u00e9m \u00e9 pior do que no \u00e1pice de mortes do ano passado (25 de julho), quando houve 1.097 registros di\u00e1rios. Na compara\u00e7\u00e3o de ontem com 25 de julho, a alta chega a 127,4%.<\/p>\n\n\n\n<p>O n\u00famero de casos da doen\u00e7a, segundo a m\u00e9dia m\u00f3vel de sete dias, tamb\u00e9m est\u00e1 em trajet\u00f3ria de queda nas duas \u00faltimas semanas. Ontem, houve 56.817 casos, 20% a menos do que 14 dias antes (71.010).<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Edi\u00e7\u00e3o: Kleber Sampaio-Publicado em 26\/04\/2021 &#8211; 08:37 Por Vitor Abdala &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Rio de Janeiro<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-2434285827\"><div id=\"jorna-1362172018\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>M\u00e9dia de \u00f3bitos recua de 3.101 em 11 de abril para 2.495, diz Fiocruz O&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4976,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,10],"tags":[],"class_list":["post-4975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-saude"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4975"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4975\/revisions"}],"predecessor-version":[{"id":4977,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4975\/revisions\/4977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/4976"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}