{"id":4994,"date":"2021-04-26T16:07:45","date_gmt":"2021-04-26T19:07:45","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=4994"},"modified":"2021-04-26T16:10:03","modified_gmt":"2021-04-26T19:10:03","slug":"mais-de-340-iranianos-aceitam-jesus-em-tres-meses-atraves-de-pregacoes-pela-tv","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/26\/mais-de-340-iranianos-aceitam-jesus-em-tres-meses-atraves-de-pregacoes-pela-tv\/","title":{"rendered":"Mais de 340 iranianos aceitam Jesus em tr\u00eas meses, atrav\u00e9s de prega\u00e7\u00f5es pela TV"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Apesar dos esfor\u00e7os do governo do Ir\u00e3 para conter o crescimento de crist\u00e3os, a igreja iraniana \u00e9 uma das que mais cresce no mundo<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/www.cpadnews.com.br\/universo-cristao\/53905\/mais-de-340-iranianos-aceitam-jesus-em-tres-meses-atraves-de-pregacoes-pela-tv.html#\"><img decoding=\"async\" src=\"http:\/\/arquivos.editoracpad.com.br\/uploads\/2021\/04\/26\/540x350_-batismo-no-ira.jpg\" alt=\"Mais de 340 iranianos aceitam Jesus em tr\u00eas meses, atrav\u00e9s de prega\u00e7\u00f5es pela TV\"\/><\/a><\/figure>\n\n\n\n<p>Embora o Ir\u00e3 seja classificado como o 8\u00ba pa\u00eds que mais persegue os crist\u00e3os, de acordo com a classifica\u00e7\u00e3o da organiza\u00e7\u00e3o Portas Abertas, o pa\u00eds tem a popula\u00e7\u00e3o evang\u00e9lica que mais cresce no mundo.<\/p>\n\n\n\n<p>Parte do evangelismo no Ir\u00e3 \u00e9 feito atrav\u00e9s de transmiss\u00f5es pela TV, apesar das tentativas do governo iraniano de impedir a entrada de emissoras crist\u00e3s. Uma delas \u00e9 a Heart4Iran, um minist\u00e9rio de TV e r\u00e1dio que tem buscado novos meios de levar a mensagem do Evangelho \u00e0s casas.<\/p>\n\n\n\n<p>\u201cMudamos nosso feed para um sat\u00e9lite diferente, transmitindo de fora do Ir\u00e3 para dentro do Ir\u00e3\u201d, disse Mike Ansari, do Heart4Iran (\u201cCora\u00e7\u00e3o Para o Ir\u00e3\u201d, em portugu\u00eas), ao Mission Network News. \u201cO governo iraniano est\u00e1 agora empenhado em bloquear as chamadas ou interferir no sinal.\u201d<\/p>\n\n\n\n<p>Por estar no mesmo sinal de transponder de alguns dos canais via sat\u00e9lite mais populares do Ir\u00e3, o Heart4Iran atinge um p\u00fablico ainda maior. Como resultado, cerca de 347 pessoas aceitaram a Cristo nos \u00faltimos tr\u00eas meses, diz Ansari.<\/p>\n\n\n\n<p>\u201cGrande parte da popula\u00e7\u00e3o iraniana est\u00e1 farta do Isl\u00e3 e est\u00e1 procurando outras op\u00e7\u00f5es. \u00c9 por isso que eles chamam organiza\u00e7\u00f5es como a Mohabat TV, que \u00e9 uma TV crist\u00e3 por sat\u00e9lite 24 horas por dia, 7 dias por semana, transmitida para o Ir\u00e3\u201d, afirma.<\/p>\n\n\n\n<p>Com o Ramad\u00e3 em andamento at\u00e9 12 de maio, Ansari espera ainda mais liga\u00e7\u00f5es nos pr\u00f3ximos dias. \u201cDurante o m\u00eas do Ramad\u00e3, por causa da tentativa dos mu\u00e7ulmanos de se aproximarem de Deus, eles est\u00e3o em um lugar muito melhor para receber o Evangelho de amor de Jesus Cristo\u201d, observa.<\/p>\n\n\n\n<p>\u201cO Ramad\u00e3 \u00e9 um momento especial em que tentamos alcan\u00e7ar o povo do Ir\u00e3 com uma mensagem de amor, paz, toler\u00e2ncia e aceita\u00e7\u00e3o\u201d, acrescenta Ansari.&nbsp;<\/p>\n\n\n\n<p>Ele tamb\u00e9m pede ora\u00e7\u00f5es pelo mundo isl\u00e2mico, especialmente no \u201cmomento cr\u00edtico\u201d do Ramad\u00e3. \u201cOs mu\u00e7ulmanos est\u00e3o jejuando e tentando estabelecer uma conex\u00e3o mais pr\u00f3xima com Deus, e pedimos a todos que, por favor, levantem a popula\u00e7\u00e3o mu\u00e7ulmana global durante o m\u00eas do Ramad\u00e3\u201d, diz Ansari.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><em>Fonte: Guiame \/ Com informa\u00e7\u00f5es Mission Network News \/ Foto: Heart4Iran<\/em><\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-3950803634\"><div id=\"jorna-2736709902\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Apesar dos esfor\u00e7os do governo do Ir\u00e3 para conter o crescimento de crist\u00e3os, a igreja&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4995,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,15],"tags":[],"class_list":["post-4994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-missoes","category-mundo-cristao"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4994"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4994\/revisions"}],"predecessor-version":[{"id":4996,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4994\/revisions\/4996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/4995"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}