{"id":5032,"date":"2021-04-28T20:10:00","date_gmt":"2021-04-28T23:10:00","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=5032"},"modified":"2021-04-28T20:10:01","modified_gmt":"2021-04-28T23:10:01","slug":"vacinacao-reduz-transmissao-da-covid-19-em-lares-mostra-estudo","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/28\/vacinacao-reduz-transmissao-da-covid-19-em-lares-mostra-estudo\/","title":{"rendered":"Vacina\u00e7\u00e3o reduz transmiss\u00e3o da covid-19 em lares, mostra estudo"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Dados s\u00e3o da Sa\u00fade P\u00fablica da Inglaterra<\/h3>\n\n\n\n<p>As vacinas contra covid-19 distribu\u00eddas na Inglaterra podem diminuir a transmiss\u00e3o do novo coronav\u00edrus nos lares at\u00e9 pela metade, mostram nesta quarta-feira (28) dados da Sa\u00fade P\u00fablica da Inglaterra (PHE), al\u00e9m da prote\u00e7\u00e3o que oferecem contra infec\u00e7\u00f5es sintom\u00e1ticas.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1408031&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1408031&amp;o=node\"><\/p>\n\n\n\n<p>A pesquisa oferece uma vis\u00e3o de uma das maiores inc\u00f3gnitas sobre as vacina\u00e7\u00f5es contra a covid-19, que \u00e9 at\u00e9 que ponto elas evitam a transmiss\u00e3o do novo coronav\u00edrus, e podem dar f\u00f4lego aos planos do primeiro-ministro, Boris Johnson, de encerrar o&nbsp;<em>lockdown<\/em>&nbsp;ingl\u00eas em junho.<\/p>\n\n\n\n<p>&#8220;J\u00e1 sabemos que as vacinas salvam vidas, e o estudo tem os dados mais abrangentes do mundo real, mostrando que elas tamb\u00e9m cortam a transmiss\u00e3o desse v\u00edrus mortal&#8221;, disse o ministro da Sa\u00fade, Matt Hancock.<\/p>\n\n\n\n<p>Novas pesquisas mostram que as pessoas que foram infectadas com o novo coronav\u00edrus tr\u00eas semanas depois de receber&nbsp;uma dose da vacina da Pfizer ou da AstraZeneca ficaram de 38% a&nbsp;49% menos suscet\u00edveis de transmiti-lo em&nbsp;contatos domiciliares, na compara\u00e7\u00e3o com as que n\u00e3o foram vacinadas.<\/p>\n\n\n\n<p>As vacinas tamb\u00e9m impedem que pessoas inoculadas desenvolvam infec\u00e7\u00f5es sintom\u00e1ticas, reduzindo o risco em cerca de 60% a 65% quatro semanas ap\u00f3s uma dose de qualquer uma das vacinas.<\/p>\n\n\n\n<p>&#8220;Embora essas descobertas sejam muito animadoras, mesmo se voc\u00ea tiver sido vacinado, \u00e9 muito importante continuar a agir como se tivesse o v\u00edrus&#8221;, disse Mary Ramsay, chefe de Imuniza\u00e7\u00e3o da PHE.<\/p>\n\n\n\n<p>O estudo incluiu mais de 57 mil contatos de 24 mil lares, nos quais havia um caso confirmado em laborat\u00f3rio que recebeu uma vacina\u00e7\u00e3o, informou a PHE, em compara\u00e7\u00e3o com quase 1 milh\u00e3o de contatos de casos n\u00e3o vacinados.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Publicado em 28\/04\/2021 &#8211; 10:29 Por Alistair Smout &#8211; Rep\u00f3rter da Reuters &#8211; Londres<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-3739454557\"><div id=\"jorna-494210699\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Dados s\u00e3o da Sa\u00fade P\u00fablica da Inglaterra As vacinas contra covid-19 distribu\u00eddas na Inglaterra podem&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8,10],"tags":[],"class_list":["post-5032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","category-saude"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5032"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5032\/revisions"}],"predecessor-version":[{"id":5034,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5032\/revisions\/5034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/5033"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}