{"id":5059,"date":"2021-04-30T10:01:01","date_gmt":"2021-04-30T13:01:01","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=5059"},"modified":"2021-04-30T10:01:03","modified_gmt":"2021-04-30T13:01:03","slug":"festival-religioso-em-israel-termina-com-dezenas-de-mortos","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/30\/festival-religioso-em-israel-termina-com-dezenas-de-mortos\/","title":{"rendered":"Festival religioso em Israel termina com dezenas de mortos"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Tumulto generalizado ocorreu em evento com mais de 100 mil judeus ultraortodoxos<\/h2>\n\n\n\n<p>Um tumulto em um festival religioso na Alta Galil\u00e9ia, ao Norte de Israel, deixou pelo menos 38 pessoas mortas e mais de 50 feridas, na noite desta quinta-feira (28). Segundo os servi\u00e7os de sa\u00fade, ao menos 20 pessoas est\u00e3o internadas em estado grave.<\/p>\n\n\n\n<p>O encontro religioso chamado Lag Ba\u2019Omer reuniu mais de 100 mil judeus, no local conhecido como Monte Meron.<\/p>\n\n\n\n<p>De acordo com a imprensa local, a confus\u00e3o generalizada come\u00e7ou depois que algumas pessoas escorregaram em degraus de uma arquibancada e foram pisoteadas pela multid\u00e3o que vinha atr\u00e1s. A informa\u00e7\u00e3o inicial era de que a arquibancada havia desabado, o que foi corrigido depois.<\/p>\n\n\n\n<p>\u2013 Est\u00e1vamos na entrada, decidimos que quer\u00edamos sair e ent\u00e3o a pol\u00edcia bloqueou o port\u00e3o, ent\u00e3o quem queria sair n\u00e3o podia mais. Nessa confus\u00e3o, come\u00e7amos a cair uns sobre os outros. Pensei que ia morrer. Eu vi pessoas mortas perto de mim \u2013 disse uma testemunha ao jornal Maariv.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Gabriela Doria &#8211;\u00a029\/04\/2021\u00a022h29 -Pleno. news<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-2863054190\"><div id=\"jorna-2759364328\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Tumulto generalizado ocorreu em evento com mais de 100 mil judeus ultraortodoxos Um tumulto em&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5060,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15,2],"tags":[],"class_list":["post-5059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-cristao","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5059"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5059\/revisions"}],"predecessor-version":[{"id":5061,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5059\/revisions\/5061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/5060"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}