{"id":5077,"date":"2021-04-30T11:04:53","date_gmt":"2021-04-30T14:04:53","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=5077"},"modified":"2021-04-30T11:04:54","modified_gmt":"2021-04-30T14:04:54","slug":"confianca-de-servicos-sobe-41-pontos-em-abril-diz-fgv","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/04\/30\/confianca-de-servicos-sobe-41-pontos-em-abril-diz-fgv\/","title":{"rendered":"Confian\u00e7a de Servi\u00e7os sobe 4,1 pontos em abril, diz FGV"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">\u00cdndice chegou a 81,7 pontos, em escala de zero a 200<\/h3>\n\n\n\n<p>O \u00cdndice de Confian\u00e7a de Servi\u00e7os (ICS), medido pela Funda\u00e7\u00e3o Getulio Vargas (FGV), subiu 4,1 pontos na passagem de mar\u00e7o para abril, depois de tr\u00eas quedas consecutivas. Com isso, o indicador chegou a 81,7 pontos, em uma escala de zero a 200 pontos, sendo que resultados cima de 100 pontos indicam confian\u00e7a.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1408280&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1408280&amp;o=node\"><\/p>\n\n\n\n<p>Houve alta na confian\u00e7a de empres\u00e1rios de 12 dos 13 segmentos de servi\u00e7os pesquisados no pa\u00eds. O \u00cdndice de Situa\u00e7\u00e3o Atual, que mede a percep\u00e7\u00e3o sobre o presente, cresceu 0,4 ponto e atingiu 74,8 pontos.<\/p>\n\n\n\n<p>O \u00cdndice de Expectativas, que mede a confian\u00e7a do empresariado no futuro, subiu 7,4 pontos e chegou a 88,7 pontos.<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Denise Griesinger Publicado em 30\/04\/2021 &#8211; 08:43 Por Vitor Abdala \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Rio de Janeiro<\/p>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-2022323238\"><div id=\"jorna-4021522166\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00cdndice chegou a 81,7 pontos, em escala de zero a 200 O \u00cdndice de Confian\u00e7a&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9,2],"tags":[],"class_list":["post-5077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-noticia"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5077"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5077\/revisions"}],"predecessor-version":[{"id":5079,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5077\/revisions\/5079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/5078"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}