{"id":544,"date":"2020-05-20T14:09:52","date_gmt":"2020-05-20T17:09:52","guid":{"rendered":"http:\/\/jornalvaleevangelico.com.br\/?p=544"},"modified":"2020-05-20T14:09:54","modified_gmt":"2020-05-20T17:09:54","slug":"ainda-bem-que-a-natureza-criou-o-coronavirus-diz-lula","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2020\/05\/20\/ainda-bem-que-a-natureza-criou-o-coronavirus-diz-lula\/","title":{"rendered":"\u201cAinda bem que a natureza criou o coronav\u00edrus\u201d, diz Lula"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Fala do ex-presidente aconteceu durante entrevista para a Carta Capital e mirou ataque a Bolsonaro<\/h3>\n\n\n\n<p>Nem a morte de quase 18 mil pessoas no Brasil parece sensibilizar o ex-presidente Lula sobre o respeito \u00e0s v\u00edtimas da Covid-19 acima da pol\u00edtica, ou do populismo, praticado por ele. Em uma recente entrevista para a Carta Capital, o ex-chefe do Executivo chegou ao ponto de \u201cagradecer a natureza\u201d pela cria\u00e7\u00e3o do coronav\u00edrus.<\/p>\n\n\n\n<p>\u2013 Ainda bem que a natureza, contra a vontade da humanidade, criou esse monstro chamado coronav\u00edrus, porque esse monstro est\u00e1 permitindo que os cegos enxerguem, que os cegos comecem a enxergar, que apenas o estado \u00e9 capaz de dar solu\u00e7\u00e3o a determinadas crises \u2013 declarou.<\/p>\n\n\n\n<p>Sem parecer se importar com os sentimentos das fam\u00edlias, o pr\u00f3prio Lula afirmou que o v\u00edrus teria servido para alertar o governo do presidente Jair Bolsonaro sobre a import\u00e2ncia de um Estado forte para conter o avan\u00e7o da crise econ\u00f4mica.<\/p>\n\n\n\n<p>Apesar de seguir com suas frases de efeito e ataques contra o presidente Jair Bolsonaro, o petista segue enquadrado na Lei da Ficha Limpa, impedido de disputar elei\u00e7\u00f5es. Lula permaneceu preso de 7 abril de 2018 a 08 de novembro de 2019 em uma cela especial da Superintend\u00eancia da Pol\u00edcia Federal, em Curitiba.<\/p>\n\n\n\n<p>Lula foi condenado em primeira, segunda e terceira inst\u00e2ncias sob a acusa\u00e7\u00e3o de aceitar reformas e a propriedade de um tr\u00edplex, em Guaruj\u00e1, como propina paga pela empreiteira OAS em troca de contrato com a Petrobras, o que ele sempre negou.<\/p>\n\n\n\n<p>A pena do ex-presidente foi definida pelo Superior Tribunal de Justi\u00e7a em 8 anos, 10 meses e 20 dias, mas o caso ainda tem recursos pendentes nessa inst\u00e2ncia e, depois, pode ser remetido para o STF.<\/p>\n\n\n\n<p>Al\u00e9m do caso tr\u00edplex, Lula foi condenado em segunda inst\u00e2ncia a 17 anos e 1 m\u00eas de pris\u00e3o por corrup\u00e7\u00e3o e lavagem no caso do s\u00edtio de Atibaia (SP).<\/p>\n\n\n\n<p>O ex-presidente ainda \u00e9 r\u00e9u em outros processos na Justi\u00e7a Federal em S\u00e3o Paulo, Curitiba e Bras\u00edlia. Com exce\u00e7\u00e3o de um dos casos, relativo \u00e0 Odebrecht no Paran\u00e1, as demais a\u00e7\u00f5es n\u00e3o t\u00eam perspectiva de serem sentenciadas em breve.  <\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><a href=\"comunicaErro()\">Comunicar erro<\/a>&#8211; Paulo Moura &#8211;\u00a020\/05\/2020\u00a012h35 | atualizado em 20\/05\/2020 13h04<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-4213172476\"><div id=\"jorna-3457348939\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Fala do ex-presidente aconteceu durante entrevista para a Carta Capital e mirou ataque a Bolsonaro&#8230;<\/p>\n","protected":false},"author":2,"featured_media":545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=544"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/544\/revisions"}],"predecessor-version":[{"id":546,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/544\/revisions\/546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/545"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}