{"id":5924,"date":"2021-06-16T19:43:25","date_gmt":"2021-06-16T22:43:25","guid":{"rendered":"https:\/\/jornalvaleevangelico.com.br\/?p=5924"},"modified":"2021-06-16T19:48:36","modified_gmt":"2021-06-16T22:48:36","slug":"buscas-pelo-termo-oracao-no-google-cresceram-50-em-2020-diz-pesquisa","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2021\/06\/16\/buscas-pelo-termo-oracao-no-google-cresceram-50-em-2020-diz-pesquisa\/","title":{"rendered":"Buscas pelo termo \u201cora\u00e7\u00e3o\u201d no Google cresceram 50% em 2020, diz pesquisa"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Segundo a Pew Research, 24% dos adultos norte-americanos afirmaram que a sua f\u00e9 se fortaleceu durante o primeiro ano da pandemia.<\/h2>\n\n\n\n<p>Em tempos de crise, as pessoas tendem a recorrer \u00e0 f\u00e9 em busca de conforto e explica\u00e7\u00f5es para os problemas. Esse fato foi demonstrado por uma pesquisa da Pew Research ao publicar o resultado das buscas online por \u201cora\u00e7\u00e3o\u201d realizadas em 90 pa\u00edses durante o ano de 2020.<\/p>\n\n\n\n<p>A procura pelo termo bateu recorde e, segundo pesquisadores, a pandemia de\u00a0<strong><a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/vencemos-pelo-poder-da-oracao-diz-pastor-sobre-irma-apos-36-dias-na-uti-por-covid-19.html\">Covid-19<\/a><\/strong>, que se tornou aguda em 2020, foi o principal motivo, elevando o n\u00edvel para o mais alto j\u00e1 registrado.<\/p>\n\n\n\n<p>Usando dados di\u00e1rios em pesquisas do Google para esses pa\u00edses, foi poss\u00edvel apontar que houve aumentou na plataforma de buscas por \u201cora\u00e7\u00e3o\u201d em rela\u00e7\u00e3o a todas as pesquisas na plataforma em anos anteriores,.<\/p>\n\n\n\n<p>De acordo com a Pew, mais da metade da popula\u00e7\u00e3o mundial orou para acabar com o coronav\u00edrus. O aumento equivale a 50% do n\u00edvel anterior de buscas por \u201c<strong><a href=\"https:\/\/guiame.com.br\/gospel\/mundo-cristao\/o-desafio-nao-e-orar-na-crise-mas-continuar-orando-quando-tudo-vai-bem-diz-pastor.html\">ora\u00e7\u00e3o<\/a><\/strong>\u201d em contraste com um quarto da queda nas buscas por \u201cvoos\u201d no Google, que ca\u00edram drasticamente devido ao fechamento da maioria dos transportes a\u00e9reos internacionais.<\/p>\n\n\n\n<p>Segundo o instituto Pew Research, 24% dos adultos norte-americanos afirmaram que a sua f\u00e9 se fortaleceu durante 2020. A pesquisa aponta ainda que as buscas por ora\u00e7\u00e3o aumentaram em todos os n\u00edveis de renda, desigualdade e inseguran\u00e7a, mas n\u00e3o para os 10% menos religiosos dos pa\u00edses.<\/p>\n\n\n\n<p>O aumento n\u00e3o \u00e9 apenas um substituto para os cultos nas igrejas f\u00edsicas que fecharam para limitar a propaga\u00e7\u00e3o do v\u00edrus. Em vez disso, o aumento se deve a uma demanda intensificada por religi\u00e3o: Oramos para enfrentar a adversidade.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">FONTE: GUIAME, COM INFORMA\u00c7\u00d5ES DO PAPERS E PEW RESEARCH ATUALIZADO: QUARTA-FEIRA, 16 JUNHO DE 2021 AS 12:57<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-312017364\"><div id=\"jorna-1533851256\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Segundo a Pew Research, 24% dos adultos norte-americanos afirmaram que a sua f\u00e9 se fortaleceu&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5925,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[17,15],"tags":[],"class_list":["post-5924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acao-social","category-mundo-cristao"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5924"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5924\/revisions"}],"predecessor-version":[{"id":5926,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5924\/revisions\/5926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/5925"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}