{"id":832,"date":"2020-06-12T19:06:46","date_gmt":"2020-06-12T22:06:46","guid":{"rendered":"http:\/\/jornalvaleevangelico.com.br\/?p=832"},"modified":"2020-06-12T19:06:47","modified_gmt":"2020-06-12T22:06:47","slug":"primeira-dama-lanca-desafio-para-distribuicao-de-alimentos","status":"publish","type":"post","link":"https:\/\/jornalvaleevangelico.com.br\/index.php\/2020\/06\/12\/primeira-dama-lanca-desafio-para-distribuicao-de-alimentos\/","title":{"rendered":"Primeira-dama lan\u00e7a desafio para distribui\u00e7\u00e3o de alimentos"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u201cVamos multiplicar a solidariedade!\u201d, escreveu Michelle nas redes sociais.<\/h2>\n\n\n\n<p><ins><\/ins><\/p>\n\n\n\n<p>A primeira-dama,&nbsp;<strong><a href=\"https:\/\/renovamidia.com.br\/tag\/michelle-bolsonaro\/\">Michelle Bolsonaro<\/a><\/strong>, lan\u00e7ou um desafio para ajudar a distribuir alimentos a quem precisa durante a&nbsp;<strong><a href=\"https:\/\/renovamidia.com.br\/tag\/pandemia\/\">pandemia<\/a>&nbsp;<\/strong>de&nbsp;<strong><a href=\"https:\/\/renovamidia.com.br\/tag\/coronavirus\/\">coronav\u00edrus<\/a><\/strong>.<\/p>\n\n\n\n<p>Michelle ainda postou fotos ajudando a preparar e a distribuir quentinhas nas ruas e institui\u00e7\u00f5es do&nbsp;<strong><a href=\"https:\/\/renovamidia.com.br\/tag\/distrito-federal\/\">Distrito Federal<\/a><\/strong>.<\/p>\n\n\n\n<p>Em mensagem nas redes sociais, Michelle declarou:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>\u201cEu e minha fam\u00edlia, preparamos com muito amor e carinho quentinhas para distribuir a quem mais precisa. Gostaria de desafiar voc\u00ea que me acompanha a preparar 5 marmitas para doa\u00e7\u00e3o e postar com a tag #borafazerobem. Eu mesma estarei conferindo e repostando seu trabalho volunt\u00e1rio. Vamos multiplicar a solidariedade!\u201d<\/strong><\/p><\/blockquote>\n\n\n\n<p>Al\u00e9m de incentivar o trabalho volunt\u00e1rio em suas redes sociais, Michelle tem participado de distribui\u00e7\u00f5es e doa\u00e7\u00f5es em v\u00e1rias institui\u00e7\u00f5es do DF.<\/p>\n\n\n\n<p>Para quem tiver interesse em ajudar, as doa\u00e7\u00f5es podem ser realizadas por transfer\u00eancia banc\u00e1ria ou via cart\u00e3o de cr\u00e9dito, por pessoas f\u00edsicas e jur\u00eddicas, no&nbsp;<strong>Brasil&nbsp;<\/strong>e no exterior. O valor m\u00ednimo \u00e9 de&nbsp;<strong>R$ 30<\/strong>.<\/p>\n\n\n\n<p>Para participar, pessoas f\u00edsicas ou jur\u00eddicas podem acessar a plataforma do&nbsp;<strong><a rel=\"noreferrer noopener\" href=\"https:\/\/patriavoluntaria.org\/\" target=\"_blank\">P\u00e1tria Volunt\u00e1ria<\/a><\/strong>&nbsp;ou o site do&nbsp;<strong><a href=\"http:\/\/www.gov.br\/todosportodos\" target=\"_blank\" rel=\"noreferrer noopener\">Todos por Todos<\/a><\/strong>.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">CANAL TELEGRAM: &#8211; m<a href=\"https:\/\/renovamidia.com.br\/author\/admin\/\">TARCISO MORAIS<\/a>Fundador e editor-chefe da RENOVA M\u00eddia<\/h6>\n<div class=\"jorna-rodape jorna-entity-placement\" id=\"jorna-546561972\"><div id=\"jorna-3881711626\"><a href=\"https:\/\/gkscontabilidade.com\/\" aria-label=\"GKS Contabilidade\"><img src=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg\" alt=\"\"  srcset=\"https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade.jpeg 1600w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-300x65.jpeg 300w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1024x223.jpeg 1024w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-768x168.jpeg 768w, https:\/\/jornalvaleevangelico.com.br\/wp-content\/uploads\/2023\/05\/GKS-Contabilidade-1536x335.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" width=\"1600\" height=\"349\"   \/><\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u201cVamos multiplicar a solidariedade!\u201d, escreveu Michelle nas redes sociais. A primeira-dama,&nbsp;Michelle Bolsonaro, lan\u00e7ou um desafio&#8230;<\/p>\n","protected":false},"author":2,"featured_media":833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acao-social"],"_links":{"self":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=832"}],"version-history":[{"count":1,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/832\/revisions"}],"predecessor-version":[{"id":834,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/posts\/832\/revisions\/834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media\/833"}],"wp:attachment":[{"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvaleevangelico.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}